{"id":7836,"date":"2021-10-04T11:41:58","date_gmt":"2021-10-04T09:41:58","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=7836"},"modified":"2021-10-04T11:41:58","modified_gmt":"2021-10-04T09:41:58","slug":"affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/","title":{"rendered":"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000."},"content":{"rendered":"<p><span style=\"color: #000000\"><span style=\"font-family: Calibri, Arial, Helvetica, sans-serif\"><span style=\"font-size: medium\">Si informa che con determinazione dirigenziale n. 1775 del 1\/10\/2021 e&#8217; stato affidato il servizio <span style=\"font-family: Tahoma, sans-serif\"><span style=\"font-size: small\">di gestione temporanea del <\/span><\/span><span style=\"font-family: Tahoma, sans-serif\"><span style=\"font-size: small\">P<\/span><\/span><span style=\"font-family: Tahoma, sans-serif\"><span style=\"font-size: small\">olo natatorio comunale sito in via <\/span><\/span><span style=\"font-family: Tahoma, sans-serif\"><span style=\"font-size: small\">E<\/span><\/span><span style=\"font-family: Tahoma, sans-serif\"><span style=\"font-size: small\">mpolitana km. 3,000.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000\"><span style=\"font-family: Calibri, Arial, Helvetica, sans-serif\"><span style=\"font-size: medium\">Il provvedimento di aggiudicazione, e i relativi atti amministrativi, sono disponibili al seguente <a href=\"https:\/\/trasparenza.strategicpa.it\/comunetivoli\/archivio\/36201-avviso-di-preinformazione-finalizzato-alla-manifestazione-di-interesse-per-l-affidamento-temporaneo-di-gestione-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3-000-tivoli-cig-z6630c674b-\">link<\/a>.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che con determinazione dirigenziale n. 1775 del 1\/10\/2021 e&#8217; stato affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. Il provvedimento [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-7836","post","type-post","status-publish","format-standard","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si informa che con determinazione dirigenziale n. 1775 del 1\/10\/2021 e&#8217; stato affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. Il provvedimento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-04T09:41:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/sport.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000.\",\"datePublished\":\"2021-10-04T09:41:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/\"},\"wordCount\":56,\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/\",\"name\":\"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2021-10-04T09:41:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/","og_locale":"it_IT","og_type":"article","og_title":"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. - Tivoli","og_description":"Si informa che con determinazione dirigenziale n. 1775 del 1\/10\/2021 e&#8217; stato affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. Il provvedimento [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-10-04T09:41:58+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/sport.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000.","datePublished":"2021-10-04T09:41:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/"},"wordCount":56,"articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/","name":"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000. - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2021-10-04T09:41:58+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/affidato-il-servizio-di-gestione-temporanea-del-polo-natatorio-comunale-sito-in-via-empolitana-km-3000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Affidato il servizio di gestione temporanea del Polo natatorio comunale sito in via Empolitana km. 3,000."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=7836"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7836\/revisions"}],"predecessor-version":[{"id":7837,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7836\/revisions\/7837"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=7836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=7836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}