{"id":7838,"date":"2021-10-04T14:07:25","date_gmt":"2021-10-04T12:07:25","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=7838"},"modified":"2021-10-05T09:38:10","modified_gmt":"2021-10-05T07:38:10","slug":"mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/","title":{"rendered":"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini"},"content":{"rendered":"<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">Riparte oggi il servizio di ristorazione nelle mense scolastiche dei cinque istituti comprensivi del territorio comunale dopo il periodo di limitazioni e distanziamento imposto dall\u2019emergenza sanitaria da\u00a0Covid-19. Attraverso un bando pubblico il Comune di Tivoli ha affidato il servizio alla societ\u00e0 cooperativa\u00a0Vivenda spa, azienda del gruppo\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201c<\/span><span class=\"Normal__Char\">La Cascina cooperativa<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201d<\/span><span class=\"Normal__Char\">. I plessi scolastici nei quali viene erogato il servizio di ristorazione sono 13, dei quali cinque dotati di punti cottura e che preparano i pasti anche per le altre scuole dotate soltanto del refettorio.<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">Tante le novit\u00e0 ad attendere i bimbi in questo anno scolastico, a cominciare proprio dai refettori che, per la prima volta dall<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">inizio della pandemia, potranno tornare a essere utilizzati per il consumo del pasto e con la previsione di pi\u00f9 turni, se necessario, per evitare eccessivi assembramenti. Le pietanze saranno servite per la gran parte sui piatti di coccio con l\u2019intento di abbattere l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">utilizzo della plastica a mensa e contribuire, cos\u00ec, a salvaguardare l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">ambiente, una priorit\u00e0 per l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">amministrazione comunale che proprio l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">estate scorsa con un<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">ordinanza firmata dal sindaco\u00a0Giuseppe Proietti\u00a0ha fissato il\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201c<\/span><span class=\"Normal__Char\">divieto di commercializzare e utilizzare materiali in plastica monouso non compostabili e destinata alle attivit\u00e0 commerciali di qualunque natura presenti sul territorio tiburtino<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201d<\/span><span class=\"Normal__Char\">. Laddove non sar\u00e0 possibile introdurre i piatti di coccio il pasto verr\u00e0 servito in piatti in polpa di cellulosa e compostabili.<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">Il menu, rivisitato dalla Vivenda in accordo con il Comune e i dirigenti scolastici rispetto alla precedente gestione, predisposto da un nutrizionista e validato dalla Asl Roma 5, prevede pasti salutari, produzioni biologiche, cibi controllati in ogni fase del processo di trasformazione e segue la stagionalit\u00e0 degli alimenti. Il servizio di ristorazione tiene conto, inoltre, anche delle differenti esigenze alimentari legate ai fattori allergici, alle patologie, alle diverse appartenenze religiose.<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">Non verranno trascurati gli aspetti di sensibilizzazione dei bambini verso i temi dell\u2019ecosostenibilit\u00e0 e dell\u2019impatto ambientale: a scandire l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">anno scolastico saranno anche diversi incontri nelle scuole per avviare un percorso di educazione alimentare, di lotta agli sprechi, di attenzione al rispetto dell<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">ambiente, che passano anche attraverso il riutilizzo intelligente del cibo, in sintonia con i principi dell<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">Agenda 2030<\/span><span class=\"Normal__Char\">\u00a0dell<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">Onu.<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">\u00abSiamo felici che gli alunni di Tivoli possano ricominciare ad andare a scuola, a frequentarsi, a parlarsi, a vivere a pieno regime la vita scolastica e il rapporto con i docenti e con i compagni di scuola. Le relazioni sono importanti quanto l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">apprendimento e la formazione; mangiare tutti insieme \u00e8 un momento fondamentale non soltanto per la loro crescita psicologica e fisica, ma anche per socializzare e condividere con gli altri momenti di convivialit\u00e0 che sono mancati in questo lungo anno e mezzo di emergenza sanitaria\u00bb, commenta l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">assessora ai Servizi sociali e alla pubblica istruzione\u00a0Maria Luisa Cappelli. \u00abRingrazio\u00a0Vivenda:\u00a0nei mesi pi\u00f9 difficili abbiamo potuto sempre contare sul sostegno e la piena collaborazione della societ\u00e0, sul lavoro di cuochi e addette alla mensa, sulla loro capacit\u00e0 di venire incontro alle esigenze della collettivit\u00e0 riorganizzando il servizio alla luce dell<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">emergenza sanitaria\u00bb.<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">\u00abNon vediamo l<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">ora di poter ricominciare il nostro servizio\u00bb,\u00a0 dice il direttore di produzione a Tivoli per il gruppo\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201c<\/span><span class=\"Normal__Char\">La Cascina<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201d<\/span><span class=\"Normal__Char\">,\u00a0Massimo Sancamillo, \u00abcercando di rendere ogni giorno il momento del pranzo un<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">occasione nuova di stimolo e di crescita per i bambini che si affidano a noi. Il nostro principale obiettivo, nel rispetto delle normative Hccp (che stabilisce i requisiti d<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">igiene e di sicurezza in ogni fase della catena alimentare) e anti\u00a0Covid-19, \u00e8 trasformare la scuola in un ambiente vivace e sano, consentendo ai bambini di capire, anche attraverso il gioco, quanto sia importante la sana e corretta alimentazione\u00bb.<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">Si ricorda, inoltre, che sono garantite le aperture degli\u00a0sportelli mensa\u00a0a Tivoli centro, e nelle delegazioni di Tivoli Terme e Villa Adriana e che i pagamenti della refezione scolastica e degli altri servizi &#8211; come tutti i pagamenti rivolti alla pubblica amministrazione &#8211; dovranno essere effettuati attraverso la piattaforma nazionale\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt;font-style: italic\">\u201c<\/span><span class=\"Normal__Char\">Pagopa<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt;font-style: italic\">\u201d<\/span><span class=\"Normal__Char\">.<\/span><span class=\"Normal__Char\">\u00a0A tale scopo, per ricaricare il borsellino elettronico si pu\u00f2 accedere:<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">&#8211; dall<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">area riservata del portale\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt;font-style: italic\">\u201c<\/span><span class=\"Normal__Char\">Novaportal<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt;font-style: italic\">\u201d<\/span><span class=\"Normal__Char\">\u00a0accedendo alla sezione\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201c<\/span><span class=\"Normal__Char\">Pagamenti online<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201d<\/span><span class=\"Normal__Char\">;<\/span><\/p>\n<p class=\"Normal\" style=\"text-align: justify;color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\"><span class=\"Normal__Char\">&#8211; dall<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u2019<\/span><span class=\"Normal__Char\">applicazione\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt;font-style: italic\">\u201c<\/span><span class=\"Normal__Char\">Servizi mensa<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt;font-style: italic\">\u201d<\/span><span class=\"Normal__Char\">\u00a0accedendo alla sezione\u00a0<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201c<\/span><span class=\"Normal__Char\">Ricarica online<\/span><span class=\"Normal__Char\" style=\"font-family: 'Songti SC', Arial;font-size: 12pt\">\u201d<\/span><span class=\"Normal__Char\">.<\/span><\/p>\n<p class=\"Normal\" style=\"color: #000000;text-transform: none;text-indent: 0px;letter-spacing: normal;font-family: 'Liberation Serif', Arial;font-size: medium;font-style: normal;font-weight: 400;margin-top: 0pt;margin-bottom: 0pt\">\n","protected":false},"excerpt":{"rendered":"<p>Riparte oggi il servizio di ristorazione nelle mense scolastiche dei cinque istituti comprensivi del territorio comunale dopo il periodo di limitazioni e distanziamento imposto dall\u2019emergenza sanitaria da\u00a0Covid-19. Attraverso un bando [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":7851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-7838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Riparte oggi il servizio di ristorazione nelle mense scolastiche dei cinque istituti comprensivi del territorio comunale dopo il periodo di limitazioni e distanziamento imposto dall\u2019emergenza sanitaria da\u00a0Covid-19. Attraverso un bando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-04T12:07:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-05T07:38:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/10\/Mensa-scuola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini\",\"datePublished\":\"2021-10-04T12:07:25+00:00\",\"dateModified\":\"2021-10-05T07:38:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/\"},\"wordCount\":706,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/10\\\/Mensa-scuola.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/\",\"name\":\"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/10\\\/Mensa-scuola.jpg\",\"datePublished\":\"2021-10-04T12:07:25+00:00\",\"dateModified\":\"2021-10-05T07:38:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/10\\\/Mensa-scuola.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/10\\\/Mensa-scuola.jpg\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/04\\\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/","og_locale":"it_IT","og_type":"article","og_title":"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini - Tivoli","og_description":"Riparte oggi il servizio di ristorazione nelle mense scolastiche dei cinque istituti comprensivi del territorio comunale dopo il periodo di limitazioni e distanziamento imposto dall\u2019emergenza sanitaria da\u00a0Covid-19. Attraverso un bando [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-10-04T12:07:25+00:00","article_modified_time":"2021-10-05T07:38:10+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/10\/Mensa-scuola.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini","datePublished":"2021-10-04T12:07:25+00:00","dateModified":"2021-10-05T07:38:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/"},"wordCount":706,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/10\/Mensa-scuola.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/","name":"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/10\/Mensa-scuola.jpg","datePublished":"2021-10-04T12:07:25+00:00","dateModified":"2021-10-05T07:38:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/10\/Mensa-scuola.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/10\/Mensa-scuola.jpg","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/04\/mense-scolastiche-da-oggi-torna-il-pranzo-a-mensa-per-oltre-duemila-bambini-tiburtini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Mense scolastiche: da oggi torna il pranzo a mensa per oltre duemila bambini tiburtini"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=7838"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7838\/revisions"}],"predecessor-version":[{"id":7841,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7838\/revisions\/7841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/7851"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=7838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=7838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}