{"id":7901,"date":"2021-10-15T14:58:18","date_gmt":"2021-10-15T12:58:18","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=7901"},"modified":"2021-10-18T09:00:33","modified_gmt":"2021-10-18T07:00:33","slug":"museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/","title":{"rendered":"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d"},"content":{"rendered":"<p>La Giunta comunale di Tivoli ha approvato oggi la delibera proposta dall\u2019assessora al Patrimonio\u00a0Angela Dimiccoli\u00a0riguardante il\u00a0\u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d\u00a0e il relativo schema di accordo di valorizzazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Con questo provvedimento si pone un tassello importante nel percorso lungo e articolato che condurr\u00e0 all\u2019acquisizione \u2013 da parte del Comune di Tivoli &#8211; del complesso di via della Carit\u00e0, nel contesto delle politiche di sviluppo economico, culturale e del turismo tramite le quali l\u2019amministrazione comunale vuole valorizzare il patrimonio della citt\u00e0, con lo scopo d\u2019incrementare i flussi turistici tramite un progetto unitario che metta a sistema operatori pubblici e privati.<\/p>\n<p>&nbsp;<\/p>\n<p>Con l\u2019atto approvato oggi si \u00e8 deliberato di procedere all\u2019approvazione del programma di valorizzazione e del connesso progetto di recupero funzionale dell\u2019immobile (ex riformatorio Niccol\u00f2 Tommaseo, ora denominato\u00a0\u201ccomplesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u201d), appartenente al ramo storico e artistico del demanio pubblico dello Stato. L\u2019accordo verr\u00e0 sottoscritto dal sindaco di Tivoli\u00a0Giuseppe Proietti. Il passaggio in Giunta di questa mattina \u00e8 fondamentale anche perch\u00e9\u00a0propedeutico e finalizzato a trasferire il complesso edilizio al Comune di Tivoli entro 180 giorni.\u00a0Dato che si tratta dell\u2019acquisizione di beni patrimoniali, il trasferimento sar\u00e0 preceduto da una deliberazione del Consiglio comunale e avverr\u00e0 a titolo gratuito, a fronte degli ingenti lavori di restauro che il Comune di Tivoli ha eseguito sul complesso monumentale con impegni finanziari consistenti (alcuni dei quali a totale carico dell\u2019ente), a partire dal 1979, anno a partire dal quale il Comune \u00e8 \u201cutilizzatore\u201d (tramite un atto ministeriale dell\u2019allora ministro dell\u2019Istruzione\u00a0Franco Maria Malfatti). La richiesta per l\u2019attribuzione a titolo non oneroso dell\u2019ex riformatorio Niccol\u00f2 Tommaseo \u00e8 stata presentata dall\u2019amministrazione tiburtina nel 2016, dando vita al percorso che si \u00e8 poi tradotto nell\u2019accordo di valorizzazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Come viene riportato nella delibera, sono diverse le riunioni che si sono tenute (in presenza o in video conferenza durante la fase pi\u00f9 acuta della pandemia da\u00a0Covid-19) con i componenti del tavolo tecnico e operativo istituito a tale scopo tra la direzione regionale del Lazio dell\u2019agenzia del Demanio, il Segretariato regionale per il Lazio del ministero dei Beni e delle attivit\u00e0 culturali e del turismo per il Lazio (ora ministero della Cultura) e la Soprintendenza Archeologica, belle arti e paesaggio per l\u2019area metropolitana di Roma e la provincia di Rieti (importante il parere favorevole rilasciato da quest\u2019ultima al programma di valorizzazione redatto dal Comune tiburtino).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Giunta comunale di Tivoli ha approvato oggi la delibera proposta dall\u2019assessora al Patrimonio\u00a0Angela Dimiccoli\u00a0riguardante il\u00a0\u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d\u00a0e il relativo schema [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-7901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d - Tivoli\" \/>\n<meta property=\"og:description\" content=\"La Giunta comunale di Tivoli ha approvato oggi la delibera proposta dall\u2019assessora al Patrimonio\u00a0Angela Dimiccoli\u00a0riguardante il\u00a0\u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d\u00a0e il relativo schema [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T12:58:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T07:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/04\/palazzo-della-missione-museo-civico-di-tivoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d\",\"datePublished\":\"2021-10-15T12:58:18+00:00\",\"dateModified\":\"2021-10-18T07:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/\"},\"wordCount\":439,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/04\\\/palazzo-della-missione-museo-civico-di-tivoli.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/\",\"name\":\"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/04\\\/palazzo-della-missione-museo-civico-di-tivoli.jpg\",\"datePublished\":\"2021-10-15T12:58:18+00:00\",\"dateModified\":\"2021-10-18T07:00:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/04\\\/palazzo-della-missione-museo-civico-di-tivoli.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/04\\\/palazzo-della-missione-museo-civico-di-tivoli.jpg\",\"width\":1024,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/10\\\/15\\\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/","og_locale":"it_IT","og_type":"article","og_title":"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d - Tivoli","og_description":"La Giunta comunale di Tivoli ha approvato oggi la delibera proposta dall\u2019assessora al Patrimonio\u00a0Angela Dimiccoli\u00a0riguardante il\u00a0\u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d\u00a0e il relativo schema [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-10-15T12:58:18+00:00","article_modified_time":"2021-10-18T07:00:33+00:00","og_image":[{"width":1024,"height":678,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/04\/palazzo-della-missione-museo-civico-di-tivoli.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d","datePublished":"2021-10-15T12:58:18+00:00","dateModified":"2021-10-18T07:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/"},"wordCount":439,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/04\/palazzo-della-missione-museo-civico-di-tivoli.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/","name":"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/04\/palazzo-della-missione-museo-civico-di-tivoli.jpg","datePublished":"2021-10-15T12:58:18+00:00","dateModified":"2021-10-18T07:00:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/04\/palazzo-della-missione-museo-civico-di-tivoli.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/04\/palazzo-della-missione-museo-civico-di-tivoli.jpg","width":1024,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/10\/15\/museo-della-citta-la-giunta-comunale-ha-approvato-la-delibera-sul-trasferimento-dei-beni-di-proprieta-statale-complesso-dellannunziata-futuro-museo-della-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Museo della citt\u00e0: la Giunta comunale ha approvato la delibera sul \u201ctrasferimento dei beni di propriet\u00e0 statale \u2018complesso dell\u2019Annunziata, futuro Museo della citt\u00e0\u2019\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=7901"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7901\/revisions"}],"predecessor-version":[{"id":7902,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7901\/revisions\/7902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/521"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=7901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=7901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}