{"id":8219,"date":"2022-01-05T14:26:46","date_gmt":"2022-01-05T13:26:46","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8219"},"modified":"2022-01-05T14:26:46","modified_gmt":"2022-01-05T13:26:46","slug":"avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/","title":{"rendered":"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali"},"content":{"rendered":"<p>Per tutte le informazioni ed il modulo consultare i seguenti link:<\/p>\n<p><a href=\"https:\/\/static.comune.tivoli.rm.it\/uploads\/AVVISO-ELENCO-PARTNER-COMUNE-DI-TIVOLI-1.pdf\" aria-labelledby=\"post-35291\" aria-label=\"AVVISO ELENCO PARTNER COMUNE DI TIVOLI\">AVVISO ELENCO PARTNER COMUNE DI TIVOLI<\/a><\/p>\n<p><a href=\"https:\/\/static.comune.tivoli.rm.it\/uploads\/MODELLO-DOMANDA-DI-INSERIMENTO-ELENCO-PARTNER-COMUNE-DI-TIVOLI-4.docx\" aria-labelledby=\"post-35291\" aria-label=\"MODELLO DOMANDA\">MODELLO DOMANDA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per tutte le informazioni ed il modulo consultare i seguenti link: AVVISO ELENCO PARTNER COMUNE DI TIVOLI MODELLO DOMANDA<\/p>\n","protected":false},"author":174,"featured_media":8195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-8219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attivita-produttive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Per tutte le informazioni ed il modulo consultare i seguenti link: AVVISO ELENCO PARTNER COMUNE DI TIVOLI MODELLO DOMANDA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-05T13:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/12\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali\",\"datePublished\":\"2022-01-05T13:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/\"},\"wordCount\":48,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/12\\\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg\",\"articleSection\":[\"Attivit\u00e0 Produttive\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/\",\"name\":\"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/12\\\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg\",\"datePublished\":\"2022-01-05T13:26:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/12\\\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/12\\\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/05\\\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali - Tivoli","og_description":"Per tutte le informazioni ed il modulo consultare i seguenti link: AVVISO ELENCO PARTNER COMUNE DI TIVOLI MODELLO DOMANDA","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-01-05T13:26:46+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/12\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali","datePublished":"2022-01-05T13:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/"},"wordCount":48,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/12\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg","articleSection":["Attivit\u00e0 Produttive"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/","name":"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/12\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg","datePublished":"2022-01-05T13:26:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/12\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/12\/Avviso-Pubblico-Comune-di-Tivoli-e1640781930534.jpeg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/05\/avviso-pubblico-manifestazione-di-interesse-per-la-costituzione-di-un-elenco-di-soggetti-esperti-nellambito-di-progetti-a-valere-sui-programmi-finanziati-con-fondi-comunitari-nazionali-e-re\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico: manifestazione di interesse per la costituzione di un elenco di soggetti esperti nell\u2019ambito di progetti a valere sui programmi finanziati con fondi comunitari, nazionali e regionali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8219"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8219\/revisions"}],"predecessor-version":[{"id":8220,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8219\/revisions\/8220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/8195"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}