{"id":8262,"date":"2022-01-18T15:59:15","date_gmt":"2022-01-18T14:59:15","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8262"},"modified":"2022-01-18T16:01:13","modified_gmt":"2022-01-18T15:01:13","slug":"proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/","title":{"rendered":"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L."},"content":{"rendered":"<p>Con ordinanza n.11 del 17 gennaio 2022\u00a0viene prorogata fino al 30 giugno 2022 la validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. per:<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p align=\"center\"><strong>A<\/strong><\/p>\n<p align=\"center\"><strong>(valido per ZTL1 e ZTL2)<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">residenti e domiciliati nella Z.T.L.;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>B<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">residenti e possessori di fondi agricoli in: via degli Orti (tratto compreso tra il civico n. 1 ed il nr. 83 e tra il nr. 2 ed il nr. 54), Via del Tartaro, Via degli Stabilimenti (tratto compreso tra piazza San Nicola e l\u2019ingresso della galleria), via Lgo di Bracciano, via delle Vigne, Strada della Torricella e piazza San Nicola;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>R1 \u2013 R2 \u2013 R3<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">residenti; proprietari di cantine e magazzini; proprietari, affittuari e detentori a titolo gratuito di garages ed aree interne destinate alla sosta nelle seguenti vie: via D.Giuliani, via della Limara, largo G. Crocchiante, vicolo del Pilaro, vicolo degli orti, vicolo Sant\u2019Antonio, vicolo Maggi, vicolo Torlonia, vicolo Lolli Lusignano, vicolo del labirinto, vicolo Boccaccini, via Sant\u2019Andrea, via San Vincenzo, piazza San Vincenzo, vicolo San Vincenzo, vicolo del Pilaro, via dei Sosii (tratto escluso dalla ZTL);<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>C1<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"673\">\n<p align=\"justify\">proprietari o affittuari, detentori a titolo gratuito di garages ovvero di aree interne adibite alla sosta sia in strutture pubbliche che private siti nelle suddette vie;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>C2 &#8211; R3<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">i proprietari di cantine, magazzini, immobili di qualsiasi natura non residenziali ed i possessori di fondi agricoli nelle suddette vie;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>H1 \u2013 H3<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">i medici generici, i medici fiscali incaricati dagli Istituti di Previdenza Sociale per le visite domiciliari, i veterinari convenzionati facenti parte dell\u2019Azienda Sanitaria Locale RM G ed infermieri professionali;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>N<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">i veicoli di propriet\u00e0 di enti pubblici, dell\u2019Amministrazione Comunale, dei Messi Comunali, delle associazione di volontariato\/umanitarie\/onlus con sede nella ZTL; i veicoli privati messi a disposizione dell\u2019Ufficio N.E.P. del Tribunale di Tivoli; i veicoli privati messi a disposizione del Servizio CAD;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p align=\"center\"><strong>P<\/strong><\/p>\n<\/td>\n<td>\n<p align=\"justify\">proprietari di auto a propulsione elettrica e\/o ibrida<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_8263\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/01\/Ordinanza-n.11-del-17-gennaio-2022.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/01\/Ordinanza-n.11-del-17-gennaio-2022.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza n.11 del 17 gennaio 2022<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con ordinanza n.11 del 17 gennaio 2022\u00a0viene prorogata fino al 30 giugno 2022 la validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. per: A (valido per ZTL1 [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":2815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-8262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Con ordinanza n.11 del 17 gennaio 2022\u00a0viene prorogata fino al 30 giugno 2022 la validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. per: A (valido per ZTL1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T14:59:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-18T15:01:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L.\",\"datePublished\":\"2022-01-18T14:59:15+00:00\",\"dateModified\":\"2022-01-18T15:01:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/\"},\"wordCount\":333,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/\",\"name\":\"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"datePublished\":\"2022-01-18T14:59:15+00:00\",\"dateModified\":\"2022-01-18T15:01:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/01\\\/18\\\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/","og_locale":"it_IT","og_type":"article","og_title":"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. - Tivoli","og_description":"Con ordinanza n.11 del 17 gennaio 2022\u00a0viene prorogata fino al 30 giugno 2022 la validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. per: A (valido per ZTL1 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-01-18T14:59:15+00:00","article_modified_time":"2022-01-18T15:01:13+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L.","datePublished":"2022-01-18T14:59:15+00:00","dateModified":"2022-01-18T15:01:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/"},"wordCount":333,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/","name":"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L. - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","datePublished":"2022-01-18T14:59:15+00:00","dateModified":"2022-01-18T15:01:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/01\/18\/proroga-fino-al-30-giugno-2022-della-validita-dei-permessi-per-il-transito-e-la-sosta-nella-z-t-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Proroga fino al 30 giugno 2022 della validit\u00e0 dei permessi per il transito e la sosta nella Z.T.L."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8262"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8262\/revisions"}],"predecessor-version":[{"id":8266,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8262\/revisions\/8266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/2815"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}