{"id":8407,"date":"2022-03-07T15:02:04","date_gmt":"2022-03-07T14:02:04","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8407"},"modified":"2022-03-07T15:02:04","modified_gmt":"2022-03-07T14:02:04","slug":"8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/","title":{"rendered":"8 marzo: &#8220;Porte Aperte&#8221; al Centro Antiviolenza La Sibilla"},"content":{"rendered":"<p>In occasione della Giornata Internazionale della Donna, il Centro Antiviolenza La Sibilla di Tivoli lancia l&#8217;iniziativa \u201cPorte Aperte\u201d dedicata alle cittadine e ai cittadini interessati a conoscere il lavoro del centro, attraverso attivit\u00e0 laboratoriali, incontri a tema, attivit\u00e0 di ascolto e ricreative.<\/p>\n<p>Il Centro Antiviolenza La Sibilla, gestito dall\u2019associazione Differenza Donna, a cui collaborano le associazioni Rete Rosa, 8 Marzo2012 e Noi Lilith, \u00e8 un luogo che accoglie ed ospita le donne vittime di ogni tipo di violenza. L&#8217;apertura alla cittadinanza e alle scuole sar\u00e0 occasione di confronto e conoscenza del grande impegno svolto negli anni. Le attivit\u00e0 si svolgeranno a partire dalle 10.00 fino alle 18.00 presso gli spazi del Centro in via Lione 11.<\/p>\n<p>\u00abL&#8217;amministrazione comunale coglie l&#8217;occasione per fare gli auguri a tutte le donne, affinch\u00e9 il loro ruolo e i loro diritti in questa societ\u00e0 siano sempre pi\u00f9 riconosciuti e rispettati. Come il Centro La Sibilla ci insegna, nessuna donna dovrebbe mai sentirsi sola o lasciata in disparte da questa societ\u00e0\u00bb, afferma l&#8217;assessora alle politiche sociali, Maria Luisa Cappelli. \u00abRingrazio in particolare la Commissione pari opportunit\u00e0 e la sua presidente Francesca Chimenti per l&#8217;impegno a supporto del Centro e delle donne\u00bb, conclude.<\/p>\n\t\t\t<h4>Inizio<\/h4>\n<p>08\/03\/2022 10:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>08\/03\/2022 18:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Via Lione 11, Tivoli, Roma Capitale, Lazio, 00019, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=41.9626074,12.7980093&z=15&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>In occasione della Giornata Internazionale della Donna, il Centro Antiviolenza La Sibilla di Tivoli lancia l&#8217;iniziativa \u201cPorte Aperte\u201d dedicata alle cittadine e ai cittadini interessati a conoscere il lavoro del [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":8408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-8407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 marzo: &quot;Porte Aperte&quot; al Centro Antiviolenza La Sibilla - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 marzo: &quot;Porte Aperte&quot; al Centro Antiviolenza La Sibilla - Tivoli\" \/>\n<meta property=\"og:description\" content=\"In occasione della Giornata Internazionale della Donna, il Centro Antiviolenza La Sibilla di Tivoli lancia l&#8217;iniziativa \u201cPorte Aperte\u201d dedicata alle cittadine e ai cittadini interessati a conoscere il lavoro del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-07T14:02:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/porte-aperte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"8 marzo: &#8220;Porte Aperte&#8221; al Centro Antiviolenza La Sibilla\",\"datePublished\":\"2022-03-07T14:02:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/\"},\"wordCount\":200,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/porte-aperte.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/\",\"name\":\"8 marzo: \\\"Porte Aperte\\\" al Centro Antiviolenza La Sibilla - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/porte-aperte.jpg\",\"datePublished\":\"2022-03-07T14:02:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/porte-aperte.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/porte-aperte.jpg\",\"width\":1000,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/07\\\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 marzo: &#8220;Porte Aperte&#8221; al Centro Antiviolenza La Sibilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 marzo: \"Porte Aperte\" al Centro Antiviolenza La Sibilla - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/","og_locale":"it_IT","og_type":"article","og_title":"8 marzo: \"Porte Aperte\" al Centro Antiviolenza La Sibilla - Tivoli","og_description":"In occasione della Giornata Internazionale della Donna, il Centro Antiviolenza La Sibilla di Tivoli lancia l&#8217;iniziativa \u201cPorte Aperte\u201d dedicata alle cittadine e ai cittadini interessati a conoscere il lavoro del [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-03-07T14:02:04+00:00","og_image":[{"width":1000,"height":625,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/porte-aperte.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"8 marzo: &#8220;Porte Aperte&#8221; al Centro Antiviolenza La Sibilla","datePublished":"2022-03-07T14:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/"},"wordCount":200,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/porte-aperte.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/","name":"8 marzo: \"Porte Aperte\" al Centro Antiviolenza La Sibilla - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/porte-aperte.jpg","datePublished":"2022-03-07T14:02:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/porte-aperte.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/porte-aperte.jpg","width":1000,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/07\/8-marzo-porte-aperte-al-centro-antiviolenza-la-sibilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"8 marzo: &#8220;Porte Aperte&#8221; al Centro Antiviolenza La Sibilla"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"08\/03\/2022 10:00","cc4_eve_data_fine":"08\/03\/2022 18:00","cc4_eve_indirizzo":"Via Lione 11, Tivoli, Roma Capitale, Lazio, 00019, Italia","cc4_eve_posizione":{"latitude":"41.9626074","longitude":"12.7980093","zoom":"15"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8407"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8407\/revisions"}],"predecessor-version":[{"id":8410,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8407\/revisions\/8410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/8408"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}