{"id":8438,"date":"2022-03-16T10:34:46","date_gmt":"2022-03-16T09:34:46","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8438"},"modified":"2022-03-16T12:52:34","modified_gmt":"2022-03-16T11:52:34","slug":"19-marzo-torna-la-fiera-di-san-giuseppe","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/","title":{"rendered":"19 marzo: torna la Fiera di San Giuseppe"},"content":{"rendered":"<p>Dopo due anni di stop dovuti all&#8217;emergenza coronavirus, sabato 19 marzo torna la Fiera di San Giuseppe a Tivoli. Il tradizionale evento si svolger\u00e0 dalle prime ore del mattino fino al tramonto e interesser\u00e0 diversi punti della citt\u00e0, nello specifico piazza Plebiscito, via Ignazio Missoni, via del Governo, piazza del Governo, piazza del Comune, via Lione, via Munazio Planco, via Parmegiani, vicolo del Melangolo, piazza Sabucci, via S. Sinferusa, piazza Campitelli, vicolo Campitelli, scalinata E. Roesler Franz, via Palatina, piazza Palatina, vicolo della Carit\u00e0, piazza delle Erbe, via Ponte Gregoriano, piazza Rivarola, piazza Colonna, piazza Domenico Tani, via Colsereno, piazza S. Vincenzo, largo G.Baja.<\/p>\n<p>Nelle piazze indicate saranno dislocati i banchi con specifiche merceologie di vendita:<br \/>\n&#8211; Piante e fiori: Piazza Plebiscito;<br \/>\n&#8211; animali (pesciolini, uccellini, pulcini): Piazza Domenico Tani;<br \/>\n&#8211; articoli artigianali creati attraverso un processo produttivo tradizionale o manuale posto in essere nell\u2019area geografica del Comune di Tivoli e della Valle dell\u2019Aniene: Via Palatina;<br \/>\n&#8211; prodotti agro-alimentari tipici locali la cui area di produzione \u00e8 riconducibile al territorio tiburtino e alla Valle dell\u2019Aniene: Via Palatina;<br \/>\n&#8211; articoli in legno, vimini, rame, ferro battuto: Piazza Rivarola.<\/p>\n<p>\u00abLa Fiera di San Giuseppe \u00e8 uno degli eventi storicamente pi\u00f9 attesi dai tiburtini. Nel 2020 e nel 2021 l&#8217;emergenza Covid-19 ci ha costretti a rimandare l&#8217;evento a &#8220;data da destinarsi&#8221;. \u00c8 per noi un onore, quest&#8217;anno, poter tornare ad animare le vie della nostra citt\u00e0 con i tipici banchi\u00bb, afferma il sindaco di Tivoli Giuseppe Proietti.<\/p>\n<p>Il centro storico non sar\u00e0 servito dai <strong>mezzi Cat<\/strong> durante la manifestazione. Dalle ore 7 alle 24 \u00e8 prevista la <strong>sospensione degli accessi Ztl<\/strong> nelle zone: Varco 1 \u2013 piazza Massimo, 7; Varco 2 \u2013 via del Colle, 98; Varco 3 \u2013 via dei Sosii; Varco 4 \u2013 via Colsereno.<\/p>\n<p>Per il giorno 19 marzo \u00e8 prevista la <strong>sospensione dell&#8217;attivit\u00e0 didattica<\/strong> in tutti gli Istituti scolastici, pubblici e privati, presenti sul territorio comunale.<\/p>\n<p>Al fine di prevenire i contagi da coronavirus, sar\u00e0 obbligatorio l\u2019uso della <strong>mascherina all\u2019aperto<\/strong>, sia per gli operatori sia per i visitatori, in tutta l&#8217;area in cui si svolger\u00e0 la Fiera. L&#8217;obbligo non si applica ai bambini di et\u00e0 inferiore ai sei anni, a chi ha patologie o disabilit\u00e0 incompatibili con l&#8217;uso della mascherina, nonch\u00e9 alle persone che devono comunicare con un disabile in modo da non poter indossare il dispositivo. In tutta l&#8217;area in cui si terr\u00e0 il tradizionale evento sar\u00e0 inoltre obbligatorio il <strong>Green Pass rafforzato.<\/strong> Il controllo del Green Pass verr\u00e0 effettuato a campione da personale appositamente incaricato dall&#8217;Amministrazione comunale.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_8440\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Polizia-Locale-ord.86-Fiera-San-Giuseppe.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Polizia-Locale-ord.86-Fiera-San-Giuseppe.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Polizia Locale ord.86 Fiera San Giuseppe<\/a><\/li>\n<li><a id=\"wpba_attachment_list_8442\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Scuola-Ordinanza-19-Marzo-22.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Scuola-Ordinanza-19-Marzo-22.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Chiusura scuole 19 marzo<\/a><\/li>\n<li><a id=\"wpba_attachment_list_8443\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Sindaco-ord.89-Fiera-San-Giuseppe.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Sindaco-ord.89-Fiera-San-Giuseppe.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ord. dispositivi protezione Covid Fiera San Giuseppe<\/a><\/li>\n<li><a id=\"wpba_attachment_list_8444\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Avviso-Cat-Fiera-San-Giuseppe.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Avviso-Cat-Fiera-San-Giuseppe.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso Cat Fiera San Giuseppe<\/a><\/li>\n<li><a id=\"wpba_attachment_list_8448\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Mappa-Fiera-San-Giuseppe.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/Mappa-Fiera-San-Giuseppe.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Mappa Fiera San Giuseppe<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dopo due anni di stop dovuti all&#8217;emergenza coronavirus, sabato 19 marzo torna la Fiera di San Giuseppe a Tivoli. Il tradizionale evento si svolger\u00e0 dalle prime ore del mattino fino [&hellip;]<\/p>\n","protected":false},"author":393,"featured_media":8439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-8438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attivita-produttive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>19 marzo: torna la Fiera di San Giuseppe - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19 marzo: torna la Fiera di San Giuseppe - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dopo due anni di stop dovuti all&#8217;emergenza coronavirus, sabato 19 marzo torna la Fiera di San Giuseppe a Tivoli. Il tradizionale evento si svolger\u00e0 dalle prime ore del mattino fino [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T09:34:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-16T11:52:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/pinocchio-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ilaria Betti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilaria Betti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/\"},\"author\":{\"name\":\"Ilaria Betti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"headline\":\"19 marzo: torna la Fiera di San Giuseppe\",\"datePublished\":\"2022-03-16T09:34:46+00:00\",\"dateModified\":\"2022-03-16T11:52:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/\"},\"wordCount\":412,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/pinocchio-scaled.jpg\",\"articleSection\":[\"Attivit\u00e0 Produttive\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/\",\"name\":\"19 marzo: torna la Fiera di San Giuseppe - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/pinocchio-scaled.jpg\",\"datePublished\":\"2022-03-16T09:34:46+00:00\",\"dateModified\":\"2022-03-16T11:52:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/pinocchio-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/03\\\/pinocchio-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Fiera di San Giuseppe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/03\\\/16\\\/19-marzo-torna-la-fiera-di-san-giuseppe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"19 marzo: torna la Fiera di San Giuseppe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\",\"name\":\"Ilaria Betti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"caption\":\"Ilaria Betti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/ibetti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"19 marzo: torna la Fiera di San Giuseppe - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/","og_locale":"it_IT","og_type":"article","og_title":"19 marzo: torna la Fiera di San Giuseppe - Tivoli","og_description":"Dopo due anni di stop dovuti all&#8217;emergenza coronavirus, sabato 19 marzo torna la Fiera di San Giuseppe a Tivoli. Il tradizionale evento si svolger\u00e0 dalle prime ore del mattino fino [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-03-16T09:34:46+00:00","article_modified_time":"2022-03-16T11:52:34+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/pinocchio-scaled.jpg","type":"image\/jpeg"}],"author":"Ilaria Betti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Ilaria Betti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/"},"author":{"name":"Ilaria Betti","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"headline":"19 marzo: torna la Fiera di San Giuseppe","datePublished":"2022-03-16T09:34:46+00:00","dateModified":"2022-03-16T11:52:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/"},"wordCount":412,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/pinocchio-scaled.jpg","articleSection":["Attivit\u00e0 Produttive"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/","name":"19 marzo: torna la Fiera di San Giuseppe - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/pinocchio-scaled.jpg","datePublished":"2022-03-16T09:34:46+00:00","dateModified":"2022-03-16T11:52:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/pinocchio-scaled.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/03\/pinocchio-scaled.jpg","width":2560,"height":1707,"caption":"Fiera di San Giuseppe"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/03\/16\/19-marzo-torna-la-fiera-di-san-giuseppe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"19 marzo: torna la Fiera di San Giuseppe"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f","name":"Ilaria Betti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","caption":"Ilaria Betti"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/ibetti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/393"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8438"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8438\/revisions"}],"predecessor-version":[{"id":8445,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8438\/revisions\/8445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/8439"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}