{"id":8501,"date":"2022-04-01T14:07:49","date_gmt":"2022-04-01T12:07:49","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8501"},"modified":"2022-04-01T14:07:49","modified_gmt":"2022-04-01T12:07:49","slug":"3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/","title":{"rendered":"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0"},"content":{"rendered":"<p>Il 5 aprile si celebra il <strong>3.237\u00b0 Natale di Tivoli<\/strong>: una data che segna\u00a0l&#8217;avvio di un mese di manifestazioni celebrative e rievocative delle antiche origini della citt\u00e0.\u00a0Tutti gli anni il Comune di Tivoli, cos\u00ec come previsto da Statuto, si occupa dell&#8217;organizzazione di eventi inerenti la tradizione storica e\u00a0folcloristica,\u00a0funzionali al rilancio del territorio nonch\u00e9 alla valorizzazione e alla promozione dei beni storico artistici e culturali.<\/p>\n<p>Il Natale di Tivoli viene fatto risalire al\u00a0<strong>5 aprile del 1215 a.C<\/strong>.: allora Catillo, figlio di Anfiarao, comandante e ammiraglio della flotta inviata dal greco Evandro alla conquista di nuovi territori latini, sopraggiunse con i suoi tre figli Tiburto, Corace e Catillo sconfiggendo i Siculi e fondando la nuova citt\u00e0 guidata dal primogenito Tiburto.<\/p>\n<p>Per il 2022 \u00e8 previsto un calendario ricco di appuntamenti, che si svolgeranno dal 5 aprile al 1 maggio. Si va dalla celebrazione del mito di fondazione, programmato in apertura a piazza Campitelli, nel centro della citt\u00e0 medievale, alla tradizionale Infiorata che chiude il mese del Natale. Grande attesa per l&#8217;apertura straordinaria del Museo della Citt\u00e0, nei giorni 9 e 10 aprile: per l&#8217;occasione, saranno previste visite guidate di Paola Perini e Leandro Teodori, presso il centro storico, incentrate sulla conoscenza dei miti tiburtini, a cura dell\u2019Amministrazione Comunale (su prenotazione per un massimo di 20 partecipanti \u2013 info e prenotazioni: serviziculturali@comune.tivoli.rm.it).<\/p>\n<p><strong>IL PROGRAMMA<\/strong><\/p>\n<p>5 aprile ore 9.30. Piazza Campitelli. Cerimonia di Inaugurazione del 3237\u00b0 \u00a0Natale di Tivoli a cura dell\u2019Amministrazione Comunale: \u201cIl mito di fondazione della di Tibur\u201d, con la partecipazione degli studenti di I. C. Tivoli IV \u201cVincenzo Pacifici\u201d e I. C. Tivoli II \u201cA. Baccelli\u201d Tivoli Centro e la partecipazione del Gruppo Storico Villa Adriana.<\/p>\n<p>5\/10 aprile. Ex chiesa dell\u2019Annunziata, Piazza Campitelli. Manifestazione culturale:\u201cLe Allegorie di Tivoli \u2013 Da Ercole alla Sibilla in armonico equilibrio con le ville tiburtine e lo scorrere del tempo\u201d a cura di Antonio Proietti e \u201cIl Caff\u00e8 Culturale\u201d.<\/p>\n<p>Programma:<\/p>\n<p>&#8211; \u00a06 aprile, ore 17.15: inaugurazione dell\u2019esposizione pittorica con presentazione critica e analisi dell\u2019opera \u201cTibur Fugit\u201d di Antonio Proietti a cura di Lucrezia Rubini.<br \/>\n&#8211; \u00a07 aprile, ore 17.30: conferenza di Roberto Borgia su \u201cErcole e la Sibilla Tiburtina nella storia e nell\u2019iconografia\u201d.<br \/>\n&#8211; \u00a08 aprile, ore 9.00 \u2013 13.00: workshop laboratoriale con Antonio Proietti e la classe V C del Liceo Artistico \u201cPublio Elio Adriano\u201d, coordinato da Lucrezia Rubini e Giovanni Borgia.<br \/>\n&#8211; \u00a09 aprile, ore 17.30: conversazione sul libro \u201cCronache dal mondo dell\u2019arte\u201d di Antonio Capitano, con letture di Marianna Scibetta, dialoga con l\u2019autore Gianni Andrei.<br \/>\n&#8211; 10 aprile, ore 18.00: chiusura dell\u2019esposizione.<\/p>\n<p>9 &#8211; 10 aprile. Apertura straordinaria\u2013 Museo della Citt\u00e0. Visite Guidate di Paola Perini e Leandro Teodori, presso il centro storico, incentrate sulla conoscenza dei miti tiburtini, a cura dell\u2019Amministrazione Comunale (su prenotazione per un massimo di 20 partecipanti \u2013 info e prenotazioni: serviziculturali@comune.tivoli.rm.it).<\/p>\n<p>Programma:<\/p>\n<p>&#8211;\u00a0\u00a0 \u00a09 aprile: partenza ore 9.30 da piazza Garibaldi, arrivo ore 11.30 a Villa Gregoriana dove il FAI \u2013 Fondo per l\u2019ambiente Italiano avr\u00e0 il piacere di offrire l\u2019ingresso gratuito ai cittadini di Tivoli e, su prenotazione, visita guidata in dialetto tiburtino.<br \/>\n&#8211;\u00a0\u00a0 \u00a010 aprile: partenza ore 9.30 da piazza Garibaldi per iniziare la visita guidata a Rocca Pia, arrivo ore 11.15 al Museo della Citt\u00e0 dove sono previste visite guidate gratuite alla mostra \u201cLe grandi Ville Romane del territorio tiburtino\u201d.<\/p>\n<p>9 aprile, ore 10.00. Sala Conferenze del Museo della Citt\u00e0, Piazza Campitelli. Convegno: L. Di Giuseppe, \u201cIl completamento del recupero del Palazzo Mauro Macera \u2013 Museo della Citt\u00e0, all\u2019interno del Complesso dell\u2019Annunziata; M. A. Tomei, \u00a0\u201cPercorsi turistico &#8211; culturali collegati alla mostra &#8211; Le grandi Ville Romane del territorio tiburtino -\u201d; Zaccaria Mari \u201cDimore da principi: le villae di otium del territorio tiburtino\u201d.<br \/>\n&#8211;\u00a0\u00a0 \u00a0ore 15.30. Conferenza \u201cCamorra, donne, Napoli\u201d Ciro Corona racconta come la lotta alla camorra pu\u00f2 riuscire quando si danno possibilit\u00e0 diverse, a cura dell\u2019Associazione \u201cIl Laboratorio del Possibile ASP\u201d.<\/p>\n<p>10 aprile. Sala Roesler Franz (ex chiesa di San Michele). Mostra fotografica \u201cLeo Click VI Edizione\u201d a cura di Leo Club Tivoli Host, in collaborazione con I.T.C.G. Enrico Fermi di Tivoli.<\/p>\n<p>10 aprile, ore 16.30. Santuario di Ercole Vincitore. Concerto Celebrativo per il Natale di Tivoli per Soli, Piano ed Ensemble di Fiati con il Soprano Arianna Morelli dal Teatro dell\u2019Opera di Roma, la Vocalist Anna Ragozzino dietro la direzione Artistica di Giuseppe Galli, a cura dell\u2019Accademia Ergo Cantemus di Tivoli.<\/p>\n<p>15 aprile, ore 18.00. Sala Conferenze delle Scuderie Estensi. Presentazione del libro \u201cL\u2019incantesimo infranto\u201d di Nello Di Millo a cura dell\u2019Associazione \u201cIl Laboratorio del Possibile ASP\u201d.<\/p>\n<p>22 aprile, ore 17.30. Convitto Nazionale \u201cA. di Savoia\u201d di Tivoli. Celebrazione dantesca: Adalberto Marinucci, donazione del busto in terracotta di Dante Alighieri; Adalberto Marinucci, M.A. Coccanari, A. Boratto, D. Viglietta, presentazione di brani danteschi del \u201cPurgatorio\u201d; A. Medri, T. Ranieri, presentazione dei video sulle bellezze di Tivoli; \u00a0L. Galeone, lettura di poesie.<\/p>\n<p>22 aprile, ore 17.30. Ex Seminario Vescovile, piazza del Seminario. Presentazione del libro \u201cLa Valle dell\u2019Inferno\u201d di Carlo Innocenti, a cura della Libera Universit\u00e0 I. Giordani \u201cLUIG\u201d.<\/p>\n<p>25 aprile. Sala Roesler Franz (ex chiesa di San Michele).Mostra fotografica \u201cLa natura, le emozioni e le prospettive del territorio italiano\u201d a cura del Club Alpino Italiano \u2013 CAI di Tivoli.<\/p>\n<p>29 aprile, ore 18.30. Sala Conferenze delle Scuderie Estensi. \u201cXLVI Stagione concertistica \u2013 Concerto per pianoforte\u201d a cura di Associazione Culturale \u201cCitt\u00e0 di Tivoli\u201d e Associazione musicale G. Martucci.<\/p>\n<p>30 aprile \u2013 1 maggio. \u201cTivoli in fiore\u201d. Infiorata in onore alla Madonna di Quintiliolo a cura delle Associazioni \u201cContrada via Maggiore\u201d, \u201cTutti_gi\u00f9\u201d e \u201cLe Porte Belle\u201d, coadiuvati dall\u2019Unione Commercianti di Tivoli.<\/p>\n<p>Programma:<br \/>\n&#8211;\u00a0\u00a0 \u00a030 aprile, ore 18.00. Preparazione dei tappeti floreali a cura dei Maestri Infioratori in via dei Sosii, Via Palatina, Piazza di Vesta (uscita Villa Gregoriana), L.go Cesare Battisti e Piazza S. Vincenzo.<\/p>\n<p>&#8211;\u00a0\u00a0 \u00a01 maggio ore 10.00. In Via dei Sosii al passaggio della SS. Madonna di Quintiliolo la Soprano Monia Salvati canter\u00e0 l\u2019Ave Maria di Schubert accompagnata dal maestro Organista Alessio Salvati.<br \/>\nL\u2019Associazione Historia \u201cRievocazione Storica\u201d svolger\u00e0 una manifestazione con legionari e arcieri dell\u2019antica Roma.<br \/>\n\u2022\u00a0\u00a0 \u00a0ore 16.00: esibizione delle Tamburellare Tiburtine<br \/>\n\u2022\u00a0\u00a0 \u00a0ore 17.00: Storie in dialetto tiburtino a cura de \u201cL\u2019allegra compagnia per un sorriso in pi\u00f9\u201d.<br \/>\nIntrattenimento musicale e percorso enogastronomico nelle zone interessate, a cura di Unione Commercianti di Tivoli.<\/p>\n<p>1 maggio, ore 19.00. Basilica Cattedrale di San Lorenzo Martire. Concerto in onore della Beata Vergine SS. Di Quintiliolo a cura dell\u2019Associazione Culturale \u201cCitt\u00e0 di Tivoli\u201d.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_8502\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/thumbnail_4e464b09-7b97-46b4-a2d3-78533eac6051.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/thumbnail_4e464b09-7b97-46b4-a2d3-78533eac6051.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Programma Natale di Tivoli 2022<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il 5 aprile si celebra il 3.237\u00b0 Natale di Tivoli: una data che segna\u00a0l&#8217;avvio di un mese di manifestazioni celebrative e rievocative delle antiche origini della citt\u00e0.\u00a0Tutti gli anni il [&hellip;]<\/p>\n","protected":false},"author":393,"featured_media":8503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-8501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Il 5 aprile si celebra il 3.237\u00b0 Natale di Tivoli: una data che segna\u00a0l&#8217;avvio di un mese di manifestazioni celebrative e rievocative delle antiche origini della citt\u00e0.\u00a0Tutti gli anni il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-01T12:07:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/natale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"565\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ilaria Betti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilaria Betti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/\"},\"author\":{\"name\":\"Ilaria Betti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"headline\":\"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0\",\"datePublished\":\"2022-04-01T12:07:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/\"},\"wordCount\":1049,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/natale.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/\",\"name\":\"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/natale.png\",\"datePublished\":\"2022-04-01T12:07:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/natale.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/natale.png\",\"width\":565,\"height\":352},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/01\\\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\",\"name\":\"Ilaria Betti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"caption\":\"Ilaria Betti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/ibetti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/","og_locale":"it_IT","og_type":"article","og_title":"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0 - Tivoli","og_description":"Il 5 aprile si celebra il 3.237\u00b0 Natale di Tivoli: una data che segna\u00a0l&#8217;avvio di un mese di manifestazioni celebrative e rievocative delle antiche origini della citt\u00e0.\u00a0Tutti gli anni il [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-04-01T12:07:49+00:00","og_image":[{"width":565,"height":352,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/natale.png","type":"image\/png"}],"author":"Ilaria Betti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Ilaria Betti","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/"},"author":{"name":"Ilaria Betti","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"headline":"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0","datePublished":"2022-04-01T12:07:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/"},"wordCount":1049,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/natale.png","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/","name":"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/natale.png","datePublished":"2022-04-01T12:07:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/natale.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/natale.png","width":565,"height":352},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/01\/3-237-natale-di-tivoli-un-mese-di-eventi-per-il-compleanno-della-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"3.237\u00b0 Natale di Tivoli: un mese di eventi per il compleanno della citt\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f","name":"Ilaria Betti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","caption":"Ilaria Betti"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/ibetti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/393"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8501"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8501\/revisions"}],"predecessor-version":[{"id":8504,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8501\/revisions\/8504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/8503"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}