{"id":8516,"date":"2022-04-06T09:40:58","date_gmt":"2022-04-06T07:40:58","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8516"},"modified":"2022-04-06T09:40:58","modified_gmt":"2022-04-06T07:40:58","slug":"natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/","title":{"rendered":"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &#8220;Ercole e la Sibilla Tiburtina&#8221;"},"content":{"rendered":"<p>Gioved\u00ec <strong>7 aprile<\/strong> 2022 alle ore 17,30 nel Complesso Monumentale dell\u2019Annunziata, in Piazza dell\u2019Annunziata a Tivoli, il prof. Roberto Borgia terr\u00e0 una conferenza dal titolo <strong>\u201cErcole e la Sibilla Tiburtina nella storia e nell\u2019iconografia\u201d<\/strong>, nell\u2019ambito del programma \u201cLe allegorie di Tivoli\u201d e dell\u2019inaugurazione dell\u2019opera pittorica Tempus fugit del maestro Antonio Proietti.<\/p>\n<p>La conferenza \u00e8 dedicata alle due figure principali del pantheon tiburtino: innanzitutto Ercole, che proprio nell\u2019antica Tibur fu la divinit\u00e0 pi\u00f9 venerata. Tibur, citt\u00e0 dell\u2019Aniene, della cascata, delle acque sotterranee e delle caverne, non poteva non appropriarsi del mito dell\u2019eroe tebano, che, introdotto come divinit\u00e0 straniera, assunse importanza fondamentale proprio per le caratteristiche che il mito, nella sua lunga elaborazione, gli aveva attribuito e con la successiva costruzione del Santuario di Ercole Vincitore. Di Ercole verr\u00e0 esaminato anche l\u2019aspetto iconografico con gli affreschi e le statue della Villa d\u2019Este e soprattutto con l\u2019importante bassorilievo presente nella Mensa Ponderaria.<\/p>\n<p>Della Sibilla Tiburtina verr\u00e0 esaminato l\u2019aspetto non sempre compreso della sua assimilazione al mito di Ino-Leucotea, fatto proprio dagli umanisti che nel secolo XVI fecero parte dell\u2019Accademia degli Agevoli e che ispirarono anche qui, soprattutto per opera di Pirro Ligorio, gli affreschi presenti negli appartamenti da basso della Villa d\u2019Este e l\u2019iconografia delle statue presenti nella fontana dell\u2019Ovato. Si approfondiranno naturalmente anche gli aspetti della Sibilla Tiburtina, ricordati dalle fonti classiche e medievali.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_8518\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/Manifesto_Ercole_e_Sibilla_7_aprile_2022_rid.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/Manifesto_Ercole_e_Sibilla_7_aprile_2022_rid.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Manifesto Ercole e Sibilla<\/a><\/li>\n<li><a id=\"wpba_attachment_list_8519\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/tib-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/tib-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Programma Le Allegorie di Tivoli<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 7 aprile 2022 alle ore 17,30 nel Complesso Monumentale dell\u2019Annunziata, in Piazza dell\u2019Annunziata a Tivoli, il prof. Roberto Borgia terr\u00e0 una conferenza dal titolo \u201cErcole e la Sibilla Tiburtina [&hellip;]<\/p>\n","protected":false},"author":393,"featured_media":8517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-8516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &quot;Ercole e la Sibilla Tiburtina&quot; - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &quot;Ercole e la Sibilla Tiburtina&quot; - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 7 aprile 2022 alle ore 17,30 nel Complesso Monumentale dell\u2019Annunziata, in Piazza dell\u2019Annunziata a Tivoli, il prof. Roberto Borgia terr\u00e0 una conferenza dal titolo \u201cErcole e la Sibilla Tiburtina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T07:40:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/ercole.png\" \/>\n\t<meta property=\"og:image:width\" content=\"508\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ilaria Betti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilaria Betti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/\"},\"author\":{\"name\":\"Ilaria Betti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"headline\":\"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &#8220;Ercole e la Sibilla Tiburtina&#8221;\",\"datePublished\":\"2022-04-06T07:40:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/\"},\"wordCount\":247,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/ercole.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/\",\"name\":\"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza \\\"Ercole e la Sibilla Tiburtina\\\" - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/ercole.png\",\"datePublished\":\"2022-04-06T07:40:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/ercole.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/04\\\/ercole.png\",\"width\":508,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/04\\\/06\\\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &#8220;Ercole e la Sibilla Tiburtina&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\",\"name\":\"Ilaria Betti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"caption\":\"Ilaria Betti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/ibetti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza \"Ercole e la Sibilla Tiburtina\" - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/","og_locale":"it_IT","og_type":"article","og_title":"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza \"Ercole e la Sibilla Tiburtina\" - Tivoli","og_description":"Gioved\u00ec 7 aprile 2022 alle ore 17,30 nel Complesso Monumentale dell\u2019Annunziata, in Piazza dell\u2019Annunziata a Tivoli, il prof. Roberto Borgia terr\u00e0 una conferenza dal titolo \u201cErcole e la Sibilla Tiburtina [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-04-06T07:40:58+00:00","og_image":[{"width":508,"height":315,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/ercole.png","type":"image\/png"}],"author":"Ilaria Betti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Ilaria Betti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/"},"author":{"name":"Ilaria Betti","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"headline":"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &#8220;Ercole e la Sibilla Tiburtina&#8221;","datePublished":"2022-04-06T07:40:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/"},"wordCount":247,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/ercole.png","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/","name":"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza \"Ercole e la Sibilla Tiburtina\" - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/ercole.png","datePublished":"2022-04-06T07:40:58+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/ercole.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/04\/ercole.png","width":508,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/04\/06\/natale-di-tivoli-giovedi-7-aprile-la-conferenza-ercole-e-la-sibilla-tiburtina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Natale di Tivoli, gioved\u00ec 7 aprile la conferenza &#8220;Ercole e la Sibilla Tiburtina&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f","name":"Ilaria Betti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","caption":"Ilaria Betti"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/ibetti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/393"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8516"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8516\/revisions"}],"predecessor-version":[{"id":8520,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8516\/revisions\/8520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/8517"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}