{"id":8778,"date":"2022-05-31T10:47:06","date_gmt":"2022-05-31T08:47:06","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=8778"},"modified":"2022-05-31T10:47:06","modified_gmt":"2022-05-31T08:47:06","slug":"torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/","title":{"rendered":"Torna &#8220;Tivoli in passerella&#8221;: dal 4 al 5 giugno sfilate, musica e ospiti"},"content":{"rendered":"<p>Torna in presenza, sabato e domenica 4 e 5 giugno,\u00a0<strong>&#8220;Tivoli in passerella&#8221;<\/strong>, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, con la regia di Paolo Pizzolorusso. I protagonisti saranno\u00a0i commercianti tiburtini insieme al cast di modelle e modelli, i quali indosseranno\u00a0i capi scelti e offerti dai titolari degli esercizi commerciali della citt\u00e0. Appuntamento alle Scuderie Estensi: sabato dalle ore 17.30 sar\u00e0 possibile assistere a mostre, convegni ed esibizioni, mentre domenica 5 giugno, dalle ore 17, si terranno\u00a0proiezioni di slide fotografiche e\u00a0la\u00a0<strong>sfilata di moda&amp;trend<\/strong>, con una variet\u00e0 di artisti ed ospiti.<\/p>\n<p>L&#8217;iniziativa coinvolge non soltanto la\u00a0<strong>realt\u00e0 giovanile locale<\/strong>, ma anche molte delle\u00a0associazioni tiburtine impegnate nell\u2019ambito culturale e sociale, ad esempio attraverso la partecipazione attiva di ragazzi con disabilit\u00e0.<\/p>\n<p>L&#8217;obiettivo dell&#8217;evento, nato nel 2014 da un&#8217;idea di Matteo Pizzolorusso, presidente dell&#8217;Associazione Culturale &#8220;Tivoli in passerella, moda, musica e commercio&#8221;, \u00e8 quello di\u00a0<strong>&#8220;dare voce&#8221; ai commercianti locali<\/strong>: \u00abDopo un periodo buio come quello della pandemia, abbiamo bisogno di una boccata d&#8217;aria fresca, abbiamo bisogno di uscire e di riappropriarci di quelle che erano le nostre passioni. La moda \u00e8 una di queste &#8211; afferma -.\u00a0Fin dal 2014 l&#8217;intento della manifestazione \u00e8 quello di valorizzare il negozio &#8220;sotto casa&#8221;, che nulla ha da invidiare alle grandi catene commerciali\u00bb.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_8780\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/PHOTO-2022-05-31-08-20-34.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/PHOTO-2022-05-31-08-20-34.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>LOCANDINA Tivoli in Passerella<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Torna in presenza, sabato e domenica 4 e 5 giugno,\u00a0&#8220;Tivoli in passerella&#8221;, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, [&hellip;]<\/p>\n","protected":false},"author":393,"featured_media":8779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-8778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torna &quot;Tivoli in passerella&quot;: dal 4 al 5 giugno sfilate, musica e ospiti - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torna &quot;Tivoli in passerella&quot;: dal 4 al 5 giugno sfilate, musica e ospiti - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Torna in presenza, sabato e domenica 4 e 5 giugno,\u00a0&#8220;Tivoli in passerella&#8221;, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-31T08:47:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/tivoli.png\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ilaria Betti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilaria Betti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/\"},\"author\":{\"name\":\"Ilaria Betti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"headline\":\"Torna &#8220;Tivoli in passerella&#8221;: dal 4 al 5 giugno sfilate, musica e ospiti\",\"datePublished\":\"2022-05-31T08:47:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/\"},\"wordCount\":228,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/05\\\/tivoli.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/\",\"name\":\"Torna \\\"Tivoli in passerella\\\": dal 4 al 5 giugno sfilate, musica e ospiti - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/05\\\/tivoli.png\",\"datePublished\":\"2022-05-31T08:47:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/05\\\/tivoli.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/05\\\/tivoli.png\",\"width\":738,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/05\\\/31\\\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torna &#8220;Tivoli in passerella&#8221;: dal 4 al 5 giugno sfilate, musica e ospiti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/412bd42c6bd7051ef22b2c2a7005111f\",\"name\":\"Ilaria Betti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g\",\"caption\":\"Ilaria Betti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/ibetti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torna \"Tivoli in passerella\": dal 4 al 5 giugno sfilate, musica e ospiti - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/","og_locale":"it_IT","og_type":"article","og_title":"Torna \"Tivoli in passerella\": dal 4 al 5 giugno sfilate, musica e ospiti - Tivoli","og_description":"Torna in presenza, sabato e domenica 4 e 5 giugno,\u00a0&#8220;Tivoli in passerella&#8221;, l&#8217;evento, patrocinato dal Comune di Tivoli, che mixa moda, musica e commercio, ideato e presentato da Matteo Pizzolorusso, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-05-31T08:47:06+00:00","og_image":[{"width":738,"height":590,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/tivoli.png","type":"image\/png"}],"author":"Ilaria Betti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Ilaria Betti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/"},"author":{"name":"Ilaria Betti","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"headline":"Torna &#8220;Tivoli in passerella&#8221;: dal 4 al 5 giugno sfilate, musica e ospiti","datePublished":"2022-05-31T08:47:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/"},"wordCount":228,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/tivoli.png","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/","name":"Torna \"Tivoli in passerella\": dal 4 al 5 giugno sfilate, musica e ospiti - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/tivoli.png","datePublished":"2022-05-31T08:47:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/tivoli.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/05\/tivoli.png","width":738,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/05\/31\/torna-tivoli-in-passerella-dal-4-al-5-giugno-sfilate-musica-e-ospiti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Torna &#8220;Tivoli in passerella&#8221;: dal 4 al 5 giugno sfilate, musica e ospiti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/412bd42c6bd7051ef22b2c2a7005111f","name":"Ilaria Betti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17de49d3fb918f6e23d53080221fdab89e4f63997cc71f74cb13d476e6a899fa?s=96&d=mm&r=g","caption":"Ilaria Betti"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/ibetti\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/393"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=8778"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8778\/revisions"}],"predecessor-version":[{"id":8781,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/8778\/revisions\/8781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/8779"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=8778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=8778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=8778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}