{"id":9054,"date":"2022-07-22T11:47:07","date_gmt":"2022-07-22T09:47:07","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9054"},"modified":"2022-07-27T17:42:26","modified_gmt":"2022-07-27T15:42:26","slug":"notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/","title":{"rendered":"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte"},"content":{"rendered":"<p>Gioved\u00ec 28 luglio, dalle ore 20 alle 24, nella magnifica cornice di piazza Campitelli, a Tivoli, si svolger\u00e0 la <strong>settima edizione della\u00a0Notte Bianca del libro e della lettura &#8220;M&#8217;illumino d&#8217;immenso&#8221;<\/strong>. L&#8217;evento \u00e8 organizzato dalle Politiche del Comune per la promozione della lettura, su proposta\u00a0della consigliera del sindaco\u00a0<strong>Rosa Mininno.\u00a0<\/strong>Collabora alla manifestazione anche la biblioteca comunale Maria Coccanari Fornari.<\/p>\n<p>Il tema conduttore proposto in questa edizione \u00e8 il gemellaggio di Tivoli con le quattro citt\u00e0: Saint Amand les Eaux (Francia), Focsani (Romania), Delfi (Grecia) e Yugawara (Giappone). Si leggeranno brani di testi dedicati alla citt\u00e0 di Tivoli e la sua storia, e brani di letteratura, teatro, saggistica italiana, francese, giapponese, greca, rumena, prevedendo anche eventuali letture in lingua originale con successiva traduzione. Parteciperanno anche scrittori, poeti, critici letterari e giornalisti del territorio. Parteciperanno attivamente alla Notte Bianca i sottoscrittori del Patto per la Lettura.<\/p>\n<p>In caso di maltempo la manifestazione si terr\u00e0 presso la sala conferenze del Museo Civico in piazza Campitelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 28 luglio, dalle ore 20 alle 24, nella magnifica cornice di piazza Campitelli, a Tivoli, si svolger\u00e0 la settima edizione della\u00a0Notte Bianca del libro e della lettura &#8220;M&#8217;illumino d&#8217;immenso&#8221;. [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":9095,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 28 luglio, dalle ore 20 alle 24, nella magnifica cornice di piazza Campitelli, a Tivoli, si svolger\u00e0 la settima edizione della\u00a0Notte Bianca del libro e della lettura &#8220;M&#8217;illumino d&#8217;immenso&#8221;. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-22T09:47:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-27T15:42:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/notte-bianca-def.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte\",\"datePublished\":\"2022-07-22T09:47:07+00:00\",\"dateModified\":\"2022-07-27T15:42:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/\"},\"wordCount\":173,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/notte-bianca-def.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/\",\"name\":\"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/notte-bianca-def.jpg\",\"datePublished\":\"2022-07-22T09:47:07+00:00\",\"dateModified\":\"2022-07-27T15:42:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/notte-bianca-def.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/notte-bianca-def.jpg\",\"width\":1120,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/22\\\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/","og_locale":"it_IT","og_type":"article","og_title":"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte - Tivoli","og_description":"Gioved\u00ec 28 luglio, dalle ore 20 alle 24, nella magnifica cornice di piazza Campitelli, a Tivoli, si svolger\u00e0 la settima edizione della\u00a0Notte Bianca del libro e della lettura &#8220;M&#8217;illumino d&#8217;immenso&#8221;. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-22T09:47:07+00:00","article_modified_time":"2022-07-27T15:42:26+00:00","og_image":[{"width":1120,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/notte-bianca-def.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte","datePublished":"2022-07-22T09:47:07+00:00","dateModified":"2022-07-27T15:42:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/"},"wordCount":173,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/notte-bianca-def.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/","name":"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/notte-bianca-def.jpg","datePublished":"2022-07-22T09:47:07+00:00","dateModified":"2022-07-27T15:42:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/notte-bianca-def.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/notte-bianca-def.jpg","width":1120,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/22\/notte-bianca-del-libro-e-della-lettura-28-luglio-a-piazza-campitelli-fino-a-mezzanotte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Notte Bianca del libro e della lettura: 28 luglio a piazza Campitelli fino a mezzanotte"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9054"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9054\/revisions"}],"predecessor-version":[{"id":9090,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9054\/revisions\/9090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/9095"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}