{"id":9077,"date":"2022-07-26T14:22:31","date_gmt":"2022-07-26T12:22:31","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9077"},"modified":"2022-07-26T20:08:33","modified_gmt":"2022-07-26T18:08:33","slug":"al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/","title":{"rendered":"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili"},"content":{"rendered":"<p>\u00c8 stato pubblicato\u00a0il bando per l\u2019<strong>iscrizione ai centri ricreativi distrettuali per minori, dai 3 ai 18 anni, e per giovani diversamente abili fino a 24 anni<\/strong>, residenti nel distretto RM5.3. Le famiglie potranno scegliere, in base alle proprie esigenze, tra le strutture che hanno risposto alla manifestazione di interesse pubblicata di recente e che\u00a0sono risultate in possesso dei requisiti. L&#8217;Assessore al Welfare Maria Luisa Cappelli esprime soddisfazione: &#8220;Continua l&#8217;impegno del nostro settore per garantire ai ragazzi e ai giovani disabili un&#8217;estate all&#8217;insegna della socialit\u00e0 e dell&#8217;inclusivit\u00e0. Grazie alla preziosa attivit\u00e0 dei centri ricreativi distrettuali riusciamo a prenderci cura di loro a dovere, con strutture idonee e proponendo attivit\u00e0 adatte alle loro necessit\u00e0. Il termine per la presentazione delle domande, inizialmente fissato al 2 agosto, potrebbe essere prorogato. Il progetto prevede una continuit\u00e0 di attivit\u00e0 anche per il periodo autunnale&#8221;.<\/p>\n<p>Una volta acquisite le domande, si proceder\u00e0 alla formazione di un\u2019unica graduatoria distrettuale, con erogazione delle rette settimanali direttamente ai centri, fino ad esaurimento dei fondi regionali.\u00a0La domanda dovr\u00e0 essere presentata su apposito modulo, completa della documentazione necessaria e consegnata a mano al proprio comune di residenza o via PEC all\u2019indirizzo info@pec.comune.tivoli.rm.it, citando in oggetto \u201cIscrizione centri ricreativi estate 2022\u201d. \u00c8 possibile la presentazione di una sola domanda per nucleo familiare. La scadenza del bando \u00e8 fissata alle\u00a0<strong>ore 12 del 2 agosto 2022<\/strong>. L&#8217;avviso\u00a0integrale con modello di domanda, in allegato,\u00a0pu\u00f2 essere scaricato sul sito istituzionale http:\/\/www.comune.tivoli.rm.it ed \u00e8 disponibile presso gli Uffici U.R.P. del Comune di Tivoli, Piazza del Governo 2, nonch\u00e9 presso gli Uffici Comunali del distretto.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_9079\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/Centri-ricreativi.-Modulo-di-domanda.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/Centri-ricreativi.-Modulo-di-domanda.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Centri ricreativi. Modulo di domanda<\/a><\/li>\n<li><a id=\"wpba_attachment_list_9080\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/Centri-ricreativi.-Avviso-Pubblico-Estate-2022-p.-39573-26.07.2022.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/Centri-ricreativi.-Avviso-Pubblico-Estate-2022-p.-39573-26.07.2022.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Centri ricreativi. Avviso Pubblico Estate 2022 p. 39573 26.07.2022<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 stato pubblicato\u00a0il bando per l\u2019iscrizione ai centri ricreativi distrettuali per minori, dai 3 ai 18 anni, e per giovani diversamente abili fino a 24 anni, residenti nel distretto RM5.3. [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":9078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-9077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili - Tivoli\" \/>\n<meta property=\"og:description\" content=\"\u00c8 stato pubblicato\u00a0il bando per l\u2019iscrizione ai centri ricreativi distrettuali per minori, dai 3 ai 18 anni, e per giovani diversamente abili fino a 24 anni, residenti nel distretto RM5.3. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-26T12:22:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T18:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili\",\"datePublished\":\"2022-07-26T12:22:31+00:00\",\"dateModified\":\"2022-07-26T18:08:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/\"},\"wordCount\":279,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/\",\"name\":\"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg\",\"datePublished\":\"2022-07-26T12:22:31+00:00\",\"dateModified\":\"2022-07-26T18:08:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/07\\\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/07\\\/26\\\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/","og_locale":"it_IT","og_type":"article","og_title":"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili - Tivoli","og_description":"\u00c8 stato pubblicato\u00a0il bando per l\u2019iscrizione ai centri ricreativi distrettuali per minori, dai 3 ai 18 anni, e per giovani diversamente abili fino a 24 anni, residenti nel distretto RM5.3. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-26T12:22:31+00:00","article_modified_time":"2022-07-26T18:08:33+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili","datePublished":"2022-07-26T12:22:31+00:00","dateModified":"2022-07-26T18:08:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/"},"wordCount":279,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/","name":"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg","datePublished":"2022-07-26T12:22:31+00:00","dateModified":"2022-07-26T18:08:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/07\/maxime-bhm-6cQHvjzmZOU-unsplash-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/07\/26\/al-via-le-iscrizioni-ai-centri-ricreativi-distrettuali-per-minori-e-per-giovani-disabili-domande-fino-al-2-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Al via le iscrizioni ai centri ricreativi distrettuali per minori e per giovani disabili"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9077"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9077\/revisions"}],"predecessor-version":[{"id":9084,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9077\/revisions\/9084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/9078"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}