{"id":9133,"date":"2022-08-09T13:22:28","date_gmt":"2022-08-09T11:22:28","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9133"},"modified":"2022-08-09T13:22:28","modified_gmt":"2022-08-09T11:22:28","slug":"biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/","title":{"rendered":"Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221;: chiusa fino al 26 agosto"},"content":{"rendered":"<p>Si comunica all&#8217;utenza che la Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221; rester\u00e0 chiusa al pubblico fino al 26 agosto. Verr\u00e0 riaperta regolarmente luned\u00ec 29 agosto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica all&#8217;utenza che la Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221; rester\u00e0 chiusa al pubblico fino al 26 agosto. Verr\u00e0 riaperta regolarmente luned\u00ec 29 agosto.<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9133","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biblioteca Comunale di Tivoli &quot;Maria Coccanari Fornari&quot;: chiusa fino al 26 agosto - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biblioteca Comunale di Tivoli &quot;Maria Coccanari Fornari&quot;: chiusa fino al 26 agosto - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si comunica all&#8217;utenza che la Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221; rester\u00e0 chiusa al pubblico fino al 26 agosto. Verr\u00e0 riaperta regolarmente luned\u00ec 29 agosto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-09T11:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221;: chiusa fino al 26 agosto\",\"datePublished\":\"2022-08-09T11:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/\"},\"wordCount\":35,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/\",\"name\":\"Biblioteca Comunale di Tivoli \\\"Maria Coccanari Fornari\\\": chiusa fino al 26 agosto - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2022-08-09T11:22:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/08\\\/09\\\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221;: chiusa fino al 26 agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biblioteca Comunale di Tivoli \"Maria Coccanari Fornari\": chiusa fino al 26 agosto - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/","og_locale":"it_IT","og_type":"article","og_title":"Biblioteca Comunale di Tivoli \"Maria Coccanari Fornari\": chiusa fino al 26 agosto - Tivoli","og_description":"Si comunica all&#8217;utenza che la Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221; rester\u00e0 chiusa al pubblico fino al 26 agosto. Verr\u00e0 riaperta regolarmente luned\u00ec 29 agosto.","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-08-09T11:22:28+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221;: chiusa fino al 26 agosto","datePublished":"2022-08-09T11:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/"},"wordCount":35,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/","name":"Biblioteca Comunale di Tivoli \"Maria Coccanari Fornari\": chiusa fino al 26 agosto - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2022-08-09T11:22:28+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/08\/09\/biblioteca-comunale-di-tivoli-maria-coccanari-fornari-chiusa-fino-al-26-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Biblioteca Comunale di Tivoli &#8220;Maria Coccanari Fornari&#8221;: chiusa fino al 26 agosto"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9133"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9133\/revisions"}],"predecessor-version":[{"id":9134,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9133\/revisions\/9134"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}