{"id":9231,"date":"2022-09-05T10:59:32","date_gmt":"2022-09-05T08:59:32","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9231"},"modified":"2022-09-02T11:01:22","modified_gmt":"2022-09-02T09:01:22","slug":"settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/","title":{"rendered":"Settembre tiburtino: mostra sull&#8217;ambiente &#8220;Se volessimo ancora salvare la Terra&#8221; dal 6 al 15"},"content":{"rendered":"<p>In occasione del Settembre tiburtino, la citt\u00e0 di Tivoli si prepara ad ospitare <strong>&#8220;Se volessimo ancora salvare la terra&#8221;<\/strong>, progetto che prende spunto dal discorso della scrittrice Marguerite Yourcenar, pronunciato il 30 settembre 1987 all&#8217;Universit\u00e0 Laval (Montr\u00e9al, Canada) e pubblicato (inedito) dal Centro Internazionale Antinoo &#8211; M. Yourcenar nel volume &#8220;Come l&#8217;ombra&#8221; nel 2004, <strong>per la salvaguardia dell&#8217;ambiente<\/strong>.<\/p>\n<p>L&#8217;evento, in collaborazione con Earth Day Italia (Nazioni Unite), prevede una <strong>mostra pittorica del Maestro Mario Moretti <\/strong>(1937 &#8211; 2017) che avr\u00e0 luogo presso le Scuderie Estensi di Tivoli dal <strong>6 al 15\u00a0settembre 2022<\/strong>, territorio scelto per la flora, la fauna e le ville patrimonio UNESCO: Villa Gregoriana, Villa\u00a0d&#8217;Este\u00a0e Villa Adriana, quest&#8217;ultima molto amata da Marguerite Yourcenar ed embrione del suo capolavoro\u00a0<strong><em>Memorie di Adriano.\u00a0<\/em><\/strong>All&#8217;inaugurazione della mostra ( 6 settembre, alle ore 18, presso le Scuderie Estensi di Tivoli) saranno presenti il sindaco di Tivoli Giuseppe Proietti, il presidente del Centro Internazionale Antinoo per l&#8217;Arte Luigi Romiti, e il presidente di Earth Day Italia Pierluigi Sassi.<\/p>\n<p>Il 16 settembre, alle ore 10, presso Pomata (Tivoli), \u00e8 prevista la <strong>visita guidata &#8220;naturalistico &#8211; archeologica&#8221;<\/strong> a cura di Gianni Innocenti, assessore all&#8217;Ambiente del Comune di Tivoli e Fabiana Marino, archeologa. Dal 22 settembre al 23 ottobre, la mostra pittorica di Mario Moretti si &#8220;trasferisce&#8221; a Roma, nel palazzo di Santa Chiara, in piazza Santa Chiara.<\/p>\n<p>Seguir\u00e0 un convegno dedicato all&#8217;ambiente il <strong>30 settembre<\/strong> presso il Ministero della Cultura (Roma, Via del Collegio Romano, Sala Spadolini), in presenza e in videoconferenza, al quale parteciperanno <strong>studiosi del settore<\/strong>, per citarne alcuni Joan E. Howard (Presidente Trust Marguerite Yourcenar, USA), R\u00e9my Poignault (Direttore della SIEY\u00a0Soci\u00e9t\u00e9 Internationale d\u2019\u00c9tudes Yourcenariennes &#8211;\u00a0Universit\u00e9 de Clermont-Ferrand, Francia), Fran\u00e7oise Bonali Fiquet (studiosa di Marguerite Yourcenar, Universit\u00e0 di Parma), Carminella Biondi (gi\u00e0\u00a0Direttore del Dipartimento di Lingue e letterature straniere moderne Universit\u00e0 di Bologna), l&#8217;Ambasciatore di Francia in Italia S.E. Christian Masset, il Prof. Avv. Emmanuele F.M. Emanuele (Presidente Fondazione Terzo Pilastro Internazionale).<\/p>\n<p>Il <strong>Centro Internazionale Antinoo per l\u2019Arte<\/strong> \u00e8 sorto e si \u00e8 sviluppato nell\u2019ispirazione della scrittrice franco-belga Marguerite Yourcenar e delle sue opere letterarie per una promozione nazionale e internazionale della cultura in ogni sua forma espressiva. La promozione di iniziative culturali \u00e8, infatti, un impegno che da tempo l\u2019associazione porta avanti, convinta com\u2019\u00e8, in tutte le sue numerose componenti di artisti, storici dell\u2019arte, archeologi, letterati, critici, dell\u2019importanza e del ruolo sociale che la cultura deve avere per contribuire fortemente ad accrescere il valore della vita di ogni individuo, della citt\u00e0 di Roma e del nostro paese intero. Come scrive il prof. Raffaele Mambella, &#8220;ripartire dalla personalit\u00e0 storica dell\u2019imperatore Adriano, da quella mitica del suo amasio Antinoo e da quella letteraria e poliedrica di Marguerite Yourcenar, significa per noi restituire a Roma, e al mondo che vi si riconosca, quel ponderato pragmatismo culturale che ha fatto dell\u2019Urbe lo spettacolo umano e politico della nostra antichit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del Settembre tiburtino, la citt\u00e0 di Tivoli si prepara ad ospitare &#8220;Se volessimo ancora salvare la terra&#8221;, progetto che prende spunto dal discorso della scrittrice Marguerite Yourcenar, pronunciato [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":9233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Settembre tiburtino: mostra sull&#039;ambiente &quot;Se volessimo ancora salvare la Terra&quot; dal 6 al 15 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Settembre tiburtino: mostra sull&#039;ambiente &quot;Se volessimo ancora salvare la Terra&quot; dal 6 al 15 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"In occasione del Settembre tiburtino, la citt\u00e0 di Tivoli si prepara ad ospitare &#8220;Se volessimo ancora salvare la terra&#8221;, progetto che prende spunto dal discorso della scrittrice Marguerite Yourcenar, pronunciato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-05T08:59:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/Invito-SCELTO-ONE-PAGE-4-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Settembre tiburtino: mostra sull&#8217;ambiente &#8220;Se volessimo ancora salvare la Terra&#8221; dal 6 al 15\",\"datePublished\":\"2022-09-05T08:59:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/\"},\"wordCount\":485,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/Invito-SCELTO-ONE-PAGE-4-1.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/\",\"name\":\"Settembre tiburtino: mostra sull'ambiente \\\"Se volessimo ancora salvare la Terra\\\" dal 6 al 15 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/Invito-SCELTO-ONE-PAGE-4-1.jpg\",\"datePublished\":\"2022-09-05T08:59:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/Invito-SCELTO-ONE-PAGE-4-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/Invito-SCELTO-ONE-PAGE-4-1.jpg\",\"width\":2500,\"height\":1754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/05\\\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Settembre tiburtino: mostra sull&#8217;ambiente &#8220;Se volessimo ancora salvare la Terra&#8221; dal 6 al 15\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Settembre tiburtino: mostra sull'ambiente \"Se volessimo ancora salvare la Terra\" dal 6 al 15 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/","og_locale":"it_IT","og_type":"article","og_title":"Settembre tiburtino: mostra sull'ambiente \"Se volessimo ancora salvare la Terra\" dal 6 al 15 - Tivoli","og_description":"In occasione del Settembre tiburtino, la citt\u00e0 di Tivoli si prepara ad ospitare &#8220;Se volessimo ancora salvare la terra&#8221;, progetto che prende spunto dal discorso della scrittrice Marguerite Yourcenar, pronunciato [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-09-05T08:59:32+00:00","og_image":[{"width":2500,"height":1754,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/Invito-SCELTO-ONE-PAGE-4-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Settembre tiburtino: mostra sull&#8217;ambiente &#8220;Se volessimo ancora salvare la Terra&#8221; dal 6 al 15","datePublished":"2022-09-05T08:59:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/"},"wordCount":485,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/Invito-SCELTO-ONE-PAGE-4-1.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/","name":"Settembre tiburtino: mostra sull'ambiente \"Se volessimo ancora salvare la Terra\" dal 6 al 15 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/Invito-SCELTO-ONE-PAGE-4-1.jpg","datePublished":"2022-09-05T08:59:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/Invito-SCELTO-ONE-PAGE-4-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/Invito-SCELTO-ONE-PAGE-4-1.jpg","width":2500,"height":1754},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/05\/settembre-tiburtino-mostra-sullambiente-se-volessimo-ancora-salvare-la-terra-dal-6-al-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Settembre tiburtino: mostra sull&#8217;ambiente &#8220;Se volessimo ancora salvare la Terra&#8221; dal 6 al 15"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9231"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9231\/revisions"}],"predecessor-version":[{"id":9234,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9231\/revisions\/9234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/9233"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}