{"id":9271,"date":"2022-09-09T10:59:35","date_gmt":"2022-09-09T08:59:35","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9271"},"modified":"2022-09-09T10:59:35","modified_gmt":"2022-09-09T08:59:35","slug":"presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/","title":{"rendered":"Presentazione de &#8220;L&#8217;oro d&#8217;Italia&#8221; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana"},"content":{"rendered":"<p>Sabato 10 settembre, presso Parco Villa Gregoriana, si terr\u00e0 la presentazione del\u00a0<strong>libro &#8220;L&#8217;oro d&#8217;Italia&#8221;<\/strong>\u00a0con la presenza dell&#8217;autore,\u00a0<strong>il direttore di Rai Libri, Marco Frittella<\/strong>. Il volume tratta il tema dei beni culturali e della loro gestione, citando anche lo stesso bene FAI tiburtino. All&#8217;evento, moderato dalla giornalista Anna Laura Consalvi, interverranno anche il Sindaco di Tivoli Giuseppe Proietti e la Responsabile del Parco Villa Gregoriana Giorgia Montesano.<\/p>\n<p>L&#8217;ingresso sar\u00e0 libero fino ad esaurimento posti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 10 settembre, presso Parco Villa Gregoriana, si terr\u00e0 la presentazione del\u00a0libro &#8220;L&#8217;oro d&#8217;Italia&#8221;\u00a0con la presenza dell&#8217;autore,\u00a0il direttore di Rai Libri, Marco Frittella. Il volume tratta il tema dei beni [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":9272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentazione de &quot;L&#039;oro d&#039;Italia&quot; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentazione de &quot;L&#039;oro d&#039;Italia&quot; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sabato 10 settembre, presso Parco Villa Gregoriana, si terr\u00e0 la presentazione del\u00a0libro &#8220;L&#8217;oro d&#8217;Italia&#8221;\u00a0con la presenza dell&#8217;autore,\u00a0il direttore di Rai Libri, Marco Frittella. Il volume tratta il tema dei beni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-09T08:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/loro-ditalia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"789\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Presentazione de &#8220;L&#8217;oro d&#8217;Italia&#8221; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana\",\"datePublished\":\"2022-09-09T08:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/\"},\"wordCount\":90,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/loro-ditalia.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/\",\"name\":\"Presentazione de \\\"L'oro d'Italia\\\" di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/loro-ditalia.png\",\"datePublished\":\"2022-09-09T08:59:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/loro-ditalia.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/09\\\/loro-ditalia.png\",\"width\":1511,\"height\":789},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/09\\\/09\\\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentazione de &#8220;L&#8217;oro d&#8217;Italia&#8221; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentazione de \"L'oro d'Italia\" di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/","og_locale":"it_IT","og_type":"article","og_title":"Presentazione de \"L'oro d'Italia\" di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana - Tivoli","og_description":"Sabato 10 settembre, presso Parco Villa Gregoriana, si terr\u00e0 la presentazione del\u00a0libro &#8220;L&#8217;oro d&#8217;Italia&#8221;\u00a0con la presenza dell&#8217;autore,\u00a0il direttore di Rai Libri, Marco Frittella. Il volume tratta il tema dei beni [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-09-09T08:59:35+00:00","og_image":[{"width":1511,"height":789,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/loro-ditalia.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Presentazione de &#8220;L&#8217;oro d&#8217;Italia&#8221; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana","datePublished":"2022-09-09T08:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/"},"wordCount":90,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/loro-ditalia.png","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/","name":"Presentazione de \"L'oro d'Italia\" di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/loro-ditalia.png","datePublished":"2022-09-09T08:59:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/loro-ditalia.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/09\/loro-ditalia.png","width":1511,"height":789},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/09\/09\/presentazione-de-loro-ditalia-di-marco-frittella-direttore-rai-libri-sabato-10-settembre-a-villa-gregoriana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Presentazione de &#8220;L&#8217;oro d&#8217;Italia&#8221; di Marco Frittella, direttore Rai Libri: sabato 10 settembre a Villa Gregoriana"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9271"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9271\/revisions"}],"predecessor-version":[{"id":9273,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9271\/revisions\/9273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/9272"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}