{"id":9500,"date":"2022-10-07T14:00:01","date_gmt":"2022-10-07T12:00:01","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9500"},"modified":"2022-10-07T14:00:01","modified_gmt":"2022-10-07T12:00:01","slug":"in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/","title":{"rendered":"&#8220;In nome di ogni donna&#8221;: al Giuseppetti l&#8217;evento contro la violenza di genere"},"content":{"rendered":"<p>Sabato 8 ottobre 2022, alle ore 17, presso il Cinema Teatro Giuseppetti di Tivoli si terr\u00e0 l&#8217;evento\u00a0<strong>&#8220;In nome di ogni donna&#8221;<\/strong>, sul tema della prevenzione alla violenza di genere. A presentare Daniela Di Camillo, presidente e coordinatrice de &#8220;Il laboratorio del Possibile&#8221;.<\/p>\n<p>Lo spettacolo \u00e8 un veicolo per informare attraverso l&#8217;arte e per arrivare anche a chi \u00e8 solito pensare\u00a0&#8220;tanto a me non succede&#8221;. Si parler\u00e0 dei segnali precedenti lo scatenarsi della violenza, dello stato di angoscia e paura della donna quando viene maltrattata, di cosa poter fare e a chi rivolgersi per avere tutela e protezione nel percorso difficilissimo della denuncia.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_9501\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/10\/WhatsApp-Image-2022-09-24-at-11.06.56.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/10\/WhatsApp-Image-2022-09-24-at-11.06.56.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>LOCANDINA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 8 ottobre 2022, alle ore 17, presso il Cinema Teatro Giuseppetti di Tivoli si terr\u00e0 l&#8217;evento\u00a0&#8220;In nome di ogni donna&#8221;, sul tema della prevenzione alla violenza di genere. A [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9500","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;In nome di ogni donna&quot;: al Giuseppetti l&#039;evento contro la violenza di genere - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;In nome di ogni donna&quot;: al Giuseppetti l&#039;evento contro la violenza di genere - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sabato 8 ottobre 2022, alle ore 17, presso il Cinema Teatro Giuseppetti di Tivoli si terr\u00e0 l&#8217;evento\u00a0&#8220;In nome di ogni donna&#8221;, sul tema della prevenzione alla violenza di genere. A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T12:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;In nome di ogni donna&#8221;: al Giuseppetti l&#8217;evento contro la violenza di genere\",\"datePublished\":\"2022-10-07T12:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/\"},\"wordCount\":112,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/\",\"name\":\"\\\"In nome di ogni donna\\\": al Giuseppetti l'evento contro la violenza di genere - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2022-10-07T12:00:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/10\\\/07\\\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;In nome di ogni donna&#8221;: al Giuseppetti l&#8217;evento contro la violenza di genere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"In nome di ogni donna\": al Giuseppetti l'evento contro la violenza di genere - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/","og_locale":"it_IT","og_type":"article","og_title":"\"In nome di ogni donna\": al Giuseppetti l'evento contro la violenza di genere - Tivoli","og_description":"Sabato 8 ottobre 2022, alle ore 17, presso il Cinema Teatro Giuseppetti di Tivoli si terr\u00e0 l&#8217;evento\u00a0&#8220;In nome di ogni donna&#8221;, sul tema della prevenzione alla violenza di genere. A [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-10-07T12:00:01+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;In nome di ogni donna&#8221;: al Giuseppetti l&#8217;evento contro la violenza di genere","datePublished":"2022-10-07T12:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/"},"wordCount":112,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/","name":"\"In nome di ogni donna\": al Giuseppetti l'evento contro la violenza di genere - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2022-10-07T12:00:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/10\/07\/in-nome-di-ogni-donna-al-giuseppetti-levento-contro-la-violenza-di-genere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;In nome di ogni donna&#8221;: al Giuseppetti l&#8217;evento contro la violenza di genere"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9500"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9500\/revisions"}],"predecessor-version":[{"id":9502,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9500\/revisions\/9502"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}