{"id":9619,"date":"2022-11-07T12:32:30","date_gmt":"2022-11-07T11:32:30","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9619"},"modified":"2022-11-07T12:32:30","modified_gmt":"2022-11-07T11:32:30","slug":"temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/","title":{"rendered":"Temporanea modifica dell&#8217;attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022"},"content":{"rendered":"<p>A causa dell&#8217;esecuzione di lavori di bonifica della rete idrica, si informa la cittadinanza della temporanea modifica dell\u2019attuale regolamentazione stradale nella seguente zona:<\/p>\n<p>&#8211; VIA DI VILLA ADRIANA intero tratto a partire dall\u2019intersezione con via Rosolina fino all\u2019intersezione con Strada San Salvatore:<br \/>\nDIVIETO DI TRANSITO \u00a0 per tutti i veicoli dalle ore 21:30 \u00a0alle ore 06:30 di ogni giorno dal 07 novembre 2022 al 23 dicembre 2022, eccetto mezzi a servizio della ditta esecutrice dei lavori.<br \/>\nDIVIETO DISOSTA CON RIMOZIONE COATTA DEI VEICOLI INADEMPIENTI per tutti i veicoli dalle ore 21:30 \u00a0alle ore 06:30 dal 07 novembre 2022 al 23 dicembre 2022 con inizio il luned\u00ec sera e fine il sabato mattina, eccetto mezzi a servizio della ditta esecutrice dei lavori<br \/>\n&#8211;\u00a0 VIA DI VILLA ADRIANA \u2013 intersezione con via Rosolina -:<br \/>\nOBBLIGO DI SVOLTA A SINISTRA IN DIREZIONE DI VIA ROSOLINA dalle ore 21:30 alle ore 06:30 di ogni giorno dal 07 novembre 2022 al 23 dicembre 2022, eccetto mezzi a servizio della ditta esecutrice dei lavori.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_9620\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/11\/ord.-391.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/11\/ord.-391.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ord. 391<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A causa dell&#8217;esecuzione di lavori di bonifica della rete idrica, si informa la cittadinanza della temporanea modifica dell\u2019attuale regolamentazione stradale nella seguente zona: &#8211; VIA DI VILLA ADRIANA intero tratto [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-9619","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temporanea modifica dell&#039;attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temporanea modifica dell&#039;attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"A causa dell&#8217;esecuzione di lavori di bonifica della rete idrica, si informa la cittadinanza della temporanea modifica dell\u2019attuale regolamentazione stradale nella seguente zona: &#8211; VIA DI VILLA ADRIANA intero tratto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-07T11:32:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Temporanea modifica dell&#8217;attuale regolamentazione stradale presso via di Villa Adriana dal 07\\\/11\\\/2022 al 23\\\/12\\\/2022\",\"datePublished\":\"2022-11-07T11:32:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/\"},\"wordCount\":163,\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/\",\"name\":\"Temporanea modifica dell'attuale regolamentazione stradale presso via di Villa Adriana dal 07\\\/11\\\/2022 al 23\\\/12\\\/2022 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2022-11-07T11:32:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/07\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporanea modifica dell&#8217;attuale regolamentazione stradale presso via di Villa Adriana dal 07\\\/11\\\/2022 al 23\\\/12\\\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temporanea modifica dell'attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Temporanea modifica dell'attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022 - Tivoli","og_description":"A causa dell&#8217;esecuzione di lavori di bonifica della rete idrica, si informa la cittadinanza della temporanea modifica dell\u2019attuale regolamentazione stradale nella seguente zona: &#8211; VIA DI VILLA ADRIANA intero tratto [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-07T11:32:30+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Temporanea modifica dell&#8217;attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022","datePublished":"2022-11-07T11:32:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/"},"wordCount":163,"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/","name":"Temporanea modifica dell'attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2022-11-07T11:32:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/07\/temporanea-modifica-dellattuale-regolamentazione-stradale-presso-via-di-villa-adriana-dal-07-11-2022-al-23-12-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Temporanea modifica dell&#8217;attuale regolamentazione stradale presso via di Villa Adriana dal 07\/11\/2022 al 23\/12\/2022"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9619"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9619\/revisions"}],"predecessor-version":[{"id":9621,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9619\/revisions\/9621"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}