{"id":9706,"date":"2022-11-23T12:43:58","date_gmt":"2022-11-23T11:43:58","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9706"},"modified":"2022-11-25T09:45:57","modified_gmt":"2022-11-25T08:45:57","slug":"moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/","title":{"rendered":"\u201cModa Autunno 2022-Per Un Capello&#8221;: dal 25 al 28 novembre alle Scuderie Estensi l&#8217;evento dedicato al &#8220;trucco e parrucco&#8221; pi\u00f9 &#8220;in&#8221; della stagione"},"content":{"rendered":"<p>Dal 25 al 28 novembre, presso le Scuderie Estensi di Tivoli, si terr\u00e0 l&#8217;evento\u00a0<strong>\u201cModa Autunno 2022-Per Un Capello&#8221;<\/strong>, che avr\u00e0 come elemento primario la riscoperta e la collaborazione tra piccoli commercianti e artigiani del territorio tiburtino.<\/p>\n<p>La manifestazione, patrocinata dal Comune di Tivoli, \u00e8 a cura di Cristina Cappuccini, che da anni si occupa di organizzare sfilate di moda e spettacoli musicali, sempre con lo scopo di valorizzare l\u2019artigianato locale ed i piccoli negozi con l\u2019esposizione dei loro prodotti e la messa a disposizione della loro professionalit\u00e0. Ad affiancarla, Lucrezia Diotallevi.<\/p>\n<p>Stand con analisi tricologica, baby coiffeur, dimostrazioni live, e ancora consigli sul &#8220;trucco e parrucco&#8221; pi\u00f9 alla moda della stagione: il programma \u00e8 ricco di appuntamenti. La sfilata si terr\u00e0 il 27 novembre alle ore 17. Alle Scuderie Estensi sar\u00e0 inoltre allestita una esposizione fotografica di Tonino Novelli e Alberto Proli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 25 al 28 novembre, presso le Scuderie Estensi di Tivoli, si terr\u00e0 l&#8217;evento\u00a0\u201cModa Autunno 2022-Per Un Capello&#8221;, che avr\u00e0 come elemento primario la riscoperta e la collaborazione tra piccoli [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9706","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cModa Autunno 2022-Per Un Capello&quot;: dal 25 al 28 novembre alle Scuderie Estensi l&#039;evento dedicato al &quot;trucco e parrucco&quot; pi\u00f9 &quot;in&quot; della stagione - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cModa Autunno 2022-Per Un Capello&quot;: dal 25 al 28 novembre alle Scuderie Estensi l&#039;evento dedicato al &quot;trucco e parrucco&quot; pi\u00f9 &quot;in&quot; della stagione - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dal 25 al 28 novembre, presso le Scuderie Estensi di Tivoli, si terr\u00e0 l&#8217;evento\u00a0\u201cModa Autunno 2022-Per Un Capello&#8221;, che avr\u00e0 come elemento primario la riscoperta e la collaborazione tra piccoli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T11:43:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T08:45:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"\u201cModa Autunno 2022-Per Un Capello&#8221;: dal 25 al 28 novembre alle Scuderie Estensi l&#8217;evento dedicato al &#8220;trucco e parrucco&#8221; pi\u00f9 &#8220;in&#8221; della stagione\",\"datePublished\":\"2022-11-23T11:43:58+00:00\",\"dateModified\":\"2022-11-25T08:45:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/\"},\"wordCount\":160,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/\",\"name\":\"\u201cModa Autunno 2022-Per Un Capello\\\": dal 25 al 28 novembre alle Scuderie Estensi l'evento dedicato al \\\"trucco e parrucco\\\" pi\u00f9 \\\"in\\\" della stagione - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2022-11-23T11:43:58+00:00\",\"dateModified\":\"2022-11-25T08:45:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/23\\\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cModa Autunno 2022-Per Un Capello&#8221;: dal 25 al 28 novembre alle Scuderie Estensi l&#8217;evento dedicato al &#8220;trucco e parrucco&#8221; pi\u00f9 &#8220;in&#8221; della stagione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cModa Autunno 2022-Per Un Capello\": dal 25 al 28 novembre alle Scuderie Estensi l'evento dedicato al \"trucco e parrucco\" pi\u00f9 \"in\" della stagione - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cModa Autunno 2022-Per Un Capello\": dal 25 al 28 novembre alle Scuderie Estensi l'evento dedicato al \"trucco e parrucco\" pi\u00f9 \"in\" della stagione - Tivoli","og_description":"Dal 25 al 28 novembre, presso le Scuderie Estensi di Tivoli, si terr\u00e0 l&#8217;evento\u00a0\u201cModa Autunno 2022-Per Un Capello&#8221;, che avr\u00e0 come elemento primario la riscoperta e la collaborazione tra piccoli [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-23T11:43:58+00:00","article_modified_time":"2022-11-25T08:45:57+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"\u201cModa Autunno 2022-Per Un Capello&#8221;: dal 25 al 28 novembre alle Scuderie Estensi l&#8217;evento dedicato al &#8220;trucco e parrucco&#8221; pi\u00f9 &#8220;in&#8221; della stagione","datePublished":"2022-11-23T11:43:58+00:00","dateModified":"2022-11-25T08:45:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/"},"wordCount":160,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/","name":"\u201cModa Autunno 2022-Per Un Capello\": dal 25 al 28 novembre alle Scuderie Estensi l'evento dedicato al \"trucco e parrucco\" pi\u00f9 \"in\" della stagione - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2022-11-23T11:43:58+00:00","dateModified":"2022-11-25T08:45:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/23\/moda-autunno-2022-per-un-capello-dal-25-al-28-novembre-alle-scuderie-estensi-levento-dedicato-al-trucco-e-parrucco-piu-in-della-stagione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"\u201cModa Autunno 2022-Per Un Capello&#8221;: dal 25 al 28 novembre alle Scuderie Estensi l&#8217;evento dedicato al &#8220;trucco e parrucco&#8221; pi\u00f9 &#8220;in&#8221; della stagione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9706"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9706\/revisions"}],"predecessor-version":[{"id":9713,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9706\/revisions\/9713"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}