{"id":9714,"date":"2022-11-25T13:23:46","date_gmt":"2022-11-25T12:23:46","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9714"},"modified":"2022-11-25T13:23:46","modified_gmt":"2022-11-25T12:23:46","slug":"natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/","title":{"rendered":"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi"},"content":{"rendered":"<p>L\u2019Amministrazione Comunale intende promuovere una serie di eventi, da realizzarsi nel periodo compreso tra l\u20198 dicembre 2022 e il 30 gennaio 2023, con lo scopo di animare l&#8217;intero territorio con diverse iniziative atte a creare il tipico clima natalizio.<\/p>\n<p>Tale indirizzo viene riaffermato nel Documento Unico di Programmazione (DUP) 2022 \u2013 2024, che sia all\u2019obiettivo strategico 1. dell\u2019Area Turismo: \u201cValorizzazione degli Attrattori Turistico Culturali\u201d sia all\u2019obiettivo strategico 1. dell\u2019Area Cultura: \u201cRealizzazione Iniziative Attivit\u00e0 ed Eventi Culturali\u201d<em>\u00a0<\/em>include tra i grandi contenitori di eventi il Natale a Tivoli, quale programma coordinato di attivit\u00e0 natalizie avente connessione strategica con gli obiettivi della promozione turistica e dello sviluppo socio &#8211; culturale del territorio.<\/p>\n<p>Con Delibera di Giunta comunale n. 235 del 11-11-2022 sono stati formulati gli indirizzi finalizzati a reperire<strong>\u00a0<\/strong>proposte organiche per la realizzazione di iniziative, che coinvolgano adeguatamente l\u2019intero territorio comunale, di intrattenimento ed installazione di attrattive, possibilmente uniformi e caratteristiche.<\/p>\n<p>A pena di esclusione la domanda di partecipazione va indirizzata e deve pervenire al Comune di Tivoli in Piazza del Governo n. 1 \u2013 00019 Tivoli (Roma)\u00a0<strong>a mezzo pec all\u2019indirizzo\u00a0<\/strong><a href=\"mailto:servizi.allacitta@pec.comune.tivoli.rm.it\">servizi.allacitta@pec.comune.tivoli.rm.it<\/a><strong>\u00a0entro e non oltre le ore 17.00 del 29-11-2022\u00a0<\/strong>. Detta domanda potr\u00e0 essere anche\u00a0<strong>consegnata a mano all\u2019Ufficio Relazioni con il Pubblico del Comune di Tivoli entro il termine sopra indicato, in ogni caso, saranno recepite le proposte gi\u00e0 pervenute e nelle date richieste.<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_9715\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/11\/AVVISO-NATALE-A-TIVOLI-corretto.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/11\/AVVISO-NATALE-A-TIVOLI-corretto.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione Comunale intende promuovere una serie di eventi, da realizzarsi nel periodo compreso tra l\u20198 dicembre 2022 e il 30 gennaio 2023, con lo scopo di animare l&#8217;intero territorio con [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9714","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi - Tivoli\" \/>\n<meta property=\"og:description\" content=\"L\u2019Amministrazione Comunale intende promuovere una serie di eventi, da realizzarsi nel periodo compreso tra l\u20198 dicembre 2022 e il 30 gennaio 2023, con lo scopo di animare l&#8217;intero territorio con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-25T12:23:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi\",\"datePublished\":\"2022-11-25T12:23:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/\"},\"wordCount\":240,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/\",\"name\":\"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2022-11-25T12:23:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/11\\\/25\\\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/","og_locale":"it_IT","og_type":"article","og_title":"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi - Tivoli","og_description":"L\u2019Amministrazione Comunale intende promuovere una serie di eventi, da realizzarsi nel periodo compreso tra l\u20198 dicembre 2022 e il 30 gennaio 2023, con lo scopo di animare l&#8217;intero territorio con [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-11-25T12:23:46+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi","datePublished":"2022-11-25T12:23:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/"},"wordCount":240,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/","name":"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2022-11-25T12:23:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/11\/25\/natale-2022-a-tivoli-manifestazione-di-interesse-per-la-realizzazione-degli-eventi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Natale 2022 a Tivoli, manifestazione di interesse per la realizzazione degli eventi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9714"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9714\/revisions"}],"predecessor-version":[{"id":9716,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9714\/revisions\/9716"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}