{"id":9787,"date":"2022-12-15T11:19:17","date_gmt":"2022-12-15T10:19:17","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9787"},"modified":"2022-12-15T11:19:17","modified_gmt":"2022-12-15T10:19:17","slug":"magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/","title":{"rendered":"&#8220;Magico Natale a Tivoli&#8221;: inaugurazione villaggio natalizio sabato 17 dicembre"},"content":{"rendered":"<p>Sabato 17 dicembre, dalle ore 16.30 alle ore 18.30, in piazza Garibaldi si terr\u00e0 l&#8217;inaugurazione del\u00a0<strong>&#8220;Magico Natale a Tivoli&#8221;<\/strong>, con l&#8217;apertura dei\u00a0tradizionali\u00a0mercatini e con l&#8217;accensione dell&#8217;albero di Natale.\u00a0Il villaggio natalizio, messo a disposizione\u00a0dal Comune di Tivoli e curato dall&#8217;Unione Commercio e Turismo, ospiter\u00e0 la Casa di Babbo Natale con la slitta, le giostre per i pi\u00f9 piccoli e un&#8217;area street food.<\/p>\n<p>Un coro gospel e\u00a0un mini coro di bambini intoneranno i tipici canti natalizi. Ad allietare l&#8217;evento di inaugurazione \u00e8 previsto anche uno spettacolo col fuoco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 17 dicembre, dalle ore 16.30 alle ore 18.30, in piazza Garibaldi si terr\u00e0 l&#8217;inaugurazione del\u00a0&#8220;Magico Natale a Tivoli&#8221;, con l&#8217;apertura dei\u00a0tradizionali\u00a0mercatini e con l&#8217;accensione dell&#8217;albero di Natale.\u00a0Il villaggio natalizio, [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":9788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-9787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Magico Natale a Tivoli&quot;: inaugurazione villaggio natalizio sabato 17 dicembre - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Magico Natale a Tivoli&quot;: inaugurazione villaggio natalizio sabato 17 dicembre - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sabato 17 dicembre, dalle ore 16.30 alle ore 18.30, in piazza Garibaldi si terr\u00e0 l&#8217;inaugurazione del\u00a0&#8220;Magico Natale a Tivoli&#8221;, con l&#8217;apertura dei\u00a0tradizionali\u00a0mercatini e con l&#8217;accensione dell&#8217;albero di Natale.\u00a0Il villaggio natalizio, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T10:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/PHOTO-2022-12-15-08-23-36.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;Magico Natale a Tivoli&#8221;: inaugurazione villaggio natalizio sabato 17 dicembre\",\"datePublished\":\"2022-12-15T10:19:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/\"},\"wordCount\":97,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/PHOTO-2022-12-15-08-23-36.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/\",\"name\":\"\\\"Magico Natale a Tivoli\\\": inaugurazione villaggio natalizio sabato 17 dicembre - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/PHOTO-2022-12-15-08-23-36.jpg\",\"datePublished\":\"2022-12-15T10:19:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/PHOTO-2022-12-15-08-23-36.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/PHOTO-2022-12-15-08-23-36.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/15\\\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Magico Natale a Tivoli&#8221;: inaugurazione villaggio natalizio sabato 17 dicembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Magico Natale a Tivoli\": inaugurazione villaggio natalizio sabato 17 dicembre - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/","og_locale":"it_IT","og_type":"article","og_title":"\"Magico Natale a Tivoli\": inaugurazione villaggio natalizio sabato 17 dicembre - Tivoli","og_description":"Sabato 17 dicembre, dalle ore 16.30 alle ore 18.30, in piazza Garibaldi si terr\u00e0 l&#8217;inaugurazione del\u00a0&#8220;Magico Natale a Tivoli&#8221;, con l&#8217;apertura dei\u00a0tradizionali\u00a0mercatini e con l&#8217;accensione dell&#8217;albero di Natale.\u00a0Il villaggio natalizio, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-12-15T10:19:17+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/PHOTO-2022-12-15-08-23-36.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;Magico Natale a Tivoli&#8221;: inaugurazione villaggio natalizio sabato 17 dicembre","datePublished":"2022-12-15T10:19:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/"},"wordCount":97,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/PHOTO-2022-12-15-08-23-36.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/","name":"\"Magico Natale a Tivoli\": inaugurazione villaggio natalizio sabato 17 dicembre - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/PHOTO-2022-12-15-08-23-36.jpg","datePublished":"2022-12-15T10:19:17+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/PHOTO-2022-12-15-08-23-36.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/PHOTO-2022-12-15-08-23-36.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/15\/magico-natale-a-tivoli-inaugurazione-villaggio-natalizio-sabato-17-dicembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;Magico Natale a Tivoli&#8221;: inaugurazione villaggio natalizio sabato 17 dicembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9787"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9787\/revisions"}],"predecessor-version":[{"id":9789,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9787\/revisions\/9789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/9788"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}