{"id":9803,"date":"2022-12-16T14:34:42","date_gmt":"2022-12-16T13:34:42","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9803"},"modified":"2022-12-16T14:34:42","modified_gmt":"2022-12-16T13:34:42","slug":"chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/","title":{"rendered":"&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre"},"content":{"rendered":"<p>Sabato 17 dicembre, presso la Sala Conferenze del Museo della Citt\u00e0, alle ore 17.30 si terr\u00e0 la presentazione del libro\u00a0<strong>&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;<\/strong>, dell&#8217;autrice tiburtina Alessandra Balla, responsabile della comunicazione dell\u2019Associazione Nazionale Volontarie Telefono Rosa. A moderare la presentazione il giornalista Giuliano Girlando. Presente all&#8217;evento anche la psicologa del Telefono Rosa Melania Celi.<\/p>\n<p>\u201cChiuse in casa\u201d \u00e8 una raccolta di racconti che riporta storie di violenza domestica avvenute durante il lockdown. Ogni nome di donna, e quindi ogni racconto, rappresenta una forma di violenza: psicologica, fisica, violenza sessuale, stalking, violenza economica e violenza assistita. Le storie si ispirano a casi realmente accaduti, registrati dal Telefono Rosa durante la pandemia. Tutti i nomi sono frutto di fantasia, come spesso i contesti e la creazione dei personaggi. L\u2019idea \u00e8 quella di entrare nelle case altrui e di dare voce alle donne che hanno subito, o subiscono, in silenzio. Non c\u2019\u00e8 alcuna morale nella violenza e purtroppo, a volte, nemmeno un lieto fine. Queste storie nascono dalla volont\u00e0 di riflettere e denunciare quello che accade vicino a noi, nel nostro palazzo o solo qualche portone pi\u00f9 in l\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 17 dicembre, presso la Sala Conferenze del Museo della Citt\u00e0, alle ore 17.30 si terr\u00e0 la presentazione del libro\u00a0&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;, dell&#8217;autrice [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":9804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-9803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Chiuse in Casa. Storie di violenza domestica durante il lockdown&quot;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Chiuse in Casa. Storie di violenza domestica durante il lockdown&quot;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sabato 17 dicembre, presso la Sala Conferenze del Museo della Citt\u00e0, alle ore 17.30 si terr\u00e0 la presentazione del libro\u00a0&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;, dell&#8217;autrice [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T13:34:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/IMG-20221207-WA0016-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre\",\"datePublished\":\"2022-12-16T13:34:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/\"},\"wordCount\":209,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/IMG-20221207-WA0016-1.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/\",\"name\":\"\\\"Chiuse in Casa. Storie di violenza domestica durante il lockdown\\\". Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/IMG-20221207-WA0016-1.jpg\",\"datePublished\":\"2022-12-16T13:34:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/IMG-20221207-WA0016-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2022\\\/12\\\/IMG-20221207-WA0016-1.jpg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2022\\\/12\\\/16\\\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Chiuse in Casa. Storie di violenza domestica durante il lockdown\". Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/","og_locale":"it_IT","og_type":"article","og_title":"\"Chiuse in Casa. Storie di violenza domestica durante il lockdown\". Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre - Tivoli","og_description":"Sabato 17 dicembre, presso la Sala Conferenze del Museo della Citt\u00e0, alle ore 17.30 si terr\u00e0 la presentazione del libro\u00a0&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;, dell&#8217;autrice [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-12-16T13:34:42+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/IMG-20221207-WA0016-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre","datePublished":"2022-12-16T13:34:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/"},"wordCount":209,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/IMG-20221207-WA0016-1.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/","url":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/","name":"\"Chiuse in Casa. Storie di violenza domestica durante il lockdown\". Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/IMG-20221207-WA0016-1.jpg","datePublished":"2022-12-16T13:34:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/IMG-20221207-WA0016-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2022\/12\/IMG-20221207-WA0016-1.jpg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2022\/12\/16\/chiuse-in-casa-storie-di-violenza-domestica-durante-il-lockdown-presentazione-del-libro-al-museo-della-citta-sabato-17-dicembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"&#8220;Chiuse in Casa. Storie di violenza domestica durante il lockdown&#8221;. Presentazione del libro al Museo della Citt\u00e0 sabato 17 dicembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9803"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9803\/revisions"}],"predecessor-version":[{"id":9805,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9803\/revisions\/9805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/9804"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}