{"id":9903,"date":"2023-01-13T14:47:45","date_gmt":"2023-01-13T13:47:45","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=9903"},"modified":"2023-01-13T14:47:45","modified_gmt":"2023-01-13T13:47:45","slug":"annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/","title":{"rendered":"Annullato evento &#8220;De Core. La canzone romana racconta&#8221; previsto per il 14 gennaio alle Scuderie Estensi"},"content":{"rendered":"<p>Si comunica che l&#8217;e<span data-offset-key=\"b82jg-0-0\">vento musicale \u201cDe Core. La canzone romana racconta&#8221;, a cura dell&#8217;Associazione Le Officine della Musica, precedentemente indicato nella prima stesura del calendario di programmazione e previsto per domani, sabato 14 gennaio, alle ore 15 presso le Scuderie Estensi, non avr\u00e0 luogo.<\/span><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che l&#8217;evento musicale \u201cDe Core. La canzone romana racconta&#8221;, a cura dell&#8217;Associazione Le Officine della Musica, precedentemente indicato nella prima stesura del calendario di programmazione e previsto per [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-9903","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Annullato evento &quot;De Core. La canzone romana racconta&quot; previsto per il 14 gennaio alle Scuderie Estensi - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annullato evento &quot;De Core. La canzone romana racconta&quot; previsto per il 14 gennaio alle Scuderie Estensi - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si comunica che l&#8217;evento musicale \u201cDe Core. La canzone romana racconta&#8221;, a cura dell&#8217;Associazione Le Officine della Musica, precedentemente indicato nella prima stesura del calendario di programmazione e previsto per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-13T13:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Annullato evento &#8220;De Core. La canzone romana racconta&#8221; previsto per il 14 gennaio alle Scuderie Estensi\",\"datePublished\":\"2023-01-13T13:47:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/\"},\"wordCount\":57,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/\",\"name\":\"Annullato evento \\\"De Core. La canzone romana racconta\\\" previsto per il 14 gennaio alle Scuderie Estensi - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2023-01-13T13:47:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2023\\\/01\\\/13\\\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annullato evento &#8220;De Core. La canzone romana racconta&#8221; previsto per il 14 gennaio alle Scuderie Estensi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annullato evento \"De Core. La canzone romana racconta\" previsto per il 14 gennaio alle Scuderie Estensi - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/","og_locale":"it_IT","og_type":"article","og_title":"Annullato evento \"De Core. La canzone romana racconta\" previsto per il 14 gennaio alle Scuderie Estensi - Tivoli","og_description":"Si comunica che l&#8217;evento musicale \u201cDe Core. La canzone romana racconta&#8221;, a cura dell&#8217;Associazione Le Officine della Musica, precedentemente indicato nella prima stesura del calendario di programmazione e previsto per [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-01-13T13:47:45+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Annullato evento &#8220;De Core. La canzone romana racconta&#8221; previsto per il 14 gennaio alle Scuderie Estensi","datePublished":"2023-01-13T13:47:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/"},"wordCount":57,"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/","url":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/","name":"Annullato evento \"De Core. La canzone romana racconta\" previsto per il 14 gennaio alle Scuderie Estensi - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2023-01-13T13:47:45+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2023\/01\/13\/annullato-evento-de-core-la-canzone-romana-racconta-previsto-per-il-14-gennaio-alle-scuderie-estensi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Annullato evento &#8220;De Core. La canzone romana racconta&#8221; previsto per il 14 gennaio alle Scuderie Estensi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=9903"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9903\/revisions"}],"predecessor-version":[{"id":9904,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/9903\/revisions\/9904"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=9903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=9903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=9903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}