{"id":7559,"date":"2021-07-20T11:02:02","date_gmt":"2021-07-20T09:02:02","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?post_type=rdif&#038;p=7559"},"modified":"2021-07-20T11:02:02","modified_gmt":"2021-07-20T09:02:02","slug":"abiti","status":"publish","type":"rdif","link":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/","title":{"rendered":"Abiti"},"content":{"rendered":"<p>Gli abiti dismessi che possono comunque essere ancora riutilizzati vanno conferiti all\u2019interno dei contenitori di abiti usati ubicati sul territorio tiburtino, prima inseriti nel contenitore all\u2019interno di buste ben chiuse. Al seguente <a href=\"https:\/\/www.asativolispa.it\/contenitori-abiti-usati\/\">link<\/a> la mappa dei contenitori di abiti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli abiti dismessi che possono comunque essere ancora riutilizzati vanno conferiti all\u2019interno dei contenitori di abiti usati ubicati sul territorio tiburtino, prima inseriti nel contenitore all\u2019interno di buste ben chiuse. [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":17,"menu_order":6,"template":"","meta":[],"class_list":["post-7559","rdif","type-rdif","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abiti - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abiti - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Gli abiti dismessi che possono comunque essere ancora riutilizzati vanno conferiti all\u2019interno dei contenitori di abiti usati ubicati sul territorio tiburtino, prima inseriti nel contenitore all\u2019interno di buste ben chiuse. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/09\/tivoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/rdif\\\/guida-alla-raccolta\\\/abiti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/rdif\\\/guida-alla-raccolta\\\/abiti\\\/\",\"name\":\"Abiti - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2021-07-20T09:02:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/rdif\\\/guida-alla-raccolta\\\/abiti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/rdif\\\/guida-alla-raccolta\\\/abiti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/rdif\\\/guida-alla-raccolta\\\/abiti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guida alla raccolta\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/rdif\\\/guida-alla-raccolta\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abiti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abiti - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/","og_locale":"it_IT","og_type":"article","og_title":"Abiti - Tivoli","og_description":"Gli abiti dismessi che possono comunque essere ancora riutilizzati vanno conferiti all\u2019interno dei contenitori di abiti usati ubicati sul territorio tiburtino, prima inseriti nel contenitore all\u2019interno di buste ben chiuse. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/09\/tivoli.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/","url":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/","name":"Abiti - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2021-07-20T09:02:02+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/abiti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Guida alla raccolta","item":"https:\/\/comunicacity.net\/tivoli\/rdif\/guida-alla-raccolta\/"},{"@type":"ListItem","position":3,"name":"Abiti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/rdif\/7559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/rdif"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/rdif"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/rdif\/17"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}