{"id":121,"date":"2016-11-24T16:17:10","date_gmt":"2016-11-24T15:17:10","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?post_type=turismo&#038;p=121"},"modified":"2021-06-21T15:58:51","modified_gmt":"2021-06-21T13:58:51","slug":"chiesa-della-maria-ss-di-quintiliolo","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/","title":{"rendered":"Chiesa della Maria SS. di Quintiliolo"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Il Santuario della Madonna di Quintiliolo si trova appena fuori il centro storico di Tivoli, su di una collina immersa nel verde degli ulivi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il nome Quintiliolo deriverebbe dal territorio in possesso della famiglia dei Quintili, qui infatti si trovava la loro villa, al margine della quale venne eretta la chiesa prima ed il convento poi. Questo splendido complesso religioso \u00e8 dedicato alla\u00a0sacra immagine della Vergine Maria, ritrovata, secondo una leggenda tiburtina, da un contadino che lavorava la terra con l\u2019aratro.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Esternamente la chiesa si presenta con uno stile neoclassico diviso in due ordini e dominato da un alto campanile che svetta sul paesaggio circostante e sulla zona delle ex cartiere tiburtine, nei pressi del Santuario di Ercole vincitore. L\u2019interno \u00e8 a navata unica con due cappelle laterali, in quella di sinistra \u00e8 conservato il dipinto della Madonna Regina dei Santi, settecentesca opera di Francesco Serbucci da Tivoli.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Ma \u00e8 sull\u2019altare maggiore che si trova il simbolo del santuario,\u00a0l\u2019Icona della Madonna di Quintiliolo, immagine sacra risalente al XIII secolo ed ancora oggi venerata dai tiburtini, raffigurante la Vergine in trono che sorregge Ges\u00f9 bambino con il ginocchio sinistro. Ogni prima domenica di maggio questa splendida figura cristiana viene portata in processione dal santuario fino alla Cattedrale di San Lorenzo, dove resta fino all\u20198 settembre, giorno in cui fa ritorno al santuario.<\/span><\/p>\n<p style=\"text-align: justify;\">\n<b>Chiesa della Maria SS. di Quintiliolo<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Via Maria SS. di Quintiliolo, 4<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">00019, Tivoli (RM)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Santuario della Madonna di Quintiliolo si trova appena fuori il centro storico di Tivoli, su di una collina immersa nel verde degli ulivi. Il nome Quintiliolo deriverebbe dal territorio [&hellip;]<\/p>\n","protected":false},"featured_media":122,"parent":32,"menu_order":2,"template":"","meta":[],"class_list":["post-121","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa della Maria SS. di Quintiliolo - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa della Maria SS. di Quintiliolo - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Il Santuario della Madonna di Quintiliolo si trova appena fuori il centro storico di Tivoli, su di una collina immersa nel verde degli ulivi. Il nome Quintiliolo deriverebbe dal territorio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-21T13:58:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/santuario-della-madonna-di-quintiliolo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/\",\"name\":\"Chiesa della Maria SS. di Quintiliolo - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/11\\\/santuario-della-madonna-di-quintiliolo.jpg\",\"datePublished\":\"2016-11-24T15:17:10+00:00\",\"dateModified\":\"2021-06-21T13:58:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/11\\\/santuario-della-madonna-di-quintiliolo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/11\\\/santuario-della-madonna-di-quintiliolo.jpg\",\"width\":756,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-della-maria-ss-di-quintiliolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luoghi di culto\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesa della Maria SS. di Quintiliolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa della Maria SS. di Quintiliolo - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa della Maria SS. di Quintiliolo - Tivoli","og_description":"Il Santuario della Madonna di Quintiliolo si trova appena fuori il centro storico di Tivoli, su di una collina immersa nel verde degli ulivi. Il nome Quintiliolo deriverebbe dal territorio [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-06-21T13:58:51+00:00","og_image":[{"width":756,"height":484,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/santuario-della-madonna-di-quintiliolo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/","url":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/","name":"Chiesa della Maria SS. di Quintiliolo - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/santuario-della-madonna-di-quintiliolo.jpg","datePublished":"2016-11-24T15:17:10+00:00","dateModified":"2021-06-21T13:58:51+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/santuario-della-madonna-di-quintiliolo.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/santuario-della-madonna-di-quintiliolo.jpg","width":756,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-della-maria-ss-di-quintiliolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Luoghi di culto","item":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/"},{"@type":"ListItem","position":3,"name":"Chiesa della Maria SS. di Quintiliolo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/turismo\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/turismo\/32"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/122"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}