{"id":123,"date":"2016-11-24T16:18:07","date_gmt":"2016-11-24T15:18:07","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?post_type=turismo&#038;p=123"},"modified":"2021-06-21T15:59:02","modified_gmt":"2021-06-21T13:59:02","slug":"chiesa-di-san-biagio","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/","title":{"rendered":"Chiesa di San Biagio"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La Chiesa di San Biagio di Tivoli fu ultimata da papa Bonifacio IX verso la fine del 1300\u00a0e si trova nella centrale Piazza del Plebiscito, spazio pubblico che decise l\u2019annessione della Citt\u00e0 di Tivoli al regno d\u2019Italia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esternamente questo luogo di culto si presenta con una facciata suddivisa in due ordini, in quella inferiore troviamo un portale centrale rialzato da tre gradini, mentre quella superiore \u00e8 abbellita da un\u00a0rosone centrale situato tra un orologio romano ed una meridiana. L\u2019interno della chiesa si presenta a navata unica caratterizzata da un altare maggiore, dalle cappelle laterali e dalle grandi finestre visibili nel presbiterio. Tra le opere conservate all\u2019interno delle cappelle troviamo la settecentesca tela di\u00a0\u201cSanta Caterina d\u2019Alessandria\u201d, il quadro del\u00a0\u201cSantissimo Nome di Ges\u00f9\u201d, ed il Fonte Battesimale. Notevoli anche gli affreschi raffiguranti la\u00a0\u201cGloria di San Tommaso d\u2019Aquino\u201d\u00a0e la\u00a0\u201cMadonna in Gloria\u201dche sorregge Ges\u00f9 Bambino situati vicino la sagrestia. Nel timpano si pu\u00f2 ammirare il busto marmoreo della\u00a0\u201cMadonna con il Bambino\u201d, nel presbiterio invece il bellissimo affresco della Crocifissione risalente alla seconda met\u00e0 del 1200.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Menzione a parte va fatta per i resti dell\u2019antico chiostro, oggi infatti dell\u2019antica struttura restano visibili soltanto le quattro arcate a tutto sesto poggiate sui pilastri affrescati.<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p><b>Chiesa di San Biagio<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Piazza Plebiscito, 21<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">00019, Tivoli (RM)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chiesa di San Biagio di Tivoli fu ultimata da papa Bonifacio IX verso la fine del 1300\u00a0e si trova nella centrale Piazza del Plebiscito, spazio pubblico che decise l\u2019annessione [&hellip;]<\/p>\n","protected":false},"featured_media":124,"parent":32,"menu_order":3,"template":"","meta":[],"class_list":["post-123","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa di San Biagio - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa di San Biagio - Tivoli\" \/>\n<meta property=\"og:description\" content=\"La Chiesa di San Biagio di Tivoli fu ultimata da papa Bonifacio IX verso la fine del 1300\u00a0e si trova nella centrale Piazza del Plebiscito, spazio pubblico che decise l\u2019annessione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-21T13:59:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/chiesa-di-san-biagio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/\",\"name\":\"Chiesa di San Biagio - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/11\\\/chiesa-di-san-biagio.jpg\",\"datePublished\":\"2016-11-24T15:18:07+00:00\",\"dateModified\":\"2021-06-21T13:59:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/11\\\/chiesa-di-san-biagio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/11\\\/chiesa-di-san-biagio.jpg\",\"width\":756,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/chiesa-di-san-biagio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luoghi di culto\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/turismo\\\/luoghi-di-culto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesa di San Biagio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa di San Biagio - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa di San Biagio - Tivoli","og_description":"La Chiesa di San Biagio di Tivoli fu ultimata da papa Bonifacio IX verso la fine del 1300\u00a0e si trova nella centrale Piazza del Plebiscito, spazio pubblico che decise l\u2019annessione [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2021-06-21T13:59:02+00:00","og_image":[{"width":756,"height":484,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/chiesa-di-san-biagio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/","url":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/","name":"Chiesa di San Biagio - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/chiesa-di-san-biagio.jpg","datePublished":"2016-11-24T15:18:07+00:00","dateModified":"2021-06-21T13:59:02+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/chiesa-di-san-biagio.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/11\/chiesa-di-san-biagio.jpg","width":756,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/chiesa-di-san-biagio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Luoghi di culto","item":"https:\/\/comunicacity.net\/tivoli\/turismo\/luoghi-di-culto\/"},{"@type":"ListItem","position":3,"name":"Chiesa di San Biagio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/turismo\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/turismo\/32"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/124"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}