{"id":17261,"date":"2022-03-29T16:35:12","date_gmt":"2022-03-29T14:35:12","guid":{"rendered":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg"},"modified":"2022-03-29T16:35:12","modified_gmt":"2022-03-29T14:35:12","slug":"riserva-di-pesca-17","status":"inherit","type":"attachment","link":"https:\/\/comunicacity.net\/valpelline\/turismo\/riserva-di-pesca\/riserva-di-pesca-17\/","title":{"rendered":"Riserva di pesca (17)"},"author":282,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-17261","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riserva di pesca (17) - Valpelline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riserva di pesca (17) - Valpelline\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Valpelline\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"493\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Riserva-di-pesca-17.jpg\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Riserva-di-pesca-17.jpg\",\"name\":\"Riserva di pesca (17) - Valpelline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#website\"},\"datePublished\":\"2022-03-29T14:35:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Riserva-di-pesca-17.jpg#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Riserva-di-pesca-17.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Riserva-di-pesca-17.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riserva di pesca\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/riserva-di-pesca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Riserva di pesca (17)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riserva di pesca (17) - Valpelline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg","og_locale":"it_IT","og_type":"article","og_title":"Riserva di pesca (17) - Valpelline","og_url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg","og_site_name":"Valpelline","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"width":493,"height":330,"url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg","url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg","name":"Riserva di pesca (17) - Valpelline","isPartOf":{"@id":"https:\/\/comunicacity.net\/valpelline\/#website"},"datePublished":"2022-03-29T14:35:12+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/valpelline\/"},{"@type":"ListItem","position":2,"name":"Riserva di pesca","item":"https:\/\/comunicacity.net\/valpelline\/turismo\/riserva-di-pesca\/"},{"@type":"ListItem","position":3,"name":"Riserva di pesca (17)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/valpelline\/#website","url":"https:\/\/comunicacity.net\/valpelline\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/valpelline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/valpelline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/valpelline\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/valpelline\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/valpelline\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/valpelline\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17-300x201.jpg 300w, https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg 493w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":493,"height":330,"file":"2022\/03\/Riserva-di-pesca-17.jpg","sizes":{"medium":{"file":"Riserva-di-pesca-17-300x201.jpg","width":300,"height":201,"mime_type":"image\/jpeg","source_url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17-300x201.jpg"},"thumbnail":{"file":"Riserva-di-pesca-17-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17-150x150.jpg"},"full":{"file":"Riserva-di-pesca-17.jpg","width":493,"height":330,"mime_type":"image\/jpeg","source_url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":17251,"source_url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Riserva-di-pesca-17.jpg","_links":{"self":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/media\/17261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/users\/282"}],"wp:attached-to":[{"embeddable":true,"post_type":"turismo","id":17251,"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/turismo\/17251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}