{"id":17334,"date":"2022-03-29T17:07:40","date_gmt":"2022-03-29T15:07:40","guid":{"rendered":"https:\/\/comunicacity.net\/valpelline\/?post_type=turismo&#038;p=17334"},"modified":"2022-03-29T17:07:40","modified_gmt":"2022-03-29T15:07:40","slug":"targa-14","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/","title":{"rendered":"Targa 14"},"content":{"rendered":"<h3>Masso<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17335\" src=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg\" alt=\"\" width=\"1024\" height=\"722\" srcset=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg 1024w, https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14-300x212.jpg 300w, https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14-768x542.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-17336\" src=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/T14.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/T14.jpg 1024w, https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/T14-300x225.jpg 300w, https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/T14-768x576.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Masso<\/p>\n","protected":false},"featured_media":0,"parent":17288,"menu_order":14,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-17334","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Targa 14 - Valpelline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Targa 14 - Valpelline\" \/>\n<meta property=\"og:description\" content=\"Masso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Valpelline\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/\",\"name\":\"Targa 14 - Valpelline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Targa-14.jpg\",\"datePublished\":\"2022-03-29T15:07:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Targa-14.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/wp-content\\\/uploads\\\/sites\\\/206\\\/2022\\\/03\\\/Targa-14.jpg\",\"width\":1024,\"height\":722},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/targa-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orienteering della Valpelline\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/turismo\\\/orienteering-della-valpelline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Targa 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/valpelline\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Targa 14 - Valpelline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/","og_locale":"it_IT","og_type":"article","og_title":"Targa 14 - Valpelline","og_description":"Masso","og_url":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/","og_site_name":"Valpelline","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/","url":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/","name":"Targa 14 - Valpelline","isPartOf":{"@id":"https:\/\/comunicacity.net\/valpelline\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg","datePublished":"2022-03-29T15:07:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/#primaryimage","url":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg","contentUrl":"https:\/\/comunicacity.net\/valpelline\/wp-content\/uploads\/sites\/206\/2022\/03\/Targa-14.jpg","width":1024,"height":722},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/targa-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/valpelline\/"},{"@type":"ListItem","position":2,"name":"Orienteering della Valpelline","item":"https:\/\/comunicacity.net\/valpelline\/turismo\/orienteering-della-valpelline\/"},{"@type":"ListItem","position":3,"name":"Targa 14"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/valpelline\/#website","url":"https:\/\/comunicacity.net\/valpelline\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/valpelline\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/valpelline\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/valpelline\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/valpelline\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/valpelline\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/valpelline\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/turismo\/17334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/turismo\/17288"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/media?parent=17334"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/valpelline\/wp-json\/wp\/v2\/plugin_turismo?post=17334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}