{"id":1012,"date":"2019-09-12T20:21:36","date_gmt":"2019-09-12T18:21:36","guid":{"rendered":"https:\/\/comunicacity.net\/venarotta\/?p=1012"},"modified":"2019-09-12T21:26:25","modified_gmt":"2019-09-12T19:26:25","slug":"servizio-civile-per-i-giovani","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/","title":{"rendered":"SERVIZIO CIVILE PER I GIOVANI"},"content":{"rendered":"<h2>Bando 2019 per la selezione di volontari da impiegare in progetti di servizio civile universale<\/h2>\n<div class=\"news-date\">Trovi tutte le informazioni e il bando completo sul sito del comune di Venarotta:<\/div>\n<div><\/div>\n<div class=\"news-date\"><a href=\"http:\/\/www.comune.venarotta.ap.it\/c044073\/po\/mostra_news.php?id=363&amp;area=H\">http:\/\/www.comune.venarotta.ap.it\/c044073\/po\/mostra_news.php?id=363&amp;area=H<\/a><\/div>\n<div><\/div>\n<div>SARA&#8217; POSSIBILE CANDIDARSI ANCHE PER I DUE POSTI DISPONIBILI NEL COMUNE DI VENAROTTA (PROGETTI DEL COMUNE DI ASCOLI PICENO \u2013 ENTE CAPOFILA AMBITO<br \/>\nTERRITORIALE SOCIALE XXII \u2013 NZ01393 ).<\/div>\n<div><\/div>\n<div>CI SONO ANCHE TRE POSTI PRESSO LA CROCE VERDE &#8211; Sez Venarotta- Roccafluvione (PROGETTO PICENUM 2019).<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<p><strong>Gli aspiranti operativi volontari devono presentare domanda di partecipazione esclusivamente attraverso la piattaforma Domanda on Line (DOL) raggiungibile tramite PC, tablet e smartphone all&#8217;indirizzo\u00a0<\/strong><a href=\"https:\/\/domandaonline.serviziocivile.it\/\">https:\/\/domandaonline.serviziocivile.it<\/a>.<\/p>\n<p>Anche quest&#8217;anno, per facilitare la partecipazione dei giovani e, in pi\u00f9 in generale, per avvicinarli al mondo del servizio civile, \u00e8 disponibile il sito dedicato\u00a0<a href=\"http:\/\/www.scelgoilserviziocivile.gov.it\/\">http:\/\/www.scelgoilserviziocivile.gov.it<\/a>\u00a0che, grazie al linguaggio pi\u00f9 semplice, diretto proprio ai ragazzi, potr\u00e0 meglio orientarli tra le tante informazioni e aiutarli a compiere la scelta migliore.<\/p>\n<p>Tutte le informazioni possono essere scaricate dal sito nazionale<br \/>\n<a href=\"https:\/\/www.politichegiovanilieserviziocivile.gov.it\/dgscn-news\/2019\/9\/bandoordinario2019.aspx\">https:\/\/www.politichegiovanilieserviziocivile.gov.it\/dgscn-news\/2019\/9\/bandoordinario2019.aspx<\/a><\/p>\n<p>dal sito regionale<br \/>\n<a href=\"http:\/\/www.regione.marche.it\/Entra-in%20Regione\/Servizio-Civile\/News-ed-eventi\/Post\/51622\">http:\/\/www.regione.marche.it\/Entra-in Regione\/Servizio-Civile\/News-ed-eventi\/Post\/51622<\/a>\u00a0o dai siti degli enti proponenti i progetti.<\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bando 2019 per la selezione di volontari da impiegare in progetti di servizio civile universale Trovi tutte le informazioni e il bando completo sul sito del comune di Venarotta: http:\/\/www.comune.venarotta.ap.it\/c044073\/po\/mostra_news.php?id=363&amp;area=H [&hellip;]<\/p>\n","protected":false},"author":160,"featured_media":808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZIO CIVILE PER I GIOVANI - Venarotta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZIO CIVILE PER I GIOVANI - Venarotta\" \/>\n<meta property=\"og:description\" content=\"Bando 2019 per la selezione di volontari da impiegare in progetti di servizio civile universale Trovi tutte le informazioni e il bando completo sul sito del comune di Venarotta: http:\/\/www.comune.venarotta.ap.it\/c044073\/po\/mostra_news.php?id=363&amp;area=H [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/\" \/>\n<meta property=\"og:site_name\" content=\"Venarotta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-12T18:21:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-12T19:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/08\/download-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabio Salvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabio Salvi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/\"},\"author\":{\"name\":\"Fabio Salvi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"headline\":\"SERVIZIO CIVILE PER I GIOVANI\",\"datePublished\":\"2019-09-12T18:21:36+00:00\",\"dateModified\":\"2019-09-12T19:26:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/\"},\"wordCount\":208,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/08\\\/download-1.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/\",\"name\":\"SERVIZIO CIVILE PER I GIOVANI - Venarotta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/08\\\/download-1.jpg\",\"datePublished\":\"2019-09-12T18:21:36+00:00\",\"dateModified\":\"2019-09-12T19:26:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/08\\\/download-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/08\\\/download-1.jpg\",\"width\":225,\"height\":224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2019\\\/09\\\/12\\\/servizio-civile-per-i-giovani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZIO CIVILE PER I GIOVANI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\",\"name\":\"Venarotta\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\",\"name\":\"Fabio Salvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"caption\":\"Fabio Salvi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/author\\\/fabiosalvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZIO CIVILE PER I GIOVANI - Venarotta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZIO CIVILE PER I GIOVANI - Venarotta","og_description":"Bando 2019 per la selezione di volontari da impiegare in progetti di servizio civile universale Trovi tutte le informazioni e il bando completo sul sito del comune di Venarotta: http:\/\/www.comune.venarotta.ap.it\/c044073\/po\/mostra_news.php?id=363&amp;area=H [&hellip;]","og_url":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/","og_site_name":"Venarotta","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-09-12T18:21:36+00:00","article_modified_time":"2019-09-12T19:26:25+00:00","og_image":[{"width":225,"height":224,"url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/08\/download-1.jpg","type":"image\/jpeg"}],"author":"Fabio Salvi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Fabio Salvi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/"},"author":{"name":"Fabio Salvi","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"headline":"SERVIZIO CIVILE PER I GIOVANI","datePublished":"2019-09-12T18:21:36+00:00","dateModified":"2019-09-12T19:26:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/"},"wordCount":208,"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/08\/download-1.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/","url":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/","name":"SERVIZIO CIVILE PER I GIOVANI - Venarotta","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/08\/download-1.jpg","datePublished":"2019-09-12T18:21:36+00:00","dateModified":"2019-09-12T19:26:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#primaryimage","url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/08\/download-1.jpg","contentUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/08\/download-1.jpg","width":225,"height":224},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/venarotta\/2019\/09\/12\/servizio-civile-per-i-giovani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/venarotta\/"},{"@type":"ListItem","position":2,"name":"SERVIZIO CIVILE PER I GIOVANI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/venarotta\/#website","url":"https:\/\/comunicacity.net\/venarotta\/","name":"Venarotta","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/venarotta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527","name":"Fabio Salvi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","caption":"Fabio Salvi"},"url":"https:\/\/comunicacity.net\/venarotta\/author\/fabiosalvi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/1012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/comments?post=1012"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/1012\/revisions"}],"predecessor-version":[{"id":1015,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/1012\/revisions\/1015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media\/808"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media?parent=1012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/categories?post=1012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/tags?post=1012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}