{"id":545,"date":"2017-11-04T10:38:29","date_gmt":"2017-11-04T09:38:29","guid":{"rendered":"https:\/\/comunicacity.net\/venarotta\/?p=545"},"modified":"2017-11-04T10:38:51","modified_gmt":"2017-11-04T09:38:51","slug":"incontro-con-i-tecnici-progettisti-della-ricostruzione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/","title":{"rendered":"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE"},"content":{"rendered":"<p><strong><span style=\"color: #ff0000\">INCONTRO CON I TECNICI PROGETTISTI &#8211; Questo incontro \u00e8 finalizzato ad un incontro con i tecnici impegnati nella progettazione degli interventi di ricostruzione dopo il sisma.\u00a0L&#8217;incontro NON E&#8217; RIVOLTO alla cittadinanza ma ai soli progettisti, non saranno discussi temi di carattere generale ma solo problematiche relative alla presentazione dei progetti per la ricostruzione.<\/span><\/strong><\/p>\n<p>________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Oggetto:<\/strong> Incontro con i tecnici progettisti impegnati nei progetti di ricostruzione post\u2013sisma<\/p>\n<p>&nbsp;<\/p>\n<p>A seguito del costante confronto con i cittadini impattati dagli effetti del sisma \u00e8 emersa l\u2019opportunit\u00e0 di <strong><u>organizzare un incontro tra i TECNICI impegnati nella progettazione e i rappresentanti dell\u2019ufficio della ricostruzione al fine di comprendere quali sono le principali problematiche relative alla presentazione dei progetti e le possibili soluzioni.<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Finalizzato a questo obiettivo \u00e8 organizzato un tavolo tecnico di lavoro che si svolger\u00e0 a <strong><u>VENAROTTA in data Venerd\u00ec 10 NOVEMBRE 2017 alle ore 15:00<\/u><\/strong> presso il <em>gazebo comunale di Venarotta (Via Papa Giovanni Paolo II, 1).<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>All\u2019incontro parteciper\u00e0 il direttore dell\u2019ufficio speciale per la ricostruzione Ing. Cesare Spuri<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INCONTRO CON I TECNICI PROGETTISTI &#8211; Questo incontro \u00e8 finalizzato ad un incontro con i tecnici impegnati nella progettazione degli interventi di ricostruzione dopo il sisma.\u00a0L&#8217;incontro NON E&#8217; RIVOLTO alla [&hellip;]<\/p>\n","protected":false},"author":160,"featured_media":527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE - Venarotta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE - Venarotta\" \/>\n<meta property=\"og:description\" content=\"INCONTRO CON I TECNICI PROGETTISTI &#8211; Questo incontro \u00e8 finalizzato ad un incontro con i tecnici impegnati nella progettazione degli interventi di ricostruzione dopo il sisma.\u00a0L&#8217;incontro NON E&#8217; RIVOLTO alla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Venarotta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-04T09:38:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-04T09:38:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2017\/10\/house-158500_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabio Salvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabio Salvi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/\"},\"author\":{\"name\":\"Fabio Salvi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"headline\":\"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE\",\"datePublished\":\"2017-11-04T09:38:29+00:00\",\"dateModified\":\"2017-11-04T09:38:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/\"},\"wordCount\":176,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2017\\\/10\\\/house-158500_640.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/\",\"name\":\"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE - Venarotta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2017\\\/10\\\/house-158500_640.jpg\",\"datePublished\":\"2017-11-04T09:38:29+00:00\",\"dateModified\":\"2017-11-04T09:38:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2017\\\/10\\\/house-158500_640.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2017\\\/10\\\/house-158500_640.jpg\",\"width\":640,\"height\":554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2017\\\/11\\\/04\\\/incontro-con-i-tecnici-progettisti-della-ricostruzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\",\"name\":\"Venarotta\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\",\"name\":\"Fabio Salvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"caption\":\"Fabio Salvi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/author\\\/fabiosalvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE - Venarotta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/","og_locale":"it_IT","og_type":"article","og_title":"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE - Venarotta","og_description":"INCONTRO CON I TECNICI PROGETTISTI &#8211; Questo incontro \u00e8 finalizzato ad un incontro con i tecnici impegnati nella progettazione degli interventi di ricostruzione dopo il sisma.\u00a0L&#8217;incontro NON E&#8217; RIVOLTO alla [&hellip;]","og_url":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/","og_site_name":"Venarotta","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-04T09:38:29+00:00","article_modified_time":"2017-11-04T09:38:51+00:00","og_image":[{"width":640,"height":554,"url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2017\/10\/house-158500_640.jpg","type":"image\/jpeg"}],"author":"Fabio Salvi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Fabio Salvi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/"},"author":{"name":"Fabio Salvi","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"headline":"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE","datePublished":"2017-11-04T09:38:29+00:00","dateModified":"2017-11-04T09:38:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/"},"wordCount":176,"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2017\/10\/house-158500_640.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/","url":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/","name":"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE - Venarotta","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2017\/10\/house-158500_640.jpg","datePublished":"2017-11-04T09:38:29+00:00","dateModified":"2017-11-04T09:38:51+00:00","author":{"@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#primaryimage","url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2017\/10\/house-158500_640.jpg","contentUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2017\/10\/house-158500_640.jpg","width":640,"height":554},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/venarotta\/2017\/11\/04\/incontro-con-i-tecnici-progettisti-della-ricostruzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/venarotta\/"},{"@type":"ListItem","position":2,"name":"INCONTRO CON I TECNICI PROGETTISTI DELLA RICOSTRUZIONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/venarotta\/#website","url":"https:\/\/comunicacity.net\/venarotta\/","name":"Venarotta","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/venarotta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527","name":"Fabio Salvi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","caption":"Fabio Salvi"},"url":"https:\/\/comunicacity.net\/venarotta\/author\/fabiosalvi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"predecessor-version":[{"id":546,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/545\/revisions\/546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media\/527"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}