{"id":690,"date":"2018-04-06T11:01:32","date_gmt":"2018-04-06T09:01:32","guid":{"rendered":"https:\/\/comunicacity.net\/venarotta\/?p=690"},"modified":"2018-04-06T11:06:07","modified_gmt":"2018-04-06T09:06:07","slug":"sportello-sulla-dislessia-a-venarotta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/","title":{"rendered":"Sportello sulla dislessia a VENAROTTA"},"content":{"rendered":"<p>Riportiamo le date di attivazione dello sportello AID (Associazione Italiana Dislessia) operativo a Venarotta presso la sede municipale provvisoria.<\/p>\n<p>Rivolto a tutti i genitori, ragazzi, insegnanti ed educatori che gestiscono problematiche legate al DSA (o hanno necessit\u00e0 di approfondire).<\/p>\n<p>Attivit\u00e0 gratuita.<\/p>\n<p>Aperto a tutti compresi i cittadini di altri comuni interessati.<\/p>\n<p>_____________________<\/p>\n<p>Ecco le date<\/p>\n<p>12 APRILE ore 15:30<\/p>\n<p>17 MAGGIO ore 15:30<\/p>\n<p>Giornate dedicate all&#8217;ordinazione di libri digitali<\/p>\n<p>14 GIUGNO ORE 15:30<\/p>\n<p>28 GIUGNO ORE 15:30<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riportiamo le date di attivazione dello sportello AID (Associazione Italiana Dislessia) operativo a Venarotta presso la sede municipale provvisoria. Rivolto a tutti i genitori, ragazzi, insegnanti ed educatori che gestiscono [&hellip;]<\/p>\n","protected":false},"author":160,"featured_media":691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sportello sulla dislessia a VENAROTTA - Venarotta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sportello sulla dislessia a VENAROTTA - Venarotta\" \/>\n<meta property=\"og:description\" content=\"Riportiamo le date di attivazione dello sportello AID (Associazione Italiana Dislessia) operativo a Venarotta presso la sede municipale provvisoria. Rivolto a tutti i genitori, ragazzi, insegnanti ed educatori che gestiscono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/\" \/>\n<meta property=\"og:site_name\" content=\"Venarotta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-06T09:01:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-06T09:06:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/SPORTELLO-AID.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"566\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabio Salvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabio Salvi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/\"},\"author\":{\"name\":\"Fabio Salvi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"headline\":\"Sportello sulla dislessia a VENAROTTA\",\"datePublished\":\"2018-04-06T09:01:32+00:00\",\"dateModified\":\"2018-04-06T09:06:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/\"},\"wordCount\":74,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/SPORTELLO-AID.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/\",\"name\":\"Sportello sulla dislessia a VENAROTTA - Venarotta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/SPORTELLO-AID.jpg\",\"datePublished\":\"2018-04-06T09:01:32+00:00\",\"dateModified\":\"2018-04-06T09:06:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/SPORTELLO-AID.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/SPORTELLO-AID.jpg\",\"width\":566,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/06\\\/sportello-sulla-dislessia-a-venarotta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sportello sulla dislessia a VENAROTTA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\",\"name\":\"Venarotta\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\",\"name\":\"Fabio Salvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"caption\":\"Fabio Salvi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/author\\\/fabiosalvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sportello sulla dislessia a VENAROTTA - Venarotta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/","og_locale":"it_IT","og_type":"article","og_title":"Sportello sulla dislessia a VENAROTTA - Venarotta","og_description":"Riportiamo le date di attivazione dello sportello AID (Associazione Italiana Dislessia) operativo a Venarotta presso la sede municipale provvisoria. Rivolto a tutti i genitori, ragazzi, insegnanti ed educatori che gestiscono [&hellip;]","og_url":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/","og_site_name":"Venarotta","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-04-06T09:01:32+00:00","article_modified_time":"2018-04-06T09:06:07+00:00","og_image":[{"width":566,"height":800,"url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/SPORTELLO-AID.jpg","type":"image\/jpeg"}],"author":"Fabio Salvi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Fabio Salvi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/"},"author":{"name":"Fabio Salvi","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"headline":"Sportello sulla dislessia a VENAROTTA","datePublished":"2018-04-06T09:01:32+00:00","dateModified":"2018-04-06T09:06:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/"},"wordCount":74,"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/SPORTELLO-AID.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/","url":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/","name":"Sportello sulla dislessia a VENAROTTA - Venarotta","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/SPORTELLO-AID.jpg","datePublished":"2018-04-06T09:01:32+00:00","dateModified":"2018-04-06T09:06:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#primaryimage","url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/SPORTELLO-AID.jpg","contentUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/SPORTELLO-AID.jpg","width":566,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/06\/sportello-sulla-dislessia-a-venarotta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/venarotta\/"},{"@type":"ListItem","position":2,"name":"Sportello sulla dislessia a VENAROTTA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/venarotta\/#website","url":"https:\/\/comunicacity.net\/venarotta\/","name":"Venarotta","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/venarotta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527","name":"Fabio Salvi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","caption":"Fabio Salvi"},"url":"https:\/\/comunicacity.net\/venarotta\/author\/fabiosalvi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/comments?post=690"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/690\/revisions"}],"predecessor-version":[{"id":694,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/690\/revisions\/694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media\/691"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media?parent=690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/categories?post=690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/tags?post=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}