{"id":7,"date":"2016-11-03T12:33:27","date_gmt":"2016-11-03T11:33:27","guid":{"rendered":"https:\/\/comunicacity.net\/venarotta\/?p=7"},"modified":"2016-11-03T23:20:22","modified_gmt":"2016-11-03T22:20:22","slug":"attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/","title":{"rendered":"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta"},"content":{"rendered":"<p><span style=\"color: #000000; font-family: Calibri;\">AGGIORNAMENO SISMA (2 novembre):<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Dopo i primi giorni di gestione dell&#8217;emergenza abbiamo oggi avviato le attivit\u00e0 di pianificazione di questa seconda fase in attesa delle successive operazioni di sopralluogo con la protezione civile.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Nei prossimi due giorni completeremo la governance per la gestione delle richieste di ospitalit\u00e0 (sia presso le strutture comunali che presso gli hotel) e per l&#8217;utilizzo delle aree di raduno comuni. Vogliamo che tutti i cittadini ricevano supporto nel miglior modo possibile.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Inoltre sar\u00e0 emesso un comunicato per chiedere a tutta la popolazione di informarci circa spostamenti dalle proprie residenze al fine di avere il controllo totale sulle presenze nell&#8217;intero territorio.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Iniziamo a fare le prime valutazioni sugli interventi immediati da fare al fine di garantire la pubblica sicurezza, comprese le operazioni di pattugliamento anti sciacallaggio in collaborazione con le forze dell&#8217;ordine.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">#venarottanonmolla.<\/span><\/p>\n<p>&nbsp;<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>AGGIORNAMENO SISMA (2 novembre): Dopo i primi giorni di gestione dell&#8217;emergenza abbiamo oggi avviato le attivit\u00e0 di pianificazione di questa seconda fase in attesa delle successive operazioni di sopralluogo con [&hellip;]<\/p>\n","protected":false},"author":159,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-7","post","type-post","status-publish","format-standard","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta - Venarotta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta - Venarotta\" \/>\n<meta property=\"og:description\" content=\"AGGIORNAMENO SISMA (2 novembre): Dopo i primi giorni di gestione dell&#8217;emergenza abbiamo oggi avviato le attivit\u00e0 di pianificazione di questa seconda fase in attesa delle successive operazioni di sopralluogo con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/\" \/>\n<meta property=\"og:site_name\" content=\"Venarotta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-03T11:33:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-03T22:20:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Andrea Trenta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Trenta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/\"},\"author\":{\"name\":\"Andrea Trenta\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/eef6e2d654641be774197f7a536daa07\"},\"headline\":\"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta\",\"datePublished\":\"2016-11-03T11:33:27+00:00\",\"dateModified\":\"2016-11-03T22:20:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/\"},\"wordCount\":145,\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/\",\"name\":\"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta - Venarotta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\"},\"datePublished\":\"2016-11-03T11:33:27+00:00\",\"dateModified\":\"2016-11-03T22:20:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/eef6e2d654641be774197f7a536daa07\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2016\\\/11\\\/03\\\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\",\"name\":\"Venarotta\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/eef6e2d654641be774197f7a536daa07\",\"name\":\"Andrea Trenta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d9318f393061f204be309fa14605e031214ed5ab66fb13c6e3685b34485276f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d9318f393061f204be309fa14605e031214ed5ab66fb13c6e3685b34485276f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d9318f393061f204be309fa14605e031214ed5ab66fb13c6e3685b34485276f?s=96&d=mm&r=g\",\"caption\":\"Andrea Trenta\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/author\\\/andreatrenta\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta - Venarotta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/","og_locale":"it_IT","og_type":"article","og_title":"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta - Venarotta","og_description":"AGGIORNAMENO SISMA (2 novembre): Dopo i primi giorni di gestione dell&#8217;emergenza abbiamo oggi avviato le attivit\u00e0 di pianificazione di questa seconda fase in attesa delle successive operazioni di sopralluogo con [&hellip;]","og_url":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/","og_site_name":"Venarotta","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-11-03T11:33:27+00:00","article_modified_time":"2016-11-03T22:20:22+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/urgenze-e-allerta.png","height":600,"width":1200,"type":""}],"author":"Andrea Trenta","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Andrea Trenta","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/"},"author":{"name":"Andrea Trenta","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/eef6e2d654641be774197f7a536daa07"},"headline":"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta","datePublished":"2016-11-03T11:33:27+00:00","dateModified":"2016-11-03T22:20:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/"},"wordCount":145,"articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/","url":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/","name":"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta - Venarotta","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/#website"},"datePublished":"2016-11-03T11:33:27+00:00","dateModified":"2016-11-03T22:20:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/eef6e2d654641be774197f7a536daa07"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/venarotta\/2016\/11\/03\/attivazione-servizio-di-comunicazione-alla-cittadinanza-smart-di-venarotta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/venarotta\/"},{"@type":"ListItem","position":2,"name":"Attivazione servizio di comunicazione alla cittadinanza SMART di Venarotta"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/venarotta\/#website","url":"https:\/\/comunicacity.net\/venarotta\/","name":"Venarotta","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/venarotta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/eef6e2d654641be774197f7a536daa07","name":"Andrea Trenta","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8d9318f393061f204be309fa14605e031214ed5ab66fb13c6e3685b34485276f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d9318f393061f204be309fa14605e031214ed5ab66fb13c6e3685b34485276f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d9318f393061f204be309fa14605e031214ed5ab66fb13c6e3685b34485276f?s=96&d=mm&r=g","caption":"Andrea Trenta"},"url":"https:\/\/comunicacity.net\/venarotta\/author\/andreatrenta\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/7\/revisions"}],"predecessor-version":[{"id":17,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/7\/revisions\/17"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media?parent=7"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/categories?post=7"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/tags?post=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}