{"id":714,"date":"2018-04-19T11:52:11","date_gmt":"2018-04-19T09:52:11","guid":{"rendered":"https:\/\/comunicacity.net\/venarotta\/?p=714"},"modified":"2018-04-19T11:52:11","modified_gmt":"2018-04-19T09:52:11","slug":"educazione-civica-a-scuola","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/","title":{"rendered":"educazione civica a scuola"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-715\" src=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg 300w, https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-768x576.jpg 768w, https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-680x510.jpg 680w, https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-600x450.jpg 600w, https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-800x600.jpg 800w, https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Si svolger\u00e0 sabato il primo incontro del progetto &#8220;il sindaco torna a scuola&#8221; finalizzato ad incontrare gli studenti per parlare con loro di Educazione Civica e del bene comune.<\/p>\n<p>Il primo incontro sar\u00e0 con gli studenti della secondaria di primo grado sabato 21 Aprile al mattino.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si svolger\u00e0 sabato il primo incontro del progetto &#8220;il sindaco torna a scuola&#8221; finalizzato ad incontrare gli studenti per parlare con loro di Educazione Civica e del bene comune. Il [&hellip;]<\/p>\n","protected":false},"author":160,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-714","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>educazione civica a scuola - Venarotta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"educazione civica a scuola - Venarotta\" \/>\n<meta property=\"og:description\" content=\"Si svolger\u00e0 sabato il primo incontro del progetto &#8220;il sindaco torna a scuola&#8221; finalizzato ad incontrare gli studenti per parlare con loro di Educazione Civica e del bene comune. Il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/\" \/>\n<meta property=\"og:site_name\" content=\"Venarotta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-19T09:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg\" \/>\n<meta name=\"author\" content=\"Fabio Salvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabio Salvi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/\"},\"author\":{\"name\":\"Fabio Salvi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"headline\":\"educazione civica a scuola\",\"datePublished\":\"2018-04-19T09:52:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/\"},\"wordCount\":51,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/Il-sindaco-torna-a-scuola-300x225.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/\",\"name\":\"educazione civica a scuola - Venarotta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/Il-sindaco-torna-a-scuola-300x225.jpg\",\"datePublished\":\"2018-04-19T09:52:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/Il-sindaco-torna-a-scuola-300x225.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/04\\\/Il-sindaco-torna-a-scuola-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/04\\\/19\\\/educazione-civica-a-scuola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"educazione civica a scuola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\",\"name\":\"Venarotta\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\",\"name\":\"Fabio Salvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"caption\":\"Fabio Salvi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/author\\\/fabiosalvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"educazione civica a scuola - Venarotta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/","og_locale":"it_IT","og_type":"article","og_title":"educazione civica a scuola - Venarotta","og_description":"Si svolger\u00e0 sabato il primo incontro del progetto &#8220;il sindaco torna a scuola&#8221; finalizzato ad incontrare gli studenti per parlare con loro di Educazione Civica e del bene comune. Il [&hellip;]","og_url":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/","og_site_name":"Venarotta","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-04-19T09:52:11+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg","type":"","width":"","height":""}],"author":"Fabio Salvi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Fabio Salvi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/"},"author":{"name":"Fabio Salvi","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"headline":"educazione civica a scuola","datePublished":"2018-04-19T09:52:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/"},"wordCount":51,"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/","url":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/","name":"educazione civica a scuola - Venarotta","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg","datePublished":"2018-04-19T09:52:11+00:00","author":{"@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#primaryimage","url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg","contentUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/04\/Il-sindaco-torna-a-scuola-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/04\/19\/educazione-civica-a-scuola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/venarotta\/"},{"@type":"ListItem","position":2,"name":"educazione civica a scuola"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/venarotta\/#website","url":"https:\/\/comunicacity.net\/venarotta\/","name":"Venarotta","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/venarotta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527","name":"Fabio Salvi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","caption":"Fabio Salvi"},"url":"https:\/\/comunicacity.net\/venarotta\/author\/fabiosalvi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/comments?post=714"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/714\/revisions"}],"predecessor-version":[{"id":716,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/714\/revisions\/716"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media?parent=714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/categories?post=714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/tags?post=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}