{"id":768,"date":"2018-07-27T14:11:43","date_gmt":"2018-07-27T12:11:43","guid":{"rendered":"https:\/\/comunicacity.net\/venarotta\/?p=768"},"modified":"2018-07-27T14:11:43","modified_gmt":"2018-07-27T12:11:43","slug":"festa-della-caccia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/","title":{"rendered":"FESTA DELLA CACCIA"},"content":{"rendered":"<p>In contemporanea con la sagra della Vitella riproponiamo la Festa della Caccia.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-769\" src=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno-213x300.jpg\" alt=\"\" width=\"204\" height=\"288\" srcset=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno-213x300.jpg 213w, https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg 568w\" sizes=\"auto, (max-width: 204px) 100vw, 204px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>In contemporanea con la sagra della Vitella riproponiamo la Festa della Caccia. &nbsp;<\/p>\n","protected":false},"author":160,"featured_media":769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FESTA DELLA CACCIA - Venarotta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESTA DELLA CACCIA - Venarotta\" \/>\n<meta property=\"og:description\" content=\"In contemporanea con la sagra della Vitella riproponiamo la Festa della Caccia. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/\" \/>\n<meta property=\"og:site_name\" content=\"Venarotta\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-27T12:11:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"568\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabio Salvi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabio Salvi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/\"},\"author\":{\"name\":\"Fabio Salvi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"headline\":\"FESTA DELLA CACCIA\",\"datePublished\":\"2018-07-27T12:11:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/\"},\"wordCount\":16,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/07\\\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/\",\"name\":\"FESTA DELLA CACCIA - Venarotta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/07\\\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg\",\"datePublished\":\"2018-07-27T12:11:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/07\\\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/wp-content\\\/uploads\\\/sites\\\/74\\\/2018\\\/07\\\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg\",\"width\":568,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/2018\\\/07\\\/27\\\/festa-della-caccia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FESTA DELLA CACCIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/\",\"name\":\"Venarotta\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/#\\\/schema\\\/person\\\/02b0420bedcf89f0d97e535740f9e527\",\"name\":\"Fabio Salvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g\",\"caption\":\"Fabio Salvi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/venarotta\\\/author\\\/fabiosalvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESTA DELLA CACCIA - Venarotta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/","og_locale":"it_IT","og_type":"article","og_title":"FESTA DELLA CACCIA - Venarotta","og_description":"In contemporanea con la sagra della Vitella riproponiamo la Festa della Caccia. &nbsp;","og_url":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/","og_site_name":"Venarotta","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-07-27T12:11:43+00:00","og_image":[{"width":568,"height":800,"url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg","type":"image\/jpeg"}],"author":"Fabio Salvi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Fabio Salvi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/"},"author":{"name":"Fabio Salvi","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"headline":"FESTA DELLA CACCIA","datePublished":"2018-07-27T12:11:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/"},"wordCount":16,"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/","url":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/","name":"FESTA DELLA CACCIA - Venarotta","isPartOf":{"@id":"https:\/\/comunicacity.net\/venarotta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg","datePublished":"2018-07-27T12:11:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#primaryimage","url":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg","contentUrl":"https:\/\/comunicacity.net\/venarotta\/wp-content\/uploads\/sites\/74\/2018\/07\/Festa-della-caccia-Venarotta-2018-Gruppo-Cinofilo-Piceno.jpg","width":568,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/venarotta\/2018\/07\/27\/festa-della-caccia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/venarotta\/"},{"@type":"ListItem","position":2,"name":"FESTA DELLA CACCIA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/venarotta\/#website","url":"https:\/\/comunicacity.net\/venarotta\/","name":"Venarotta","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/venarotta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/venarotta\/#\/schema\/person\/02b0420bedcf89f0d97e535740f9e527","name":"Fabio Salvi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/454a9a2cad9e453693d323fd80a939f5d794fc2eb5b32cdc76d185fd8d4f3ea5?s=96&d=mm&r=g","caption":"Fabio Salvi"},"url":"https:\/\/comunicacity.net\/venarotta\/author\/fabiosalvi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/comments?post=768"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/768\/revisions"}],"predecessor-version":[{"id":770,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/posts\/768\/revisions\/770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media\/769"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/media?parent=768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/categories?post=768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/venarotta\/wp-json\/wp\/v2\/tags?post=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}