{"id":539,"date":"2017-08-21T15:52:44","date_gmt":"2017-08-21T13:52:44","guid":{"rendered":"https:\/\/comunicacity.net\/verres\/?p=539"},"modified":"2017-08-21T15:52:44","modified_gmt":"2017-08-21T13:52:44","slug":"a-verres-la-zucca-dallorto-alla-tavola-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/","title":{"rendered":"A VERRES, LA ZUCCA DALL&#8217;ORTO ALLA TAVOLA"},"content":{"rendered":"<p>Sono aperte le iscrizioni alla 6^ edizione de<strong> &#8220;A Verr\u00e8s, la zucca&#8230; dall&#8217;orto alla Tavola&#8221;<\/strong>. Gli interessati potranno consegnare l&#8217;adesione entro il <strong>15 settembre 2017.<\/strong><\/p>\n<p>Potranno aderire anche i proprietari di orti siti al di fuori del territorio verreziese<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sono aperte le iscrizioni alla 6^ edizione de &#8220;A Verr\u00e8s, la zucca&#8230; dall&#8217;orto alla Tavola&#8221;. Gli interessati potranno consegnare l&#8217;adesione entro il 15 settembre 2017. Potranno aderire anche i proprietari [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":540,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A VERRES, LA ZUCCA DALL&#039;ORTO ALLA TAVOLA - Verr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A VERRES, LA ZUCCA DALL&#039;ORTO ALLA TAVOLA - Verr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Sono aperte le iscrizioni alla 6^ edizione de &#8220;A Verr\u00e8s, la zucca&#8230; dall&#8217;orto alla Tavola&#8221;. Gli interessati potranno consegnare l&#8217;adesione entro il 15 settembre 2017. Potranno aderire anche i proprietari [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Verr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-21T13:52:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/08\/locandina-iscrizione-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"566\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Barbara Tonolini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara Tonolini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/\"},\"author\":{\"name\":\"Barbara Tonolini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"headline\":\"A VERRES, LA ZUCCA DALL&#8217;ORTO ALLA TAVOLA\",\"datePublished\":\"2017-08-21T13:52:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/\"},\"wordCount\":44,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/08\\\/locandina-iscrizione-2017.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/\",\"name\":\"A VERRES, LA ZUCCA DALL'ORTO ALLA TAVOLA - Verr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/08\\\/locandina-iscrizione-2017.jpg\",\"datePublished\":\"2017-08-21T13:52:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/08\\\/locandina-iscrizione-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/08\\\/locandina-iscrizione-2017.jpg\",\"width\":566,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2017\\\/08\\\/21\\\/a-verres-la-zucca-dallorto-alla-tavola-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A VERRES, LA ZUCCA DALL&#8217;ORTO ALLA TAVOLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\",\"name\":\"Verr\u00e8s\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\",\"name\":\"Barbara Tonolini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"caption\":\"Barbara Tonolini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/author\\\/barbaratonolini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A VERRES, LA ZUCCA DALL'ORTO ALLA TAVOLA - Verr\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/","og_locale":"it_IT","og_type":"article","og_title":"A VERRES, LA ZUCCA DALL'ORTO ALLA TAVOLA - Verr\u00e8s","og_description":"Sono aperte le iscrizioni alla 6^ edizione de &#8220;A Verr\u00e8s, la zucca&#8230; dall&#8217;orto alla Tavola&#8221;. Gli interessati potranno consegnare l&#8217;adesione entro il 15 settembre 2017. Potranno aderire anche i proprietari [&hellip;]","og_url":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/","og_site_name":"Verr\u00e8s","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-08-21T13:52:44+00:00","og_image":[{"width":566,"height":800,"url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/08\/locandina-iscrizione-2017.jpg","type":"image\/jpeg"}],"author":"Barbara Tonolini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Barbara Tonolini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/"},"author":{"name":"Barbara Tonolini","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"headline":"A VERRES, LA ZUCCA DALL&#8217;ORTO ALLA TAVOLA","datePublished":"2017-08-21T13:52:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/"},"wordCount":44,"image":{"@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/08\/locandina-iscrizione-2017.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/","url":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/","name":"A VERRES, LA ZUCCA DALL'ORTO ALLA TAVOLA - Verr\u00e8s","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/08\/locandina-iscrizione-2017.jpg","datePublished":"2017-08-21T13:52:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#primaryimage","url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/08\/locandina-iscrizione-2017.jpg","contentUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/08\/locandina-iscrizione-2017.jpg","width":566,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/verres\/2017\/08\/21\/a-verres-la-zucca-dallorto-alla-tavola-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/verres\/"},{"@type":"ListItem","position":2,"name":"A VERRES, LA ZUCCA DALL&#8217;ORTO ALLA TAVOLA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/verres\/#website","url":"https:\/\/comunicacity.net\/verres\/","name":"Verr\u00e8s","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/verres\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946","name":"Barbara Tonolini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","caption":"Barbara Tonolini"},"url":"https:\/\/comunicacity.net\/verres\/author\/barbaratonolini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/comments?post=539"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/539\/revisions"}],"predecessor-version":[{"id":541,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/539\/revisions\/541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media\/540"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media?parent=539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/categories?post=539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/tags?post=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}