{"id":71,"date":"2016-05-25T10:13:16","date_gmt":"2016-05-25T08:13:16","guid":{"rendered":"https:\/\/comunicacity.net\/verres\/?p=71"},"modified":"2016-05-25T10:34:27","modified_gmt":"2016-05-25T08:34:27","slug":"13-giornata-nazionale-dello-sport","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/","title":{"rendered":"13^ GIORNATA NAZIONALE DELLO SPORT"},"content":{"rendered":"<p>Nell&#8217;ambito della giornata nazionale dello sport, domenica 29 maggio, a partire dalle ore 14.00, presso l&#8217;Espace Loisirs M. Massa, si terr\u00e0 una giornata di giochi e sport che tutti possono praticare con la guida di esperti<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;ambito della giornata nazionale dello sport, domenica 29 maggio, a partire dalle ore 14.00, presso l&#8217;Espace Loisirs M. Massa, si terr\u00e0 una giornata di giochi e sport che tutti possono [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":72,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-71","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13^ GIORNATA NAZIONALE DELLO SPORT - Verr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13^ GIORNATA NAZIONALE DELLO SPORT - Verr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Nell&#8217;ambito della giornata nazionale dello sport, domenica 29 maggio, a partire dalle ore 14.00, presso l&#8217;Espace Loisirs M. Massa, si terr\u00e0 una giornata di giochi e sport che tutti possono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"Verr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-25T08:13:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-25T08:34:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/05\/LOCANDINA-sport.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"283\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Barbara Tonolini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara Tonolini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/\"},\"author\":{\"name\":\"Barbara Tonolini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"headline\":\"13^ GIORNATA NAZIONALE DELLO SPORT\",\"datePublished\":\"2016-05-25T08:13:16+00:00\",\"dateModified\":\"2016-05-25T08:34:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/\"},\"wordCount\":39,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2016\\\/05\\\/LOCANDINA-sport.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/\",\"name\":\"13^ GIORNATA NAZIONALE DELLO SPORT - Verr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2016\\\/05\\\/LOCANDINA-sport.jpg\",\"datePublished\":\"2016-05-25T08:13:16+00:00\",\"dateModified\":\"2016-05-25T08:34:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2016\\\/05\\\/LOCANDINA-sport.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2016\\\/05\\\/LOCANDINA-sport.jpg\",\"width\":283,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2016\\\/05\\\/25\\\/13-giornata-nazionale-dello-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13^ GIORNATA NAZIONALE DELLO SPORT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\",\"name\":\"Verr\u00e8s\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\",\"name\":\"Barbara Tonolini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"caption\":\"Barbara Tonolini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/author\\\/barbaratonolini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13^ GIORNATA NAZIONALE DELLO SPORT - Verr\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/","og_locale":"it_IT","og_type":"article","og_title":"13^ GIORNATA NAZIONALE DELLO SPORT - Verr\u00e8s","og_description":"Nell&#8217;ambito della giornata nazionale dello sport, domenica 29 maggio, a partire dalle ore 14.00, presso l&#8217;Espace Loisirs M. Massa, si terr\u00e0 una giornata di giochi e sport che tutti possono [&hellip;]","og_url":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/","og_site_name":"Verr\u00e8s","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-05-25T08:13:16+00:00","article_modified_time":"2016-05-25T08:34:27+00:00","og_image":[{"width":283,"height":400,"url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/05\/LOCANDINA-sport.jpg","type":"image\/jpeg"}],"author":"Barbara Tonolini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Barbara Tonolini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/"},"author":{"name":"Barbara Tonolini","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"headline":"13^ GIORNATA NAZIONALE DELLO SPORT","datePublished":"2016-05-25T08:13:16+00:00","dateModified":"2016-05-25T08:34:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/"},"wordCount":39,"image":{"@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/05\/LOCANDINA-sport.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/","url":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/","name":"13^ GIORNATA NAZIONALE DELLO SPORT - Verr\u00e8s","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/05\/LOCANDINA-sport.jpg","datePublished":"2016-05-25T08:13:16+00:00","dateModified":"2016-05-25T08:34:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#primaryimage","url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/05\/LOCANDINA-sport.jpg","contentUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/05\/LOCANDINA-sport.jpg","width":283,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/verres\/2016\/05\/25\/13-giornata-nazionale-dello-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/verres\/"},{"@type":"ListItem","position":2,"name":"13^ GIORNATA NAZIONALE DELLO SPORT"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/verres\/#website","url":"https:\/\/comunicacity.net\/verres\/","name":"Verr\u00e8s","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/verres\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946","name":"Barbara Tonolini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","caption":"Barbara Tonolini"},"url":"https:\/\/comunicacity.net\/verres\/author\/barbaratonolini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/comments?post=71"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/71\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/71\/revisions\/74"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media\/72"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media?parent=71"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/categories?post=71"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/tags?post=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}