{"id":755,"date":"2018-02-21T16:49:04","date_gmt":"2018-02-21T15:49:04","guid":{"rendered":"https:\/\/comunicacity.net\/verres\/?p=755"},"modified":"2018-02-21T16:49:04","modified_gmt":"2018-02-21T15:49:04","slug":"possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/","title":{"rendered":"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI &#8211;  ESPERIENZE PRATICHE"},"content":{"rendered":"<p><strong>Gioved\u00ec 22 febbraio 2018 alle ore 20.30<\/strong>, presso il Salone Comunale M. Bonomi si terr\u00e0 il secondo appuntamento de &#8220;I gioved\u00ec dell&#8217;Orto&#8221;.<\/p>\n<p>La Coldiretti Valle d&#8217;Aosta e le Aziende Agricole &#8220;Montiflor&#8221; e &#8220;La Sauvagette&#8221; illustreranno i <strong>POSSIBILI UTILIZZI DELLE ERBE OFFICINALI &#8211; ESPERIENZE PRATICHE.<\/strong><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 22 febbraio 2018 alle ore 20.30, presso il Salone Comunale M. Bonomi si terr\u00e0 il secondo appuntamento de &#8220;I gioved\u00ec dell&#8217;Orto&#8221;. La Coldiretti Valle d&#8217;Aosta e le Aziende Agricole [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POSSIBILI UTILIZZI DELLE ERBE OFFICINALI - ESPERIENZE PRATICHE - Verr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI - ESPERIENZE PRATICHE - Verr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 22 febbraio 2018 alle ore 20.30, presso il Salone Comunale M. Bonomi si terr\u00e0 il secondo appuntamento de &#8220;I gioved\u00ec dell&#8217;Orto&#8221;. La Coldiretti Valle d&#8217;Aosta e le Aziende Agricole [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Verr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-21T15:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2018\/02\/locandina-22_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"566\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Barbara Tonolini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara Tonolini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/\"},\"author\":{\"name\":\"Barbara Tonolini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"headline\":\"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI &#8211; ESPERIENZE PRATICHE\",\"datePublished\":\"2018-02-21T15:49:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/\"},\"wordCount\":49,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2018\\\/02\\\/locandina-22_02.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/\",\"name\":\"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI - ESPERIENZE PRATICHE - Verr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2018\\\/02\\\/locandina-22_02.jpg\",\"datePublished\":\"2018-02-21T15:49:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2018\\\/02\\\/locandina-22_02.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2018\\\/02\\\/locandina-22_02.jpg\",\"width\":566,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2018\\\/02\\\/21\\\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI &#8211; ESPERIENZE PRATICHE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\",\"name\":\"Verr\u00e8s\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\",\"name\":\"Barbara Tonolini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"caption\":\"Barbara Tonolini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/author\\\/barbaratonolini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI - ESPERIENZE PRATICHE - Verr\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/","og_locale":"it_IT","og_type":"article","og_title":"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI - ESPERIENZE PRATICHE - Verr\u00e8s","og_description":"Gioved\u00ec 22 febbraio 2018 alle ore 20.30, presso il Salone Comunale M. Bonomi si terr\u00e0 il secondo appuntamento de &#8220;I gioved\u00ec dell&#8217;Orto&#8221;. La Coldiretti Valle d&#8217;Aosta e le Aziende Agricole [&hellip;]","og_url":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/","og_site_name":"Verr\u00e8s","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-02-21T15:49:04+00:00","og_image":[{"width":566,"height":800,"url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2018\/02\/locandina-22_02.jpg","type":"image\/jpeg"}],"author":"Barbara Tonolini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Barbara Tonolini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/"},"author":{"name":"Barbara Tonolini","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"headline":"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI &#8211; ESPERIENZE PRATICHE","datePublished":"2018-02-21T15:49:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/"},"wordCount":49,"image":{"@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2018\/02\/locandina-22_02.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/","url":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/","name":"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI - ESPERIENZE PRATICHE - Verr\u00e8s","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2018\/02\/locandina-22_02.jpg","datePublished":"2018-02-21T15:49:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#primaryimage","url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2018\/02\/locandina-22_02.jpg","contentUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2018\/02\/locandina-22_02.jpg","width":566,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/verres\/2018\/02\/21\/possibili-utilizzi-delle-erbe-officinali-esperienze-pratiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/verres\/"},{"@type":"ListItem","position":2,"name":"POSSIBILI UTILIZZI DELLE ERBE OFFICINALI &#8211; ESPERIENZE PRATICHE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/verres\/#website","url":"https:\/\/comunicacity.net\/verres\/","name":"Verr\u00e8s","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/verres\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946","name":"Barbara Tonolini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","caption":"Barbara Tonolini"},"url":"https:\/\/comunicacity.net\/verres\/author\/barbaratonolini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/comments?post=755"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/755\/revisions"}],"predecessor-version":[{"id":757,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/755\/revisions\/757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media\/756"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media?parent=755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/categories?post=755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/tags?post=755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}