{"id":934,"date":"2019-02-18T13:10:49","date_gmt":"2019-02-18T12:10:49","guid":{"rendered":"https:\/\/comunicacity.net\/verres\/?p=934"},"modified":"2019-02-18T13:10:49","modified_gmt":"2019-02-18T12:10:49","slug":"bandi-gal-valle-daosta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/","title":{"rendered":"BANDI GAL VALLE D&#8217;AOSTA"},"content":{"rendered":"<p><strong>Domani Marted\u00ec 19 febbraio 2019 alle ore 20.30<\/strong>, presso il Salone Comunale M. Bonomi, si terr\u00e0 la presentazione dei <strong>bandi GAL VALLE D&#8217;AOSTA.<\/strong><\/p>\n<p>I tre bandi e la relativa modulistica sono disponibilit\u00e0 all&#8217;indirizzo: <a href=\"http:\/\/www.gal.vda.it\">www.gal.vda.it.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani Marted\u00ec 19 febbraio 2019 alle ore 20.30, presso il Salone Comunale M. Bonomi, si terr\u00e0 la presentazione dei bandi GAL VALLE D&#8217;AOSTA. I tre bandi e la relativa modulistica [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BANDI GAL VALLE D&#039;AOSTA - Verr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BANDI GAL VALLE D&#039;AOSTA - Verr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Domani Marted\u00ec 19 febbraio 2019 alle ore 20.30, presso il Salone Comunale M. Bonomi, si terr\u00e0 la presentazione dei bandi GAL VALLE D&#8217;AOSTA. I tre bandi e la relativa modulistica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/\" \/>\n<meta property=\"og:site_name\" content=\"Verr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-18T12:10:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2019\/02\/GAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Barbara Tonolini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara Tonolini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/\"},\"author\":{\"name\":\"Barbara Tonolini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"headline\":\"BANDI GAL VALLE D&#8217;AOSTA\",\"datePublished\":\"2019-02-18T12:10:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/\"},\"wordCount\":38,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2019\\\/02\\\/GAL.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/\",\"name\":\"BANDI GAL VALLE D'AOSTA - Verr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2019\\\/02\\\/GAL.jpg\",\"datePublished\":\"2019-02-18T12:10:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2019\\\/02\\\/GAL.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2019\\\/02\\\/GAL.jpg\",\"width\":1240,\"height\":1754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/2019\\\/02\\\/18\\\/bandi-gal-valle-daosta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BANDI GAL VALLE D&#8217;AOSTA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\",\"name\":\"Verr\u00e8s\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#\\\/schema\\\/person\\\/1d1e1342c0243b3566ac33501a891946\",\"name\":\"Barbara Tonolini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g\",\"caption\":\"Barbara Tonolini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/author\\\/barbaratonolini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BANDI GAL VALLE D'AOSTA - Verr\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/","og_locale":"it_IT","og_type":"article","og_title":"BANDI GAL VALLE D'AOSTA - Verr\u00e8s","og_description":"Domani Marted\u00ec 19 febbraio 2019 alle ore 20.30, presso il Salone Comunale M. Bonomi, si terr\u00e0 la presentazione dei bandi GAL VALLE D&#8217;AOSTA. I tre bandi e la relativa modulistica [&hellip;]","og_url":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/","og_site_name":"Verr\u00e8s","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-18T12:10:49+00:00","og_image":[{"width":1240,"height":1754,"url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2019\/02\/GAL.jpg","type":"image\/jpeg"}],"author":"Barbara Tonolini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Barbara Tonolini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/"},"author":{"name":"Barbara Tonolini","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"headline":"BANDI GAL VALLE D&#8217;AOSTA","datePublished":"2019-02-18T12:10:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/"},"wordCount":38,"image":{"@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2019\/02\/GAL.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/","url":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/","name":"BANDI GAL VALLE D'AOSTA - Verr\u00e8s","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2019\/02\/GAL.jpg","datePublished":"2019-02-18T12:10:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#primaryimage","url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2019\/02\/GAL.jpg","contentUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2019\/02\/GAL.jpg","width":1240,"height":1754},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/verres\/2019\/02\/18\/bandi-gal-valle-daosta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/verres\/"},{"@type":"ListItem","position":2,"name":"BANDI GAL VALLE D&#8217;AOSTA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/verres\/#website","url":"https:\/\/comunicacity.net\/verres\/","name":"Verr\u00e8s","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/verres\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/verres\/#\/schema\/person\/1d1e1342c0243b3566ac33501a891946","name":"Barbara Tonolini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fae9bc7d50fd5d6bdc656151715628fb7eaef45bac4c2312ddd2677a66320bfc?s=96&d=mm&r=g","caption":"Barbara Tonolini"},"url":"https:\/\/comunicacity.net\/verres\/author\/barbaratonolini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/comments?post=934"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/934\/revisions"}],"predecessor-version":[{"id":936,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/posts\/934\/revisions\/936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media\/935"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media?parent=934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/categories?post=934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/tags?post=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}