{"id":304,"date":"2017-02-27T11:27:15","date_gmt":"2017-02-27T10:27:15","guid":{"rendered":"https:\/\/comunicacity.net\/verres\/?post_type=turismo&#038;p=304"},"modified":"2017-02-27T11:27:15","modified_gmt":"2017-02-27T10:27:15","slug":"iv-ed-il-v-secolo","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/","title":{"rendered":"IV ed il V secolo"},"content":{"rendered":"<p class=\"testoGiustificato\">Della diffusione del Cristianesimo in Valle d\u2019Aosta tra il IV ed il V secolo Verr\u00e8s conserva tracce nel nome di Martorey dato ad un suo quartiere, toponimo che richiama la presenza di un edificio di culto in cui si veneravano reliquie di martiri, fors\u2019anche abitanti la zona ed uccisi sul posto. All\u2019Alto Medioevo &#8211; secondo la tradizione al 912 &#8211; risale la fondazione del convento di Saint-Gilles (Sant\u2019Egidio) i cui canonici, retti da un prevosto &#8211; da cui il nome di Prevostura dato all\u2019istituzione &#8211; vivevano in comunit\u00e0 seguendo, almeno a partire dall\u2019inizio del XIII secolo, la regola di sant\u2019Agostino. L\u2019edificio della Prevostura, pi\u00f9 volte rimaneggiato fino alla fine del XVIII secolo, conserva una dominante impronta tardogotica e, col castello, caratterizza ancora oggi il vecchio borgo. La Prevostura acquist\u00f2 subito anche importanza economica grazie ai benefici ed alle parrocchie che le vennero affidati da vescovi e da Papi ed alle donazioni dei fedeli. Essa costitu\u00ec quindi un centro di attrazione per la popolazione dei dintorni e contribu\u00ec cos\u00ec al popolamento ed allo sviluppo del borgo la cui posizione assunse sempre pi\u00f9 &#8211; a partire dal rinnovamento economico e sociale riscontrabile in tutta l\u2019Europa occidentale all\u2019inizio del secondo millennio dell\u2019era cristiana &#8211; una importanza anche strategica per il controllo del transito nella valle centrale della Dora ed in quella laterale dell\u2019Evan\u00e7on. Nella parte alta di quest\u2019ultima, nel territorio di Brusson controllato dal castello di Graines, giungeva infatti, dal colle Ranzola (2200 m), la via commerciale che univa la Lombardia alla Svizzera proseguendo, alla testata della valle, attraverso il colle delle Cime Bianche (3000 m) e, nella Valtournenche, attraverso il colle del Teodulo (3300 m). Questa via commerciale, che collegava i mercati dell\u2019Europa del Nord con quelli della pianura padana, era, nel Basso Medioevo, percorribile con relativa facilit\u00e0 da portatori e da bestie da soma, grazie ad un clima che, meno freddo dell\u2019attuale, manteneva libero dai ghiacci anche il passo del Teodulo. La necessit\u00e0 di controllare queste vie commerciali spiega anche la presenza a Verr\u00e8s dell\u2019imponente castello che possiamo ammirare ancora oggi sul promontorio che sovrasta il borgo dalla sponda sinistra dell\u2019Evan\u00e7on. L\u2019attuale edificio &#8211; che gli Challant eressero alla fine del Trecento &#8211; dovette sicuramente essere stato preceduto da altri pi\u00f9 antichi e meno formidabili. La famiglia nobile dei De Verrecio compare, come titolare di signoria sul paese da cui trae il nome, nell\u2019anno 1205. Come i signori di Quart, i De Verrecio discendevano dai signori aostani De Porta Sancti Ursi, la cui torre sorge ancora oggi su un lato della romana Porta Praetoria di Aosta. Su Torille avevano una qualche giurisdizione anche i De Turrilia che vi possedevano appunto una dimora fortificata. Anche i De Arnado, signori di una parte di Arnad, esercitarono nel Duecento loro diritti sulla parte orientale del borgo di Verr\u00e8s fino all\u2019Evan\u00e7on. Infine, il prevosto di Saint-Gilles vantava anch\u2019egli diritti feudali ed ecclesiastici sul territorio circostante la Prevostura. I pi\u00f9 importanti signori del luogo erano per\u00f2 &#8211; prima che gli Challant li soppiantassero &#8211; i De Verrecio. Ad essi, nella persona di Roleto nel 1312, si devono le prime franchigie concesse agli abitanti di Verr\u00e8s. Questi vi videro riconosciuti alcuni loro diritti &#8211; specie in materia di successione &#8211; e regolamentate la riscossione delle imposte e la punizione dei delitti. La carta di concessione ci informa anche che il borgo di Verr\u00e8s era all\u2019epoca circondato da mura, protette in un tratto da un fossato<\/p>\n<p class=\"testoGiustificato\">Nella zona le rivalit\u00e0 tra signori, tipiche del mondo feudale, si manifestarono soprattutto tra i De Verrecio ed il vescovo di Aosta, titolare della signoria di Issogne, sfociando anche in scontri armati.<br \/>\nNella seconda met\u00e0 del Trecento i De Verrecio si estinsero ed il loro feudo torn\u00f2 nelle mani del conte di Savoia Amedeo VI che nel 1372 lo diede ad Ibleto di Challant, signore del paese omonimo da cui la sua famiglia aveva tratto il nome, di Graines, Ch\u00e2tillon, Saint-Vincent e Montjovet. Ibleto &#8211; che gi\u00e0 aveva ereditato, perch\u00e9 giunti nel suo ceppo familiare, la giurisdizione dei De Turrilia ed i diritti dei De Arnado &#8211; diveniva cos\u00ec unico signore di tutto il territorio di Verr\u00e8s. Nel 1379, acquistando dal vescovo di Aosta la signoria di Issogne, diventava padrone di tutta la valle dell\u2019Evan\u00e7on e dell\u2019intera porzione di valle centrale su cui si affaccia la valle di Challand. Ibleto, gi\u00e0 noto per la prestigiosa carica di capitano di Piemonte attribuitagli nel 1369 da Amedeo VI di Savoia, si diede allora ad ingrandire il vecchio castello vescovile di Issogne ed a costruire dalle fondamenta l\u2019attuale castello di Verr\u00e8s. Termin\u00f2 quest\u2019ultimo nel 1390 e fece incidere tale data sull\u2019architrave di pietra della prima porta che si incontra al primo piano salendo lo scalone del cortile. Costruito in un corpo unico, in forma di grossa torre cubica, il castello di Verr\u00e8s \u00e8 una delle migliori fortezze europee del Medioevo. Ibleto ne cur\u00f2 anche gli interni per ricavare, riuscendovi, una dimora signorile. La sua morte, nel 1409, avvenne probabilmente in questo castello.<br \/>\nCon l\u2019intenzione di farne il proprio mausoleo, Ibleto aveva iniziato, gi\u00e0 prima del 1405, nel convento di Saint-Gilles, la costruzione della cappella Challant, nella cui cripta fu poi effettivamente sepolto. Suo figlio Francesco divenne nel 1424 il primo conte di Challant. Amedeo VIII di Savoia, nel 1416 da conte fatto duca dall\u2019imperatore Sigismondo di Lussemburgo, volle cos\u00ec ricompensare i servigi resi alla sua dinastia dal ramo principale di Casa Challant. Verr\u00e8s continu\u00f2 naturalmente ad essere una delle terre pi\u00f9 importanti della contea. Nel 1435 il conte Francesco rinnov\u00f2 ed ampli\u00f2 le franchigie di Roleto e, alla met\u00e0 di quello stesso secolo, la cittadina di Verr\u00e8s venne coinvolta nella guerra di successione per l\u2019eredit\u00e0 del conte Francesco. Costui, infrangendo le norme del diritto feudale, aveva lasciato i suoi feudi &#8211; tra cui appunto Verr\u00e8s &#8211; in eredit\u00e0 alle figlie Margherita e Caterina. I parenti maschi pi\u00f9 prossimi protestarono appoggiandosi al duca di Savoia. Caterina, forte del sostegno del suo secondo marito Pierre d\u2019Introd, fece fronte anche con le armi ai suoi nemici. A queste vicende s\u2019ispira oggi il carnevale storico. Pierre d\u2019Introd trov\u00f2 la morte cercando, partito dal castello di Verr\u00e8s, di portare soccorso a sua moglie assediata nel castello di Ch\u00e2tillon. Il titolo di conte di Challant and\u00f2, nel 1456, a Giacomo del ramo Aymavilles. Ma Caterina, passata nel 1462 a terze nozze con Pierre de Chiss\u00e9, riprese le armi. Lo scontro decisivo tra le parti in lotta avvenne nel 1465 nella piana di Verr\u00e8s e segn\u00f2 la definitiva sconfitta di Caterina. Verr\u00e8s e la contea di Challant restavano cos\u00ec saldamente nelle mani del conte Luigi, figlio e successore di Giacomo.<br \/>\nLa potenza politica ed economica raggiunta dai Challant tra la fine del Quattrocento e l\u2019inizio del Cinquecento lasci\u00f2 segni evidenti a Saint-Gilles dove il prevosto Carlo di Challant, fratello del conte Filiberto figlio di Luigi, innalz\u00f2 &#8211; terminandola nel 1512 &#8211; la torre campanaria e l\u2019edificio in pietra a vista rivolto verso la valle centrale. Sempre nel 1512 lo stesso Carlo dotava il convento della cascina Murasse situata nel piano. Nel 1536 Renato, figlio di Filiberto e quinto conte di Challant, faceva circondare il castello di Verr\u00e8s da bastioni capaci di portare l\u2019artiglieria. Era infatti in corso la lunga guerra della Francia contro la Spagna e l\u2019Impero e si temeva che gli eserciti dei contendenti potessero invadere la Valle d\u2019Aosta, che invece riusc\u00ec ad evitare questo pericolo essendosi dotata, nello sfacelo del Ducato di Savoia, di organismi autonomi di governo ed avendo stretto patti di neutralit\u00e0 con la Francia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Della diffusione del Cristianesimo in Valle d\u2019Aosta tra il IV ed il V secolo Verr\u00e8s conserva tracce nel nome di Martorey dato ad un suo quartiere, toponimo che richiama la [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":299,"menu_order":3,"template":"","meta":[],"class_list":["post-304","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IV ed il V secolo - Verr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IV ed il V secolo - Verr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Della diffusione del Cristianesimo in Valle d\u2019Aosta tra il IV ed il V secolo Verr\u00e8s conserva tracce nel nome di Martorey dato ad un suo quartiere, toponimo che richiama la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Verr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/03\/verr\u00e8s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/storia\\\/iv-ed-il-v-secolo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/storia\\\/iv-ed-il-v-secolo\\\/\",\"name\":\"IV ed il V secolo - Verr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\"},\"datePublished\":\"2017-02-27T10:27:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/storia\\\/iv-ed-il-v-secolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/storia\\\/iv-ed-il-v-secolo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/storia\\\/iv-ed-il-v-secolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storia\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/storia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IV ed il V secolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\",\"name\":\"Verr\u00e8s\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IV ed il V secolo - Verr\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/","og_locale":"it_IT","og_type":"article","og_title":"IV ed il V secolo - Verr\u00e8s","og_description":"Della diffusione del Cristianesimo in Valle d\u2019Aosta tra il IV ed il V secolo Verr\u00e8s conserva tracce nel nome di Martorey dato ad un suo quartiere, toponimo che richiama la [&hellip;]","og_url":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/","og_site_name":"Verr\u00e8s","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2016\/03\/verr\u00e8s.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/","url":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/","name":"IV ed il V secolo - Verr\u00e8s","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/#website"},"datePublished":"2017-02-27T10:27:15+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/iv-ed-il-v-secolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/verres\/"},{"@type":"ListItem","position":2,"name":"Storia","item":"https:\/\/comunicacity.net\/verres\/turismo\/storia\/"},{"@type":"ListItem","position":3,"name":"IV ed il V secolo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/verres\/#website","url":"https:\/\/comunicacity.net\/verres\/","name":"Verr\u00e8s","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/verres\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/turismo\/304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/turismo\/299"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media?parent=304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}