{"id":334,"date":"2017-02-27T11:55:57","date_gmt":"2017-02-27T10:55:57","guid":{"rendered":"https:\/\/comunicacity.net\/verres\/?post_type=turismo&#038;p=334"},"modified":"2017-02-27T11:55:57","modified_gmt":"2017-02-27T10:55:57","slug":"arboretum-borna-du-laou","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/","title":{"rendered":"Arboretum &#8220;Borna du laou&#8221;"},"content":{"rendered":"<p>Un panorama e dei profumi decisamente mediterranei accompagnano il visitatore all&#8217;interno di questo particolare arboreto impiantato nella prima met\u00e0 degli anni &#8217;50 dal Corpo Forestale, allora ancora dello Stato. Difatti, a partire dal 1951, furono messe a dimora o seminate diverse specie esotiche tra le quali i pini marittimo, domestico, nero e strobo, il cedro dell&#8217;Atlante, l&#8217;abete del Caucaso, il leccio, il carpino, la tuia, ecc. La zona scelta per il rimboschimento, (da secoli di propriet\u00e0 della Prevostura di Saint-Gilles, ora di propriet\u00e0 dell&#8217;Istituto Diocesano per il<br \/>\nSostentamento del Clero), si estende su una superficie di circa 6 Ha. e la natura del terreno, pietrosa, arida e inframezzata da arditi terrazzamenti che racchiudevano lembi di terra precedentemente coltivati, non garantiva un sicuro attecchimento. Ci\u00f2 nonostante il risultato dell&#8217;esperimento \u00e8 quello che appare ora ai nostri occhi: un suggestivo alternarsi di gruppi di piante ottimamente affermate che, addirittura, iniziano gi\u00e0 a rinnovarsi naturalmente, soprattutto cedro, pini e tuia. Alcune specie menzionate nei registri di rimboschimento dell&#8217;epoca non sono state pi\u00f9 ritrovate, come il carpino ed il pino strobo, ma i superstiti, assieme all&#8217;abbondante vegetazione autoctona impiantata o spontanea, garantiscono lo stesso un notevole effetto paesaggistico al bosco costituitosi. Ma quel che pi\u00f9 interessa \u00e8 l&#8217;aspetto botanico di questo arboreto, in quanto risulta essere uno dei rari esempi, nella nostra regione, dove specie come il pino domestico e quello marittimo, si siano affermate cos\u00ec bene a dispetto delle non ideali condizioni climatiche per le stesse. Bisogna per\u00f2 ricordare che Verr\u00e8s beneficia di un clima pi\u00f9 dolce rispetto ad altre localit\u00e0 della regione, soprattutto della media e alta Valle, per cui questo microclima favorevole \u00e8 stato determinante per l&#8217;affermarsi delle specie esotiche.<br \/>\nL&#8217;arboreto si situa in uno dei pi\u00f9 panoramici angoli di Verr\u00e8s, difatti \u00e8 posizionato lungo il fianco sinistro orografico all&#8217;imbocco della Val d&#8217;Ayas. Il paesaggio visibile da questo sito \u00e8 straordinariamente vasto e bello: il severo maniero di Verr\u00e8s, eretto nella seconda met\u00e0 del 1300 da Ibleto di Challant, appare alla nostra sinistra in tutta la sua imponenza. Inoltre, ai piedi del rimboschimento, esiste uno dei pi\u00f9 celebri e vecchi conventi della Valle d&#8217;Aosta: il Priorato di Saint-Gilles. Le antiche carte rivelano che fu fondato nel 925 da Adalberto di Ivrea ed ancora oggi possiamo ammirare i suoi edifici, tra i quali la torre dell&#8217;Orologio ed il chiostro, nonch\u00e9 alcuni olivi (dichiarati monumentali) riparati a sud dai possenti muri dell&#8217;edificio. Gli olivi, intorno al 1850, fornivano sufficiente olio per tutto l&#8217;anno alla Confraternita. Il vasto giardino del Priorato \u00e8 stato oggetto di completo rifacimento e risistemazione a cura della Direzione Forestazione dell&#8217;Assessorato regionale all&#8217;Agricoltura e Risorse Naturali.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-336\" src=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-699.jpg\" alt=\"\" width=\"960\" height=\"540\" srcset=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-699.jpg 960w, https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-699-300x169.jpg 300w, https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-699-768x432.jpg 768w, https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-699-680x383.jpg 680w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>L&#8217;arboreto ha caratteristiche tali che si \u00e8 ritenuto opportuno valorizzare e rendere fruibile anche questo polmone verde, che interessa un&#8217;area di circa 2 ettari, facilmente accessibile dagli abitanti di Verr\u00e8s e dai turisti. In questo diversificato ambiente troviamo, oltre alle specie autoctone tipiche di questo ambiente xerofilo, quali roverella, corniolo, biancospino, olmo, bagolaro, robinia, ecc., specie pi\u00f9 esigenti, quali ciliegio, frassino, castagno, pero selvatico, tiglio, farnia, acero ecc, fino a scoprire delle vere e proprie rarit\u00e0 botaniche spontanee se rapportate a questo tipo di stazione: nespolo, pungitopo, alloro e fusaggine.<br \/>\nAnche la flora erbacea e arbustiva \u00e8 diversificata e, seppur non si riscontrino degli endemismi, troviamo le tipiche specie degli ambienti molto secchi e caldi: saponarie, silene, semprevivi, sassifraghe, rosa canina, vitalba, erba vescicaria, gigli selvatici ecc. e altre pi\u00f9 esigenti, quali la viola, la fra-gola, l&#8217;edera ed il sigillo di Salomone.<br \/>\nI lavori di approntamento dell&#8217;area sono consistiti in delicate operazioni colturali alla vegetazione presente e nella messa a dimora di altre specie arboree ed arbustive che richiamano le caratteristiche di questo straordinario ambiente (variet\u00e0 diverse di olivo, carpino, cipresso, bosso, acero, quercia, cedro, lonicera, timo, ginestra, nespolo, ecc). \u00c8 stata inoltre realizzata una piccola &#8220;roccera&#8221;, presso l&#8217;entrata principale, che racchiude diverse variet\u00e0 di ginepro, timo, rosmarino e altre essenze mediterranee. In un secondo tempo \u00e8 stata ripristinata o costruita ex-novo la rete sentieristica e sono stati approntati due accessi all&#8217;arboreto, ove sono state posizionate delle pensiline contenenti la cartografia della zona attrezzata. Sono state altres\u00ec predisposte 9 piazzole panoramiche dotate di comode panche in legno e cestini per rifiuti.<br \/>\nLa variegata vegetazione potr\u00e0 essere riconosciuta mediante appositi cartelli che ne indicano il nome botanico, oltre a quello francese ed italiano. Sebbene non vi siano zone pericolose nell&#8217;arboreto, i passaggi pi\u00f9 scoscesi sono protetti da idonea recinzione (un terzo accesso, dotato di sentiero preesistente, risulta essere pericoloso perch\u00e9 insiste proprio sul tornante della S.R. della Val d&#8217;Ayas, per cui non viene evidenziato come percorso aperto ai visitatori e l&#8217;eventuale transito sullo stesso, sar\u00e0 da ritenersi a rischio e responsabilit\u00e0 dell&#8217;utente).<br \/>\nGli abitanti di Verr\u00e8s chiamano questo luogo, in patois &#8220;Borna di laou&#8221; o, in piemontese &#8220;Tampa del luf&#8221;, in quanto pare che nella zona, fino alla fine del 1800, ci fosse una tana abitata dal lupo.<br \/>\nPer cui. vista la curiosit\u00e0 dell&#8217;informazione, si \u00e8 deciso di dare questo inquietante nome all&#8217;arboreto, sebbene di lupi non ve sia pi\u00f9 traccia da circa un secolo, mentre tassi, volpi, cinghiali, caprioli e mustelidi hanno trovato un luogo ideale per ripararsi e riprodursi. Gli equilibri che si instaurano in questi ambienti particolari sono per\u00f2 fragili, per cui si chiede al visitatore il massimo rispetto degli stessi, potendo nel contempo usufruire di un angolo di natura paesaggisticamente e botanicamente di alto valore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un panorama e dei profumi decisamente mediterranei accompagnano il visitatore all&#8217;interno di questo particolare arboreto impiantato nella prima met\u00e0 degli anni &#8217;50 dal Corpo Forestale, allora ancora dello Stato. Difatti, [&hellip;]<\/p>\n","protected":false},"featured_media":335,"parent":0,"menu_order":7,"template":"","meta":[],"class_list":["post-334","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arboretum &quot;Borna du laou&quot; - Verr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arboretum &quot;Borna du laou&quot; - Verr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Un panorama e dei profumi decisamente mediterranei accompagnano il visitatore all&#8217;interno di questo particolare arboreto impiantato nella prima met\u00e0 degli anni &#8217;50 dal Corpo Forestale, allora ancora dello Stato. Difatti, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/\" \/>\n<meta property=\"og:site_name\" content=\"Verr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-697.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/\",\"name\":\"Arboretum \\\"Borna du laou\\\" - Verr\u00e8s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/02\\\/arbore-697.jpg\",\"datePublished\":\"2017-02-27T10:55:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/02\\\/arbore-697.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/wp-content\\\/uploads\\\/sites\\\/55\\\/2017\\\/02\\\/arbore-697.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/turismo\\\/arboretum-borna-du-laou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arboretum &#8220;Borna du laou&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/\",\"name\":\"Verr\u00e8s\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/verres\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arboretum \"Borna du laou\" - Verr\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/","og_locale":"it_IT","og_type":"article","og_title":"Arboretum \"Borna du laou\" - Verr\u00e8s","og_description":"Un panorama e dei profumi decisamente mediterranei accompagnano il visitatore all&#8217;interno di questo particolare arboreto impiantato nella prima met\u00e0 degli anni &#8217;50 dal Corpo Forestale, allora ancora dello Stato. Difatti, [&hellip;]","og_url":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/","og_site_name":"Verr\u00e8s","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"width":960,"height":540,"url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-697.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/","url":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/","name":"Arboretum \"Borna du laou\" - Verr\u00e8s","isPartOf":{"@id":"https:\/\/comunicacity.net\/verres\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-697.jpg","datePublished":"2017-02-27T10:55:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/#primaryimage","url":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-697.jpg","contentUrl":"https:\/\/comunicacity.net\/verres\/wp-content\/uploads\/sites\/55\/2017\/02\/arbore-697.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/verres\/turismo\/arboretum-borna-du-laou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/verres\/"},{"@type":"ListItem","position":2,"name":"Arboretum &#8220;Borna du laou&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/verres\/#website","url":"https:\/\/comunicacity.net\/verres\/","name":"Verr\u00e8s","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/verres\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/turismo\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/types\/turismo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media\/335"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/verres\/wp-json\/wp\/v2\/media?parent=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}