{"id":1062,"date":"2020-03-13T16:40:27","date_gmt":"2020-03-13T15:40:27","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=1062"},"modified":"2020-03-13T16:37:40","modified_gmt":"2020-03-13T15:37:40","slug":"servizio-di-supporto-ad-anziani-e-persone-sole","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/","title":{"rendered":"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE"},"content":{"rendered":"<p>IL COMUNE E LA PROTEZIONE CIVILE DI VISCO PORTANO CIBO E MEDICINALI A DOMICILIO.<br \/>\nIl servizio partir\u00e0 da sabato 14 marzo. Telefonando al numero<strong> 0432 997003<\/strong> (interno 4),<strong> dalle ore 10:00 alle 12:00<\/strong>, dal luned\u00ec al sabato, sar\u00e0 possibile prenotare la consegna a casa di generi alimentari (piccole quantit\u00e0) e medicinali.<br \/>\nIl servizio \u00e8 riservato a:<\/p>\n<ul>\n<li>soggetti deboli (in situazione di solitudine)<\/li>\n<li>\u00a0agli anziani (oltre i 70 anni, soli)<\/li>\n<\/ul>\n<p>ma <strong>non<\/strong> \u00e8 disponibile per le<strong> persone in quarantena<\/strong>.<br \/>\nDalle 14:00 alle 16:00 di ogni giornata, ad esclusione della domenica, gli utenti che hanno richiesto il servizio in mattinata, verranno richiamati da personale della Protezione Civile per ricevere la lista o le disposizioni di dettaglio.<br \/>\nDalle 16:00 alle 18:00 il personale della Protezione Civile si recher\u00e0 nell\u2019abitazione della persona per effettuare il servizio. In caso ci siano tante richieste, il servizio potr\u00e0 slittare al mattino successivo.<br \/>\n<strong>I volontari della Protezione Civile, riconoscibili tramite tesserino e divisa, non entreranno mai in casa ma effettueranno la consegna sull\u2019uscio della porta, indossando mascherina e guanti.<\/strong><br \/>\nPer informazioni sanitarie rimane comunque attivo il numero di telefono regionale <strong>800 500 300<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IL COMUNE E LA PROTEZIONE CIVILE DI VISCO PORTANO CIBO E MEDICINALI A DOMICILIO. Il servizio partir\u00e0 da sabato 14 marzo. Telefonando al numero 0432 997003 (interno 4), dalle ore [&hellip;]<\/p>\n","protected":false},"author":229,"featured_media":1063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE - Visco\" \/>\n<meta property=\"og:description\" content=\"IL COMUNE E LA PROTEZIONE CIVILE DI VISCO PORTANO CIBO E MEDICINALI A DOMICILIO. Il servizio partir\u00e0 da sabato 14 marzo. Telefonando al numero 0432 997003 (interno 4), dalle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-13T15:40:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2020\/03\/avviso-supporto-1-pdf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1058\" \/>\n\t<meta property=\"og:image:height\" content=\"1497\" \/>\n<meta name=\"author\" content=\"comunevisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunevisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/\"},\"author\":{\"name\":\"comunevisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"headline\":\"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE\",\"datePublished\":\"2020-03-13T15:40:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/\"},\"wordCount\":179,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2020\\\/03\\\/avviso-supporto-1-pdf.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/\",\"name\":\"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2020\\\/03\\\/avviso-supporto-1-pdf.jpg\",\"datePublished\":\"2020-03-13T15:40:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2020\\\/03\\\/avviso-supporto-1-pdf.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2020\\\/03\\\/avviso-supporto-1-pdf.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/13\\\/servizio-di-supporto-ad-anziani-e-persone-sole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\",\"name\":\"comunevisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"caption\":\"comunevisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/comunevisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE - Visco","og_description":"IL COMUNE E LA PROTEZIONE CIVILE DI VISCO PORTANO CIBO E MEDICINALI A DOMICILIO. Il servizio partir\u00e0 da sabato 14 marzo. Telefonando al numero 0432 997003 (interno 4), dalle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-13T15:40:27+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2020\/03\/avviso-supporto-1-pdf.jpg","height":1497,"width":1058,"type":""}],"author":"comunevisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunevisco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/"},"author":{"name":"comunevisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"headline":"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE","datePublished":"2020-03-13T15:40:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/"},"wordCount":179,"image":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2020\/03\/avviso-supporto-1-pdf.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/","url":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/","name":"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2020\/03\/avviso-supporto-1-pdf.jpg","datePublished":"2020-03-13T15:40:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#primaryimage","url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2020\/03\/avviso-supporto-1-pdf.jpg","contentUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2020\/03\/avviso-supporto-1-pdf.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/13\/servizio-di-supporto-ad-anziani-e-persone-sole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"SERVIZIO DI SUPPORTO AD ANZIANI E PERSONE SOLE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5","name":"comunevisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","caption":"comunevisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/comunevisco\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1062\/revisions"}],"predecessor-version":[{"id":1064,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1062\/revisions\/1064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media\/1063"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=1062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=1062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}