{"id":1101,"date":"2020-03-23T14:00:30","date_gmt":"2020-03-23T13:00:30","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=1101"},"modified":"2020-03-23T11:35:45","modified_gmt":"2020-03-23T10:35:45","slug":"aumento-temporaneo-della-tolleranza-delle-rc-auto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/","title":{"rendered":"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO"},"content":{"rendered":"<p>Con il decreto \u201cCura Italia\u201d, <strong>la tolleranza delle Rc auto sale da 15 a 30 giorni per le polizze in scadenza<\/strong>. Quindi 15 giorni in pi\u00f9 rispetto ai 15 giorni di validit\u00e0 della polizza stabiliti dalla legge ordinaria alla scadenza del contratto.<br \/>\nTale misura vale per le assicurazioni in scadenza <strong>da qui al 31 luglio 2020<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con il decreto \u201cCura Italia\u201d, la tolleranza delle Rc auto sale da 15 a 30 giorni per le polizze in scadenza. Quindi 15 giorni in pi\u00f9 rispetto ai 15 giorni [&hellip;]<\/p>\n","protected":false},"author":229,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1101","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO - Visco\" \/>\n<meta property=\"og:description\" content=\"Con il decreto \u201cCura Italia\u201d, la tolleranza delle Rc auto sale da 15 a 30 giorni per le polizze in scadenza. Quindi 15 giorni in pi\u00f9 rispetto ai 15 giorni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T13:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"comunevisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunevisco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/\"},\"author\":{\"name\":\"comunevisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"headline\":\"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO\",\"datePublished\":\"2020-03-23T13:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/\"},\"wordCount\":57,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/\",\"name\":\"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"datePublished\":\"2020-03-23T13:00:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2020\\\/03\\\/23\\\/aumento-temporaneo-della-tolleranza-delle-rc-auto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\",\"name\":\"comunevisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"caption\":\"comunevisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/comunevisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/","og_locale":"it_IT","og_type":"article","og_title":"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO - Visco","og_description":"Con il decreto \u201cCura Italia\u201d, la tolleranza delle Rc auto sale da 15 a 30 giorni per le polizze in scadenza. Quindi 15 giorni in pi\u00f9 rispetto ai 15 giorni [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-23T13:00:30+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/visco\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"comunevisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunevisco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/"},"author":{"name":"comunevisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"headline":"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO","datePublished":"2020-03-23T13:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/"},"wordCount":57,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/","url":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/","name":"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"datePublished":"2020-03-23T13:00:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2020\/03\/23\/aumento-temporaneo-della-tolleranza-delle-rc-auto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"AUMENTO TEMPORANEO DELLA TOLLERANZA DELLE RC AUTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5","name":"comunevisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","caption":"comunevisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/comunevisco\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=1101"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1101\/revisions"}],"predecessor-version":[{"id":1102,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1101\/revisions\/1102"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=1101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=1101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=1101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}