{"id":1914,"date":"2022-07-13T17:30:50","date_gmt":"2022-07-13T15:30:50","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=1914"},"modified":"2022-07-12T20:38:58","modified_gmt":"2022-07-12T18:38:58","slug":"happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/","title":{"rendered":"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale"},"content":{"rendered":"<p><strong>Mercoled\u00ec 20 luglio 2022 alle ore 17.30<\/strong> vi invitiamo a seguire l\u2019happy hour digitale di presentazione del nuovo <strong>sportello telematico polifunzionale<\/strong> comunale in diretta su <a href=\"https:\/\/www.facebook.com\/Areacittadinanzadigitale\">Facebook<\/a> e in contemporanea sul canale <a href=\"https:\/\/www.youtube.com\/user\/Globogis\">YouTube<\/a> dello sportello telematico polifunzionale.<\/p>\n<p>Lo sportello telematico polifunzionale permetter\u00e0 di presentare in modo guidato e digitale le pratiche comunali, comodamente da casa o dall\u2019ufficio, in qualunque momento. Sar\u00e0\u00a0quindi possibile compilare in modo guidato qualunque istanza online, completare la procedura direttamente in internet, conoscere tutte le informazioni sulla propria pratica e i termini di conclusione del procedimento, effettuare i pagamenti in modalit\u00e0 digitale con PagoPA.<\/p>\n<p>L\u2019attivazione dello sportello telematico polifunzionale permetter\u00e0 al Comune di Visco di raggiungere rapidamente importanti risultati, in termini di semplificazione dell\u2019interazione tra i cittadini, professionisti e imprese e la pubblica amministrazione, riduzione dei tempi di attesa, snellimento delle modalit\u00e0 operative interne agli uffici, eliminazione dei documenti cartacei.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1916\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/Locandina-sportello-telematico-Visco.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/Locandina-sportello-telematico-Visco.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Locandina presentazione sportello telematico Visco<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 20 luglio 2022 alle ore 17.30 vi invitiamo a seguire l\u2019happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale in diretta su Facebook e in contemporanea sul [&hellip;]<\/p>\n","protected":false},"author":229,"featured_media":1915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale - Visco\" \/>\n<meta property=\"og:description\" content=\"Mercoled\u00ec 20 luglio 2022 alle ore 17.30 vi invitiamo a seguire l\u2019happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale in diretta su Facebook e in contemporanea sul [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-13T15:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/sportelloTelematicoPolifunzionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunevisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunevisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/\"},\"author\":{\"name\":\"comunevisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"headline\":\"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale\",\"datePublished\":\"2022-07-13T15:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/\"},\"wordCount\":155,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2022\\\/07\\\/sportelloTelematicoPolifunzionale.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/\",\"name\":\"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2022\\\/07\\\/sportelloTelematicoPolifunzionale.jpg\",\"datePublished\":\"2022-07-13T15:30:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2022\\\/07\\\/sportelloTelematicoPolifunzionale.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2022\\\/07\\\/sportelloTelematicoPolifunzionale.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2022\\\/07\\\/13\\\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\",\"name\":\"comunevisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"caption\":\"comunevisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/comunevisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale - Visco","og_description":"Mercoled\u00ec 20 luglio 2022 alle ore 17.30 vi invitiamo a seguire l\u2019happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale in diretta su Facebook e in contemporanea sul [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-13T15:30:50+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/sportelloTelematicoPolifunzionale.jpg","type":"image\/jpeg"}],"author":"comunevisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunevisco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/"},"author":{"name":"comunevisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"headline":"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale","datePublished":"2022-07-13T15:30:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/"},"wordCount":155,"image":{"@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/sportelloTelematicoPolifunzionale.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/","url":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/","name":"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/sportelloTelematicoPolifunzionale.jpg","datePublished":"2022-07-13T15:30:50+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/sportelloTelematicoPolifunzionale.jpg","contentUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2022\/07\/sportelloTelematicoPolifunzionale.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2022\/07\/13\/happy-hour-digitale-di-presentazione-del-nuovo-sportello-telematico-polifunzionale-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"Happy hour digitale di presentazione del nuovo sportello telematico polifunzionale comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5","name":"comunevisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","caption":"comunevisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/comunevisco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=1914"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1914\/revisions"}],"predecessor-version":[{"id":1917,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/1914\/revisions\/1917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media\/1915"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=1914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=1914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=1914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}