{"id":2885,"date":"2025-01-28T09:00:16","date_gmt":"2025-01-28T08:00:16","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=2885"},"modified":"2025-01-28T08:28:02","modified_gmt":"2025-01-28T07:28:02","slug":"segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/","title":{"rendered":"Segnalazione malfunzionamenti dell&#8217;impianto di illuminazione pubblica"},"content":{"rendered":"<p>Si comunica la possibilit\u00e0 di utilizzare il <a href=\"https:\/\/segnalazioni.chiurlo.it\/visco\/segnala\">servizio digitale<\/a> garantito da Chiurlo per comunicare eventuali malfunzionamenti dell&#8217;impianto di illuminazione pubblica.<\/p>\n<p>COME FUNZIONA?<\/p>\n<p>Individuare il palo che non funziona e selezionarlo per aprire la pagina: indicare qual \u00e8 il problema ed i propri recapiti per venire aggiornati in seguito sulla risoluzione del malfunzionamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica la possibilit\u00e0 di utilizzare il servizio digitale garantito da Chiurlo per comunicare eventuali malfunzionamenti dell&#8217;impianto di illuminazione pubblica. COME FUNZIONA? Individuare il palo che non funziona e selezionarlo [&hellip;]<\/p>\n","protected":false},"author":229,"featured_media":2886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segnalazione malfunzionamenti dell&#039;impianto di illuminazione pubblica - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segnalazione malfunzionamenti dell&#039;impianto di illuminazione pubblica - Visco\" \/>\n<meta property=\"og:description\" content=\"Si comunica la possibilit\u00e0 di utilizzare il servizio digitale garantito da Chiurlo per comunicare eventuali malfunzionamenti dell&#8217;impianto di illuminazione pubblica. COME FUNZIONA? Individuare il palo che non funziona e selezionarlo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T08:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2025\/01\/luce-illuminazione-pubblica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunevisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunevisco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/\"},\"author\":{\"name\":\"comunevisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"headline\":\"Segnalazione malfunzionamenti dell&#8217;impianto di illuminazione pubblica\",\"datePublished\":\"2025-01-28T08:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/\"},\"wordCount\":57,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2025\\\/01\\\/luce-illuminazione-pubblica.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/\",\"name\":\"Segnalazione malfunzionamenti dell'impianto di illuminazione pubblica - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2025\\\/01\\\/luce-illuminazione-pubblica.png\",\"datePublished\":\"2025-01-28T08:00:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2025\\\/01\\\/luce-illuminazione-pubblica.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2025\\\/01\\\/luce-illuminazione-pubblica.png\",\"width\":600,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/01\\\/28\\\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segnalazione malfunzionamenti dell&#8217;impianto di illuminazione pubblica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\",\"name\":\"comunevisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"caption\":\"comunevisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/comunevisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segnalazione malfunzionamenti dell'impianto di illuminazione pubblica - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/","og_locale":"it_IT","og_type":"article","og_title":"Segnalazione malfunzionamenti dell'impianto di illuminazione pubblica - Visco","og_description":"Si comunica la possibilit\u00e0 di utilizzare il servizio digitale garantito da Chiurlo per comunicare eventuali malfunzionamenti dell&#8217;impianto di illuminazione pubblica. COME FUNZIONA? Individuare il palo che non funziona e selezionarlo [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-01-28T08:00:16+00:00","og_image":[{"width":600,"height":500,"url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2025\/01\/luce-illuminazione-pubblica.png","type":"image\/png"}],"author":"comunevisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunevisco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/"},"author":{"name":"comunevisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"headline":"Segnalazione malfunzionamenti dell&#8217;impianto di illuminazione pubblica","datePublished":"2025-01-28T08:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/"},"wordCount":57,"image":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2025\/01\/luce-illuminazione-pubblica.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/","url":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/","name":"Segnalazione malfunzionamenti dell'impianto di illuminazione pubblica - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2025\/01\/luce-illuminazione-pubblica.png","datePublished":"2025-01-28T08:00:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#primaryimage","url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2025\/01\/luce-illuminazione-pubblica.png","contentUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2025\/01\/luce-illuminazione-pubblica.png","width":600,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2025\/01\/28\/segnalazione-malfunzionamenti-dellimpianto-di-illuminazione-pubblica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"Segnalazione malfunzionamenti dell&#8217;impianto di illuminazione pubblica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5","name":"comunevisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","caption":"comunevisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/comunevisco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/2885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=2885"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/2885\/revisions"}],"predecessor-version":[{"id":2890,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/2885\/revisions\/2890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media\/2886"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=2885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=2885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=2885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}