{"id":2964,"date":"2025-04-02T09:00:52","date_gmt":"2025-04-02T07:00:52","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=2964"},"modified":"2025-04-02T09:31:05","modified_gmt":"2025-04-02T07:31:05","slug":"2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/","title":{"rendered":"2 aprile &#8211; Giornata Mondiale della Consapevolezza sull&#8217;Autismo"},"content":{"rendered":"<p>Il 2 aprile\u00a0\u00e8 la\u00a0<span style=\"color: #00ccff\"><strong>Giornata Mondiale della Consapevolezza sull\u2019Autismo<\/strong> <\/span>(WAAD,\u00a0World Autism Awareness Day) istituita nel 2007 dall\u2019Assemblea Generale dell\u2019ONU. La ricorrenza richiama l\u2019attenzione di tutti sui diritti delle persone nello spettro autistico.<\/p>\n<p>I disturbi dello spettro autistico (Autism Spectrum Disorders, ASD) sono un insieme eterogeneo di\u00a0<strong>disturbi del neurosviluppo<\/strong>\u00a0caratterizzati da:<\/p>\n<ul>\n<li>compromissione qualitativa nelle aree dell\u2019interazione sociale e della comunicazione;<\/li>\n<li>modelli ripetitivi e stereotipati di comportamento, interessi e attivit\u00e0.<\/li>\n<\/ul>\n<p>I sintomi e la loro severit\u00e0 possono manifestarsi in modo differente da persona a persona, conseguentemente i bisogni specifici e la necessit\u00e0 di sostegno sono variabili e possono mutare nel tempo. Per questo \u00e8 fondamentale progettare interventi individualizzati e calibrati su bisogni specifici.<\/p>\n<p><span style=\"color: #00ccff\"><em><b>Concentrati\u00a0<\/b><b>su ci\u00f2 che posso fare e non su ci\u00f2 che non posso\u00a0<\/b><b>fare<\/b><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 2 aprile\u00a0\u00e8 la\u00a0Giornata Mondiale della Consapevolezza sull\u2019Autismo (WAAD,\u00a0World Autism Awareness Day) istituita nel 2007 dall\u2019Assemblea Generale dell\u2019ONU. La ricorrenza richiama l\u2019attenzione di tutti sui diritti delle persone nello spettro [&hellip;]<\/p>\n","protected":false},"author":229,"featured_media":2426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2 aprile - Giornata Mondiale della Consapevolezza sull&#039;Autismo - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2 aprile - Giornata Mondiale della Consapevolezza sull&#039;Autismo - Visco\" \/>\n<meta property=\"og:description\" content=\"Il 2 aprile\u00a0\u00e8 la\u00a0Giornata Mondiale della Consapevolezza sull\u2019Autismo (WAAD,\u00a0World Autism Awareness Day) istituita nel 2007 dall\u2019Assemblea Generale dell\u2019ONU. La ricorrenza richiama l\u2019attenzione di tutti sui diritti delle persone nello spettro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-02T07:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T07:31:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2024\/03\/Screenshot-2024-03-29-143921.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1037\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunevisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunevisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/\"},\"author\":{\"name\":\"comunevisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"headline\":\"2 aprile &#8211; Giornata Mondiale della Consapevolezza sull&#8217;Autismo\",\"datePublished\":\"2025-04-02T07:00:52+00:00\",\"dateModified\":\"2025-04-02T07:31:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/\"},\"wordCount\":136,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2024\\\/03\\\/Screenshot-2024-03-29-143921.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/\",\"name\":\"2 aprile - Giornata Mondiale della Consapevolezza sull'Autismo - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2024\\\/03\\\/Screenshot-2024-03-29-143921.png\",\"datePublished\":\"2025-04-02T07:00:52+00:00\",\"dateModified\":\"2025-04-02T07:31:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2024\\\/03\\\/Screenshot-2024-03-29-143921.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2024\\\/03\\\/Screenshot-2024-03-29-143921.png\",\"width\":1037,\"height\":748},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2025\\\/04\\\/02\\\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2 aprile &#8211; Giornata Mondiale della Consapevolezza sull&#8217;Autismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\",\"name\":\"comunevisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"caption\":\"comunevisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/comunevisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2 aprile - Giornata Mondiale della Consapevolezza sull'Autismo - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/","og_locale":"it_IT","og_type":"article","og_title":"2 aprile - Giornata Mondiale della Consapevolezza sull'Autismo - Visco","og_description":"Il 2 aprile\u00a0\u00e8 la\u00a0Giornata Mondiale della Consapevolezza sull\u2019Autismo (WAAD,\u00a0World Autism Awareness Day) istituita nel 2007 dall\u2019Assemblea Generale dell\u2019ONU. La ricorrenza richiama l\u2019attenzione di tutti sui diritti delle persone nello spettro [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-02T07:00:52+00:00","article_modified_time":"2025-04-02T07:31:05+00:00","og_image":[{"width":1037,"height":748,"url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2024\/03\/Screenshot-2024-03-29-143921.png","type":"image\/png"}],"author":"comunevisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunevisco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/"},"author":{"name":"comunevisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"headline":"2 aprile &#8211; Giornata Mondiale della Consapevolezza sull&#8217;Autismo","datePublished":"2025-04-02T07:00:52+00:00","dateModified":"2025-04-02T07:31:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/"},"wordCount":136,"image":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2024\/03\/Screenshot-2024-03-29-143921.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/","url":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/","name":"2 aprile - Giornata Mondiale della Consapevolezza sull'Autismo - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2024\/03\/Screenshot-2024-03-29-143921.png","datePublished":"2025-04-02T07:00:52+00:00","dateModified":"2025-04-02T07:31:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#primaryimage","url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2024\/03\/Screenshot-2024-03-29-143921.png","contentUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2024\/03\/Screenshot-2024-03-29-143921.png","width":1037,"height":748},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2025\/04\/02\/2-aprile-giornata-mondiale-per-la-consapevolezza-sullautismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"2 aprile &#8211; Giornata Mondiale della Consapevolezza sull&#8217;Autismo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5","name":"comunevisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","caption":"comunevisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/comunevisco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/2964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=2964"}],"version-history":[{"count":12,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/2964\/revisions"}],"predecessor-version":[{"id":3067,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/2964\/revisions\/3067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media\/2426"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=2964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=2964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=2964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}