{"id":3918,"date":"2026-04-22T14:24:38","date_gmt":"2026-04-22T12:24:38","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=3918"},"modified":"2026-04-22T14:22:40","modified_gmt":"2026-04-22T12:22:40","slug":"bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/","title":{"rendered":"Bando di concorso 7^ Premiazione dell&#8217;economia e dello sviluppo"},"content":{"rendered":"<p>La Camera di Commercio Industria Artigianato e Agricoltura di Pordenone-Udine ha indetto il Bando di Concorso per la 7^ edizione della\u00a0<strong>Premiazione dell\u2019economia e dello sviluppo<\/strong>.<\/p>\n<p>Il <a href=\"https:\/\/municipium-images-production.s3-eu-west-1.amazonaws.com\/s3\/7990\/allegati\/servizio-civile\/web-bando_2026.pdf\">Bando<\/a> \u00e8 rivolto alle\u00a0<strong>imprese<\/strong>, ai\u00a0<strong>lavoratori\u00a0<\/strong>e agli\u00a0<strong>istituti scolastici\u00a0<\/strong>del territorio di competenza della Camera di Commercio.<\/p>\n<p>Il concorso promuove il sostegno e la\u00a0<strong>valorizzazione della cultura di impresa<\/strong>\u00a0e prevede categorie e premi differenti, con ripartizione dei riconoscimenti rispetto ai territori di competenza di Pordenone e Udine.<\/p>\n<p>Le domande dovranno essere inviate\u00a0<strong>entro il 29\/05\/2026<\/strong>.<\/p>\n<p>Per maggiori informazioni <a href=\"https:\/\/www.pnud.camcom.it\/news\/premiazione-delleconomia-e-dello-sviluppo-2026\">clicca qui.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Camera di Commercio Industria Artigianato e Agricoltura di Pordenone-Udine ha indetto il Bando di Concorso per la 7^ edizione della\u00a0Premiazione dell\u2019economia e dello sviluppo. Il Bando \u00e8 rivolto alle\u00a0imprese, [&hellip;]<\/p>\n","protected":false},"author":229,"featured_media":3921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando di concorso 7^ Premiazione dell&#039;economia e dello sviluppo - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando di concorso 7^ Premiazione dell&#039;economia e dello sviluppo - Visco\" \/>\n<meta property=\"og:description\" content=\"La Camera di Commercio Industria Artigianato e Agricoltura di Pordenone-Udine ha indetto il Bando di Concorso per la 7^ edizione della\u00a0Premiazione dell\u2019economia e dello sviluppo. Il Bando \u00e8 rivolto alle\u00a0imprese, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T12:24:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2026\/04\/AVVISO-BANDO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1857\" \/>\n\t<meta property=\"og:image:height\" content=\"1056\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunevisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunevisco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/\"},\"author\":{\"name\":\"comunevisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"headline\":\"Bando di concorso 7^ Premiazione dell&#8217;economia e dello sviluppo\",\"datePublished\":\"2026-04-22T12:24:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/\"},\"wordCount\":96,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2026\\\/04\\\/AVVISO-BANDO.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/\",\"name\":\"Bando di concorso 7^ Premiazione dell'economia e dello sviluppo - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2026\\\/04\\\/AVVISO-BANDO.png\",\"datePublished\":\"2026-04-22T12:24:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2026\\\/04\\\/AVVISO-BANDO.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2026\\\/04\\\/AVVISO-BANDO.png\",\"width\":1857,\"height\":1056},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2026\\\/04\\\/22\\\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando di concorso 7^ Premiazione dell&#8217;economia e dello sviluppo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/febe8a3e5bc4d0a725409d0bbcdff8a5\",\"name\":\"comunevisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g\",\"caption\":\"comunevisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/comunevisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando di concorso 7^ Premiazione dell'economia e dello sviluppo - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/","og_locale":"it_IT","og_type":"article","og_title":"Bando di concorso 7^ Premiazione dell'economia e dello sviluppo - Visco","og_description":"La Camera di Commercio Industria Artigianato e Agricoltura di Pordenone-Udine ha indetto il Bando di Concorso per la 7^ edizione della\u00a0Premiazione dell\u2019economia e dello sviluppo. Il Bando \u00e8 rivolto alle\u00a0imprese, [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-04-22T12:24:38+00:00","og_image":[{"width":1857,"height":1056,"url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2026\/04\/AVVISO-BANDO.png","type":"image\/png"}],"author":"comunevisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunevisco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/"},"author":{"name":"comunevisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"headline":"Bando di concorso 7^ Premiazione dell&#8217;economia e dello sviluppo","datePublished":"2026-04-22T12:24:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/"},"wordCount":96,"image":{"@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2026\/04\/AVVISO-BANDO.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/","url":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/","name":"Bando di concorso 7^ Premiazione dell'economia e dello sviluppo - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2026\/04\/AVVISO-BANDO.png","datePublished":"2026-04-22T12:24:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#primaryimage","url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2026\/04\/AVVISO-BANDO.png","contentUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2026\/04\/AVVISO-BANDO.png","width":1857,"height":1056},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2026\/04\/22\/bando-di-concorso-7-premiazione-delleconomia-e-dello-sviluppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"Bando di concorso 7^ Premiazione dell&#8217;economia e dello sviluppo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/febe8a3e5bc4d0a725409d0bbcdff8a5","name":"comunevisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6d804784ed939be1b69394a7b769f7c6c368ed92912338c3399e472848864ba?s=96&d=mm&r=g","caption":"comunevisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/comunevisco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"9"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/3918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=3918"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/3918\/revisions"}],"predecessor-version":[{"id":3922,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/3918\/revisions\/3922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media\/3921"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=3918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=3918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=3918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}