{"id":461,"date":"2018-07-06T14:06:03","date_gmt":"2018-07-06T12:06:03","guid":{"rendered":"https:\/\/comunicacity.net\/visco\/?p=461"},"modified":"2018-07-06T14:06:03","modified_gmt":"2018-07-06T12:06:03","slug":"info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/","title":{"rendered":"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018)"},"content":{"rendered":"<h3>Bando di concorso n. 4\/2018 del 06.07.2018\u00a0per l\u2019assegnazione in locazione degli alloggi di risulta di edilizia residenziale pubblica sovvenzionata, che si renderanno disponibili nei Comuni di AIELLO DEL FRIULI, CAMPOLONGO TAPOGLIANO, RUDA, FIUMICELLO VILLA VICENTINA, SAN VITO AL TORRE, TORVISCOSA, VISCO<\/h3>\n<p class=\"bodytext\">\n<p class=\"bodytext\"><strong>Scadenza presentazione domande:<\/strong><\/p>\n<p class=\"bodytext\"><strong>6 settembre 2018<\/strong><\/p>\n<p class=\"bodytext\"><a href=\"http:\/\/udine.aterfvg.it\/index.php?id=41995&amp;no_cache=1\">http:\/\/udine.aterfvg.it\/index.php?id=41995&amp;no_cache=1<\/a><\/p>\n<p class=\"bodytext\">\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_462\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/2018-07-06-BandoeModulo-AielloCampolongoTapoglianoRudaFiumicelloVillaVicentina_...pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/2018-07-06-BandoeModulo-AielloCampolongoTapoglianoRudaFiumicelloVillaVicentina_...pdf', '_system'); return false;\"><i class='icon attachment'><\/i>2018 07 06 BandoeModulo-AielloCampolongoTapoglianoRudaFiumicelloVillaVicentina_..<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bando di concorso n. 4\/2018 del 06.07.2018\u00a0per l\u2019assegnazione in locazione degli alloggi di risulta di edilizia residenziale pubblica sovvenzionata, che si renderanno disponibili nei Comuni di AIELLO DEL FRIULI, CAMPOLONGO [&hellip;]<\/p>\n","protected":false},"author":228,"featured_media":463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018) - Visco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018) - Visco\" \/>\n<meta property=\"og:description\" content=\"Bando di concorso n. 4\/2018 del 06.07.2018\u00a0per l\u2019assegnazione in locazione degli alloggi di risulta di edilizia residenziale pubblica sovvenzionata, che si renderanno disponibili nei Comuni di AIELLO DEL FRIULI, CAMPOLONGO [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/\" \/>\n<meta property=\"og:site_name\" content=\"Visco\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-06T12:06:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/Screenshot-27.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"462\" \/>\n\t<meta property=\"og:image:height\" content=\"149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacovisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacovisco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/\"},\"author\":{\"name\":\"sindacovisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/265da660138ea63c3a0dcac0dd37e53d\"},\"headline\":\"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\\\/09\\\/2018)\",\"datePublished\":\"2018-07-06T12:06:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/\"},\"wordCount\":65,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2018\\\/07\\\/Screenshot-27.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/\",\"name\":\"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\\\/09\\\/2018) - Visco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2018\\\/07\\\/Screenshot-27.jpg\",\"datePublished\":\"2018-07-06T12:06:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/265da660138ea63c3a0dcac0dd37e53d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2018\\\/07\\\/Screenshot-27.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/wp-content\\\/uploads\\\/sites\\\/96\\\/2018\\\/07\\\/Screenshot-27.jpg\",\"width\":462,\"height\":149},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/2018\\\/07\\\/06\\\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\\\/09\\\/2018)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/\",\"name\":\"Visco\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/#\\\/schema\\\/person\\\/265da660138ea63c3a0dcac0dd37e53d\",\"name\":\"sindacovisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d92b2f7004ee646baf3ec7757797d7931f9c6c70b9ad7fb2de02046abce3e2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d92b2f7004ee646baf3ec7757797d7931f9c6c70b9ad7fb2de02046abce3e2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d92b2f7004ee646baf3ec7757797d7931f9c6c70b9ad7fb2de02046abce3e2c?s=96&d=mm&r=g\",\"caption\":\"sindacovisco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/visco\\\/author\\\/sindacovisco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018) - Visco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/","og_locale":"it_IT","og_type":"article","og_title":"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018) - Visco","og_description":"Bando di concorso n. 4\/2018 del 06.07.2018\u00a0per l\u2019assegnazione in locazione degli alloggi di risulta di edilizia residenziale pubblica sovvenzionata, che si renderanno disponibili nei Comuni di AIELLO DEL FRIULI, CAMPOLONGO [&hellip;]","og_url":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/","og_site_name":"Visco","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-07-06T12:06:03+00:00","og_image":[{"width":462,"height":149,"url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/Screenshot-27.jpg","type":"image\/jpeg"}],"author":"sindacovisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacovisco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/"},"author":{"name":"sindacovisco","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/265da660138ea63c3a0dcac0dd37e53d"},"headline":"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018)","datePublished":"2018-07-06T12:06:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/"},"wordCount":65,"image":{"@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/Screenshot-27.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/","url":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/","name":"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018) - Visco","isPartOf":{"@id":"https:\/\/comunicacity.net\/visco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/Screenshot-27.jpg","datePublished":"2018-07-06T12:06:03+00:00","author":{"@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/265da660138ea63c3a0dcac0dd37e53d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#primaryimage","url":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/Screenshot-27.jpg","contentUrl":"https:\/\/comunicacity.net\/visco\/wp-content\/uploads\/sites\/96\/2018\/07\/Screenshot-27.jpg","width":462,"height":149},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/visco\/2018\/07\/06\/info-ater-pubblicato-nuovo-bando-alloggi-ater-scadenza-presentazione-domande-06092018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/visco\/"},{"@type":"ListItem","position":2,"name":"info ATER: pubblicato nuovo bando alloggi Ater (scadenza presentazione domande 06\/09\/2018)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/visco\/#website","url":"https:\/\/comunicacity.net\/visco\/","name":"Visco","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/visco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/visco\/#\/schema\/person\/265da660138ea63c3a0dcac0dd37e53d","name":"sindacovisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4d92b2f7004ee646baf3ec7757797d7931f9c6c70b9ad7fb2de02046abce3e2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d92b2f7004ee646baf3ec7757797d7931f9c6c70b9ad7fb2de02046abce3e2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d92b2f7004ee646baf3ec7757797d7931f9c6c70b9ad7fb2de02046abce3e2c?s=96&d=mm&r=g","caption":"sindacovisco"},"url":"https:\/\/comunicacity.net\/visco\/author\/sindacovisco\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/users\/228"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/comments?post=461"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/461\/revisions"}],"predecessor-version":[{"id":464,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/posts\/461\/revisions\/464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media\/463"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/media?parent=461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/categories?post=461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/visco\/wp-json\/wp\/v2\/tags?post=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}