{"id":214,"date":"2024-04-24T12:14:25","date_gmt":"2024-04-24T10:14:25","guid":{"rendered":"https:\/\/comunicacity.net\/viticuso\/?p=214"},"modified":"2024-04-24T12:44:33","modified_gmt":"2024-04-24T10:44:33","slug":"bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/","title":{"rendered":"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d"},"content":{"rendered":"<p style=\"font-weight: 400\">AIUTI ALL\u2019AVVIAMENTO AZIENDALE PER I GIOVANI AGRICOLTORI<\/p>\n<p style=\"font-weight: 400\">\nSi rende noto che, nell\u2019ambito del PSR LAZIO 2014-2022, la Regione Lazio ha pubblicato il bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d( Misura 6.1.1) rivolto giovani agricoltori con et\u00e0 compresa tra 18 e 40 anni che si insediano per la prima volta in un\u2019azienda agricola di micro e piccole dimensioni.<br \/>\nIl premio, che sar\u00e0 corrisposto obbligatoriamente in due rate, la prima del 70% e la seconda del 30%, \u00e8 cos\u00ec modulato:<br \/>\n&#8211; 50.000 euro per insediamenti in zona ordinaria;<br \/>\n&#8211; 70.000 euro per insediamenti in zona svantaggiata.<br \/>\nLa presentazione della domanda di sostegno deve avvenire entro le ore 23.59 del 17 giugno 2024 esclusivamente mediante apposita procedura informatica, attraverso il portale SIAN al seguente indirizzo internet: https:\/\/www.sian.it.<br \/>\nSi allegano la Determinazione N. G04351 della Regione Lazio, il testo integrale del Bando e la Scheda di sintesi reperibili anche al seguente indirizzo internet: Regione Lazio | Bando &#8211; Determinazione n. G04351 del 17\/04\/2024.<br \/>\nPer qualsiasi supporto o richiesta di chiarimento, gli Amministratori e gli Uffici comunali competenti sono a disposizione. I contatti degli organi Regionali competenti sono inoltre reperibili al seguente indirizzo internet: Aiuti all&#8217;avviamento aziendale per i giovani agricoltori &#8211; LazioEuropa<\/p>\n<p style=\"font-weight: 400\">\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_216\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/AGR-DD-G04351-17-04-2024-Allegato.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/AGR-DD-G04351-17-04-2024-Allegato.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AGR-DD-G04351-17-04-2024-Allegato<\/a><\/li>\n<li><a id=\"wpba_attachment_list_217\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/AGR-DD-G04351-17-04-2024.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/AGR-DD-G04351-17-04-2024.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AGR-DD-G04351-17-04-2024<\/a><\/li>\n<li><a id=\"wpba_attachment_list_218\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/AGC-DD-G04351-17-04-2024-Scheda-Sintesi.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/AGC-DD-G04351-17-04-2024-Scheda-Sintesi.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AGC-DD-G04351-17-04-2024-Scheda-Sintesi<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AIUTI ALL\u2019AVVIAMENTO AZIENDALE PER I GIOVANI AGRICOLTORI Si rende noto che, nell\u2019ambito del PSR LAZIO 2014-2022, la Regione Lazio ha pubblicato il bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d( Misura [&hellip;]<\/p>\n","protected":false},"author":399,"featured_media":215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d - Comune di Viticuso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d - Comune di Viticuso\" \/>\n<meta property=\"og:description\" content=\"AIUTI ALL\u2019AVVIAMENTO AZIENDALE PER I GIOVANI AGRICOLTORI Si rende noto che, nell\u2019ambito del PSR LAZIO 2014-2022, la Regione Lazio ha pubblicato il bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d( Misura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/\" \/>\n<meta property=\"og:site_name\" content=\"Comune di Viticuso\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T10:14:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T10:44:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/Immagine-GiovaniAgricoltori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1052\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itodisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"itodisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/\"},\"author\":{\"name\":\"itodisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\"},\"headline\":\"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d\",\"datePublished\":\"2024-04-24T10:14:25+00:00\",\"dateModified\":\"2024-04-24T10:44:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/\"},\"wordCount\":200,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/04\\\/Immagine-GiovaniAgricoltori.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/\",\"name\":\"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d - Comune di Viticuso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/04\\\/Immagine-GiovaniAgricoltori.png\",\"datePublished\":\"2024-04-24T10:14:25+00:00\",\"dateModified\":\"2024-04-24T10:44:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/04\\\/Immagine-GiovaniAgricoltori.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/04\\\/Immagine-GiovaniAgricoltori.png\",\"width\":1052,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/04\\\/24\\\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\",\"name\":\"itodisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"caption\":\"itodisco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d - Comune di Viticuso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/","og_locale":"it_IT","og_type":"article","og_title":"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d - Comune di Viticuso","og_description":"AIUTI ALL\u2019AVVIAMENTO AZIENDALE PER I GIOVANI AGRICOLTORI Si rende noto che, nell\u2019ambito del PSR LAZIO 2014-2022, la Regione Lazio ha pubblicato il bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d( Misura [&hellip;]","og_url":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/","og_site_name":"Comune di Viticuso","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-04-24T10:14:25+00:00","article_modified_time":"2024-04-24T10:44:33+00:00","og_image":[{"width":1052,"height":550,"url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/Immagine-GiovaniAgricoltori.png","type":"image\/png"}],"author":"itodisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"itodisco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/"},"author":{"name":"itodisco","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431"},"headline":"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d","datePublished":"2024-04-24T10:14:25+00:00","dateModified":"2024-04-24T10:44:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/"},"wordCount":200,"publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/Immagine-GiovaniAgricoltori.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/","url":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/","name":"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d - Comune di Viticuso","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/Immagine-GiovaniAgricoltori.png","datePublished":"2024-04-24T10:14:25+00:00","dateModified":"2024-04-24T10:44:33+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#primaryimage","url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/Immagine-GiovaniAgricoltori.png","contentUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/04\/Immagine-GiovaniAgricoltori.png","width":1052,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/04\/24\/bando-aiuti-allavviamento-aziendale-per-giovani-agricoltori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/viticuso\/"},{"@type":"ListItem","position":2,"name":"Bando \u201cAiuti all\u2019avviamento aziendale per giovani agricoltori\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/viticuso\/#website","url":"https:\/\/comunicacity.net\/viticuso\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/viticuso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/viticuso\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/viticuso\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431","name":"itodisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","caption":"itodisco"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/users\/399"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"predecessor-version":[{"id":222,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/214\/revisions\/222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media\/215"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}