{"id":24,"date":"2023-05-30T11:38:40","date_gmt":"2023-05-30T09:38:40","guid":{"rendered":"https:\/\/comunicacity.net\/viticuso\/?p=24"},"modified":"2023-05-30T11:38:40","modified_gmt":"2023-05-30T09:38:40","slug":"approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/","title":{"rendered":"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali"},"content":{"rendered":"<p>Nella giornata di ieri la giunta comunale, con delibera\u00a0n. 36 del 29-05-2023, ha approvato il progetto esecutivo per la realizzazione di nuovi loculi cimiteriali.<\/p>\n<p><a href=\"https:\/\/ww2.gazzettaamministrativa.it\/opencms\/opencms\/_gazzetta_amministrativa\/albo_pretorio\/_lazio\/_comuni\/_viticuso\/delibere\/2023\/Pratica_1685356229104\/delibera_n._36_del_29-05-2023.pdf\">scarica la delibera<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata di ieri la giunta comunale, con delibera\u00a0n. 36 del 29-05-2023, ha approvato il progetto esecutivo per la realizzazione di nuovi loculi cimiteriali. scarica la delibera<\/p>\n","protected":false},"author":399,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-24","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali - Comune di Viticuso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali - Comune di Viticuso\" \/>\n<meta property=\"og:description\" content=\"Nella giornata di ieri la giunta comunale, con delibera\u00a0n. 36 del 29-05-2023, ha approvato il progetto esecutivo per la realizzazione di nuovi loculi cimiteriali. scarica la delibera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/\" \/>\n<meta property=\"og:site_name\" content=\"Comune di Viticuso\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T09:38:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"itodisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"itodisco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/\"},\"author\":{\"name\":\"itodisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\"},\"headline\":\"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali\",\"datePublished\":\"2023-05-30T09:38:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/\"},\"wordCount\":35,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/\",\"name\":\"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali - Comune di Viticuso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\"},\"datePublished\":\"2023-05-30T09:38:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/05\\\/30\\\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\",\"name\":\"itodisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"caption\":\"itodisco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali - Comune di Viticuso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/","og_locale":"it_IT","og_type":"article","og_title":"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali - Comune di Viticuso","og_description":"Nella giornata di ieri la giunta comunale, con delibera\u00a0n. 36 del 29-05-2023, ha approvato il progetto esecutivo per la realizzazione di nuovi loculi cimiteriali. scarica la delibera","og_url":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/","og_site_name":"Comune di Viticuso","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-30T09:38:40+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"itodisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"itodisco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/"},"author":{"name":"itodisco","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431"},"headline":"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali","datePublished":"2023-05-30T09:38:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/"},"wordCount":35,"publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/","url":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/","name":"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali - Comune di Viticuso","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/#website"},"datePublished":"2023-05-30T09:38:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/05\/30\/approvazione-progetto-esecutivo-costruzione-di-90-loculi-cimiteriali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/viticuso\/"},{"@type":"ListItem","position":2,"name":"Approvazione progetto esecutivo costruzione di 90 loculi cimiteriali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/viticuso\/#website","url":"https:\/\/comunicacity.net\/viticuso\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/viticuso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/viticuso\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/viticuso\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431","name":"itodisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","caption":"itodisco"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/users\/399"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/24\/revisions"}],"predecessor-version":[{"id":25,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/24\/revisions\/25"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/categories?post=24"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/tags?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}