{"id":286,"date":"2024-08-19T12:21:01","date_gmt":"2024-08-19T10:21:01","guid":{"rendered":"https:\/\/comunicacity.net\/viticuso\/?p=286"},"modified":"2024-08-19T12:21:01","modified_gmt":"2024-08-19T10:21:01","slug":"servizio-civile-2024-25","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/","title":{"rendered":"SERVIZIO CIVILE 2024\/25"},"content":{"rendered":"<p>Si informano i ragazzi tra 18 ed i 28 anni che \u00e8 stato pubblicato il bando per Servizio Civile 2024\/25.<br \/>\nTutti i dettagli sono disponibili al sito internet predisposto dal Dipartimento per le politiche giovanili e il servizio civile universale della Presidenza del Consiglio dei Ministri: <a href=\"https:\/\/www.scelgoilserviziocivile.gov.it\/\">https:\/\/www.scelgoilserviziocivile.gov.it\/<\/a> .<br \/>\nDal sito \u00e8 possibile scaricare il bando con tutte le informazioni e requisiti necessari alla partecipazione, cercare il progetto di interesse e presentare la domanda di partecipazione.<br \/>\nLe domande di partecipazione devono essere presentate entro e non oltre le *ore 14.00 del 26 settembre 2024* esclusivamente attraverso la piattaforma Domanda on Line (DOL) all\u2019indirizzo <a href=\"https:\/\/domandaonline.serviziocivile.it\">https:\/\/domandaonline.serviziocivile.it<\/a>.<br \/>\nPer qualsiasi chiarimento o supporto gli Uffici comunali competenti e gli Amministratori sono a disposizione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informano i ragazzi tra 18 ed i 28 anni che \u00e8 stato pubblicato il bando per Servizio Civile 2024\/25. Tutti i dettagli sono disponibili al sito internet predisposto dal [&hellip;]<\/p>\n","protected":false},"author":399,"featured_media":287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVIZIO CIVILE 2024\/25 - Comune di Viticuso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVIZIO CIVILE 2024\/25 - Comune di Viticuso\" \/>\n<meta property=\"og:description\" content=\"Si informano i ragazzi tra 18 ed i 28 anni che \u00e8 stato pubblicato il bando per Servizio Civile 2024\/25. Tutti i dettagli sono disponibili al sito internet predisposto dal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Comune di Viticuso\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-19T10:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/08\/PHOTO-2024-08-19-10-37-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"902\" \/>\n\t<meta property=\"og:image:height\" content=\"875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itodisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"itodisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/\"},\"author\":{\"name\":\"itodisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\"},\"headline\":\"SERVIZIO CIVILE 2024\\\/25\",\"datePublished\":\"2024-08-19T10:21:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/\"},\"wordCount\":119,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/08\\\/PHOTO-2024-08-19-10-37-16.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/\",\"name\":\"SERVIZIO CIVILE 2024\\\/25 - Comune di Viticuso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/08\\\/PHOTO-2024-08-19-10-37-16.jpg\",\"datePublished\":\"2024-08-19T10:21:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/08\\\/PHOTO-2024-08-19-10-37-16.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2024\\\/08\\\/PHOTO-2024-08-19-10-37-16.jpg\",\"width\":902,\"height\":875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2024\\\/08\\\/19\\\/servizio-civile-2024-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVIZIO CIVILE 2024\\\/25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\",\"name\":\"itodisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"caption\":\"itodisco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVIZIO CIVILE 2024\/25 - Comune di Viticuso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/","og_locale":"it_IT","og_type":"article","og_title":"SERVIZIO CIVILE 2024\/25 - Comune di Viticuso","og_description":"Si informano i ragazzi tra 18 ed i 28 anni che \u00e8 stato pubblicato il bando per Servizio Civile 2024\/25. Tutti i dettagli sono disponibili al sito internet predisposto dal [&hellip;]","og_url":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/","og_site_name":"Comune di Viticuso","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-08-19T10:21:01+00:00","og_image":[{"width":902,"height":875,"url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/08\/PHOTO-2024-08-19-10-37-16.jpg","type":"image\/jpeg"}],"author":"itodisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"itodisco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/"},"author":{"name":"itodisco","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431"},"headline":"SERVIZIO CIVILE 2024\/25","datePublished":"2024-08-19T10:21:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/"},"wordCount":119,"publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/08\/PHOTO-2024-08-19-10-37-16.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/","url":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/","name":"SERVIZIO CIVILE 2024\/25 - Comune di Viticuso","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/08\/PHOTO-2024-08-19-10-37-16.jpg","datePublished":"2024-08-19T10:21:01+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#primaryimage","url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/08\/PHOTO-2024-08-19-10-37-16.jpg","contentUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2024\/08\/PHOTO-2024-08-19-10-37-16.jpg","width":902,"height":875},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/viticuso\/2024\/08\/19\/servizio-civile-2024-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/viticuso\/"},{"@type":"ListItem","position":2,"name":"SERVIZIO CIVILE 2024\/25"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/viticuso\/#website","url":"https:\/\/comunicacity.net\/viticuso\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/viticuso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/viticuso\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/viticuso\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431","name":"itodisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","caption":"itodisco"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/users\/399"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/286\/revisions"}],"predecessor-version":[{"id":288,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/286\/revisions\/288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media\/287"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/categories?post=286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/tags?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}