{"id":34,"date":"2023-06-05T09:32:56","date_gmt":"2023-06-05T07:32:56","guid":{"rendered":"https:\/\/comunicacity.net\/viticuso\/?p=34"},"modified":"2023-06-05T09:33:07","modified_gmt":"2023-06-05T07:33:07","slug":"sistemazione-della-strada-di-vasmondo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/","title":{"rendered":"Sistemazione della Strada di Vasmondo"},"content":{"rendered":"<p>Il CUC della XIV Comunit\u00e0 Montana ha provveduto all&#8217;espletamento della gara di appalto per la sistemazione della Strada di Vasmondo. Si proceder\u00e0 con la firma del contratto e successivamente con l&#8217;inizio lavori.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-35\" src=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo-1024x664.jpg\" alt=\"\" width=\"640\" height=\"415\" srcset=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo-1024x664.jpg 1024w, https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo-300x195.jpg 300w, https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo-768x498.jpg 768w, https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo-1536x996.jpg 1536w, https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo-2048x1329.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il CUC della XIV Comunit\u00e0 Montana ha provveduto all&#8217;espletamento della gara di appalto per la sistemazione della Strada di Vasmondo. Si proceder\u00e0 con la firma del contratto e successivamente con [&hellip;]<\/p>\n","protected":false},"author":399,"featured_media":35,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-34","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistemazione della Strada di Vasmondo - Comune di Viticuso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistemazione della Strada di Vasmondo - Comune di Viticuso\" \/>\n<meta property=\"og:description\" content=\"Il CUC della XIV Comunit\u00e0 Montana ha provveduto all&#8217;espletamento della gara di appalto per la sistemazione della Strada di Vasmondo. Si proceder\u00e0 con la firma del contratto e successivamente con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Comune di Viticuso\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T07:32:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T07:33:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2058\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itodisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"itodisco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/\"},\"author\":{\"name\":\"itodisco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\"},\"headline\":\"Sistemazione della Strada di Vasmondo\",\"datePublished\":\"2023-06-05T07:32:56+00:00\",\"dateModified\":\"2023-06-05T07:33:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/\"},\"wordCount\":37,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2023\\\/06\\\/vasmondo.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/\",\"name\":\"Sistemazione della Strada di Vasmondo - Comune di Viticuso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2023\\\/06\\\/vasmondo.jpg\",\"datePublished\":\"2023-06-05T07:32:56+00:00\",\"dateModified\":\"2023-06-05T07:33:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2023\\\/06\\\/vasmondo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/wp-content\\\/uploads\\\/sites\\\/209\\\/2023\\\/06\\\/vasmondo.jpg\",\"width\":2058,\"height\":1335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/2023\\\/06\\\/05\\\/sistemazione-della-strada-di-vasmondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistemazione della Strada di Vasmondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/viticuso\\\/#\\\/schema\\\/person\\\/1112a6ed5ee184e03da7e391cb89f431\",\"name\":\"itodisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g\",\"caption\":\"itodisco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistemazione della Strada di Vasmondo - Comune di Viticuso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/","og_locale":"it_IT","og_type":"article","og_title":"Sistemazione della Strada di Vasmondo - Comune di Viticuso","og_description":"Il CUC della XIV Comunit\u00e0 Montana ha provveduto all&#8217;espletamento della gara di appalto per la sistemazione della Strada di Vasmondo. Si proceder\u00e0 con la firma del contratto e successivamente con [&hellip;]","og_url":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/","og_site_name":"Comune di Viticuso","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-06-05T07:32:56+00:00","article_modified_time":"2023-06-05T07:33:07+00:00","og_image":[{"width":2058,"height":1335,"url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo.jpg","type":"image\/jpeg"}],"author":"itodisco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"itodisco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/"},"author":{"name":"itodisco","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431"},"headline":"Sistemazione della Strada di Vasmondo","datePublished":"2023-06-05T07:32:56+00:00","dateModified":"2023-06-05T07:33:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/"},"wordCount":37,"publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/","url":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/","name":"Sistemazione della Strada di Vasmondo - Comune di Viticuso","isPartOf":{"@id":"https:\/\/comunicacity.net\/viticuso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo.jpg","datePublished":"2023-06-05T07:32:56+00:00","dateModified":"2023-06-05T07:33:07+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#primaryimage","url":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo.jpg","contentUrl":"https:\/\/comunicacity.net\/viticuso\/wp-content\/uploads\/sites\/209\/2023\/06\/vasmondo.jpg","width":2058,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/viticuso\/2023\/06\/05\/sistemazione-della-strada-di-vasmondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/viticuso\/"},{"@type":"ListItem","position":2,"name":"Sistemazione della Strada di Vasmondo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/viticuso\/#website","url":"https:\/\/comunicacity.net\/viticuso\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/viticuso\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/viticuso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/viticuso\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/viticuso\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/viticuso\/#\/schema\/person\/1112a6ed5ee184e03da7e391cb89f431","name":"itodisco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c43a5cf23afeb32b92ae4fc332840736952a5849f0c9fbc837fe4c915732911?s=96&d=mm&r=g","caption":"itodisco"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/users\/399"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"predecessor-version":[{"id":36,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/posts\/34\/revisions\/36"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media\/35"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/viticuso\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}